{"id":73730,"date":"2024-08-15T06:47:54","date_gmt":"2024-08-15T09:47:54","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/df\/?p=73730"},"modified":"2026-04-17T11:35:39","modified_gmt":"2026-04-17T14:35:39","slug":"hoy-te-cuento-mujeres-que-corren-con-los-lobos","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/","title":{"rendered":"Hoy te cuento: Mujeres que corren con los lobos"},"content":{"rendered":"<p>Mujeres que corren con los lobos, de Clarissa Pinkola Est\u00e9s<\/p>\n<p>Creo que la primera edici\u00f3n la tuve en mis manos a principios de los 90\u2019, mucho tiempo despu\u00e9s supe que Pinkola Est\u00e9s hab\u00eda estado produciendo cintas de audio populares de sus historias e investigaciones cuando los editores le sugirieron que las convirtiera en un libro, edici\u00f3n que le llev\u00f3 alrededor de 20 a\u00f1os de su vida.<\/p>\n<p>\u201cLas historias que se relatan en el libro fueron recopiladas por los relatos de su familia, personas que conoci\u00f3 en sus viajes o incluso sus pacientes, como parte de su trabajo de investigaci\u00f3n cl\u00ednica\u201d<a href=\"#_ftn1\" name=\"_ftnref1\">[1]<\/a>. La autora es psicoanalista y tiene un doctorado en Estudios interculturales y psicolog\u00eda Cl\u00ednica, tambi\u00e9n fue directora ejecutiva del <em>Jung Center for Education and Research<\/em>. La autora analiza las historias como una forma de transmitir conocimientos sobre los ciclos de la vida, las formas de sanar, y tambi\u00e9n como formas de arte que pueden usarse para ayudar a las personas en el camino.<\/p>\n<p>Puedo decir que es un libro que le\u00ed toda mi vida, y no es que lo leyera todos los d\u00edas, mi contacto se dio de manera natural y jam\u00e1s lo le\u00ed entero o de corrido.<br \/>\nAnte una situaci\u00f3n propia de angustia, desconsuelo, alegr\u00eda o incertidumbre; ante la escucha a una mujer que estaba acompa\u00f1ando, que atravesaba una dura situaci\u00f3n\u2026 siempre relacionada con su historia, estructuras y temores con origen en el instinto, abr\u00eda una p\u00e1gina y la segu\u00eda hasta donde me llevara. Esa fue y es mi conexi\u00f3n y confluencia con la obra. Su tuviera que hacer una recomendaci\u00f3n les dir\u00eda: nunca dejen de leerlo, de a pedazos, entero, por cap\u00edtulos, como sea\u2026 no dejen de leerlo.<\/p>\n<p>Por\u00a0<a href=\"https:\/\/diariofemenino.com.ar\/df\/?s=Lenny+C%C3%A1ceres\">Lenny C\u00e1ceres<\/a>*<\/p>\n<p><a href=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/Mujeres-que-corren-con-los-lobos-1998.pdf\">Descargarlo<\/a> en la portada o en la <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/biblioteca\/\">Biblioteca Virtual<\/a><\/p>\n<figure id=\"attachment_73741\" aria-describedby=\"caption-attachment-73741\" style=\"width: 293px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/Mujeres-que-corren-con-los-lobos-1998.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-73741\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/MujeresQueCorrenConlosLobos.jpg\" alt=\"Hoy te cuento: Mujeres que corren con los lobos\" width=\"293\" height=\"400\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/MujeresQueCorrenConlosLobos.jpg 293w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/MujeresQueCorrenConlosLobos-220x300.jpg 220w\" sizes=\"auto, (max-width: 293px) 100vw, 293px\" \/><\/a><figcaption id=\"caption-attachment-73741\" class=\"wp-caption-text\">Hoy te cuento: Mujeres que corren con los lobos<\/figcaption><\/figure>\n<p>Como para comenzar a desnudar esa maravillosa herramienta (prefiero ante que mencionarla obra literaria, que tambi\u00e9n lo es), puedo contar que este libro revela interesantes e intensos mitos interculturales, cuentos de hadas e historias para contribuir a que las mujeres recuperen su fuerza y su salud.<\/p>\n<p>\u00bfPor qu\u00e9 leerlo?\u00a0 \u201cLas mujeres que corren con los lobos\u201d nos brinda claves para saber reconocer, rescatar del olvido, y muchas veces del desconocimiento, lo que la autora describe como un instinto femenino primitivo que nos invita a ser libres. \u201cPara amar a una mujer, el hombre tiene que amar tambi\u00e9n su naturaleza ind\u00f3mita\u201d, asegura.<\/p>\n<p>Cuando habla de los huesos se refiere a que nos pongamos en la tarea de buscar nuestros huesos-semillas indestructibles, donde se a\u00fanan la vida y la muerte:\u00a0la luz de la vida que llevan las mujeres en sus ovarios&#8230; y cant\u00e9mosle una canci\u00f3n. Cantar significa utilizar la voz del alma, decir la verdad acerca del propio ser y las propias necesidades. Siempre que atravesaba esa parte me preguntaba \u00bfcu\u00e1l es mi canci\u00f3n? Nunca era la misma, pero les puedo asegurar que escucharla era un alivio y me ha resultado sanadora.<\/p>\n<p>Y ante la pregunta que muchas nos hicimos y se hacen sobre \u00bfqu\u00e9 significa correr con lobos? No es nada m\u00e1s y nada menos que encontrarse con lo numinoso de una sin huir, viviendo activamente con la naturaleza salvaje de una manera propia.<\/p>\n<p><strong>Resumen<\/strong><\/p>\n<p><strong>\u00abMujeres que corren con los lobos\u00bb<\/strong>, de Clarissa Pinkola Est\u00e9s, publicado en 1989 -comenzado a editar en 1971-, es una obra que mezcla psicolog\u00eda, mitolog\u00eda y narraci\u00f3n para explorar la naturaleza instintiva y salvaje de las mujeres. Compartimos un resumen de los principales temas:<\/p>\n<p>Dentro de la<strong> introducci\u00f3n y premisa <\/strong>se destaca que el libro parte de la idea de que todas las mujeres tienen una \u00abmujer salvaje\u00bb dentro de ellas, un arquetipo profundo que representa la esencia instintiva, creativa y sabia de la feminidad. Este arquetipo ha sido suprimido y desvalorizado en muchas culturas (y sistemas pol\u00edticos, como el patriarcal), lo que ha llevado a que las mujeres pierdan el contacto con su verdadera naturaleza.<\/p>\n<p>Se estructura en varios cap\u00edtulos, cada uno de los cuales narra un cuento o mito de diferentes culturas. A partir de estas historias, la autora extrae lecciones sobre la psicolog\u00eda femenina, la recuperaci\u00f3n de la fuerza interna y la conexi\u00f3n con la naturaleza salvaje. De esos <strong>cap\u00edtulos p<\/strong><strong>rincipales <\/strong>compartimos:<\/p>\n<ul>\n<li><strong>La Loba (La Mujer Salvaje)<\/strong>: A trav\u00e9s de la historia de la Loba, una figura que recolecta huesos y resucita esqueletos de lobos, la autora explica c\u00f3mo las mujeres deben recordar y recuperar partes de s\u00ed mismas que han sido olvidadas o reprimidas. Es un llamado a despertar la naturaleza instintiva.<br \/>\n<strong>Barba Azul<\/strong>: Esta historia sirve como advertencia sobre los peligros de no prestar atenci\u00f3n a las se\u00f1ales internas de peligro. Ense\u00f1a sobre la importancia de la intuici\u00f3n y la sabidur\u00eda interior para evitar caer en situaciones da\u00f1inas.<\/li>\n<li><strong>Vasalisa la Sabia<\/strong>: Este cuento ruso narra el viaje de una joven que, gracias a su intuici\u00f3n (representada por una mu\u00f1eca m\u00e1gica), logra sobrevivir y prosperar. Refuerza la idea de confiar en la sabidur\u00eda interna y en la fuerza de las mujeres para superar pruebas.<\/li>\n<li><strong>La Mujer Esqueleto<\/strong>: En este mito <em>inuit<a href=\"#_ftn2\" name=\"_ftnref2\"><strong>[2]<\/strong><\/a><\/em>, la autora habla de la relaci\u00f3n entre la vida y la muerte en el amor, y c\u00f3mo enfrentar los aspectos oscuros y dif\u00edciles de la vida es necesario para encontrar la plenitud y la renovaci\u00f3n.<\/li>\n<li><strong>La Llorona<\/strong>: A trav\u00e9s de la leyenda de la mujer que pierde a sus hijos, se explora el dolor, la culpa y la redenci\u00f3n. Es una reflexi\u00f3n sobre c\u00f3mo lidiar con el sufrimiento y las emociones reprimidas.<\/li>\n<li><strong>\u00a0<\/strong><strong>El Patito Feo<\/strong>: La historia del patito que no encaja hasta que descubre su verdadera identidad como cisne es utilizada para hablar de la b\u00fasqueda de la identidad y el reconocimiento del propio valor.<\/li>\n<\/ul>\n<p><strong>No pueden quedar fuera de este breve resumen la fuerza e importancia de los temas clave de la publicaci\u00f3n.<\/strong><\/p>\n<ul>\n<li><strong>Recuperaci\u00f3n del Yo Salvaje<\/strong>: El libro insiste en la necesidad de que las mujeres reconecten con su naturaleza instintiva y libre, que ha sido silenciada por la sociedad patriarcal.<\/li>\n<li><strong>Intuici\u00f3n<\/strong>: La intuici\u00f3n es presentada como una herramienta poderosa que todas las mujeres poseen y deben aprender a escuchar para protegerse y prosperar.<br \/>\n<strong>Ciclos de Vida, Muerte y Renacimiento<\/strong>: Las historias muestran c\u00f3mo la vida est\u00e1 llena de ciclos naturales de destrucci\u00f3n y creaci\u00f3n, y c\u00f3mo las mujeres deben aceptar y abrazar estos ciclos para crecer.<br \/>\n<strong>Sanaci\u00f3n y Autenticidad<\/strong>: A trav\u00e9s de la introspecci\u00f3n y la conexi\u00f3n con la mujer salvaje, se puede alcanzar la sanaci\u00f3n personal y una vida m\u00e1s aut\u00e9ntica.<\/li>\n<\/ul>\n<p><strong>Conclusi\u00f3n<\/strong><\/p>\n<p>\u00abMujeres que corren con los lobos\u00bb es un llamado a las mujeres para que redescubran su fuerza interior, se conecten con su naturaleza salvaje y vivan de manera plena y aut\u00e9ntica. La obra combina narrativas tradicionales con an\u00e1lisis psicol\u00f3gico para ofrecer una gu\u00eda espiritual y emocional hacia la autorrealizaci\u00f3n femenina.<\/p>\n<p><strong>\u00a0A modo de cierre les regalamos: <\/strong><\/p>\n<p style=\"text-align: center;\"><em><strong>25 frases del libro \u201cMujeres que corren con los lobos\u201d<a href=\"#_ftn3\" name=\"_ftnref3\">[3]<\/a><\/strong><\/em><\/p>\n<ol>\n<li style=\"list-style-type: none;\">\n<ol>\n<li><strong>\u00a0<\/strong><strong>Ser uno mismo<br \/>\n<\/strong>\u201cSer nosotros mismos hace que acabemos exiliados por muchos otros. Sin embargo, cumplir con lo que otros quieren nos causa exiliarnos de nosotros mismos.\u201d<\/li>\n<li><strong>El aut\u00e9ntico crecimiento<br \/>\n<\/strong>\u201cSi vivimos como respiramos, tomando y soltando, no podremos equivocarnos.\u201d<\/li>\n<li><strong>Tocar fondo<br \/>\n<\/strong>\u201cEl fondo es el mejor terreno para sembrar y volver a cultivar algo nuevo. En este sentido, alcanzar el fondo, aunque sea extremadamente doloroso, es tambi\u00e9n llegar al terreno de siembra.\u201d<\/li>\n<li><strong>Ser fuertes<br \/>\n<\/strong>\u201cSer fuerte no significa tener m\u00fasculos y hacer flexiones. Significa afrontar la propia numinosidad sin huir, viviendo activamente con la naturaleza salvaje cada una a su manera. Significa poder aprender, poder resistir lo que sabemos. Significa resistir y vivir.\u201d<\/li>\n<li><strong>Alejarse permite reencontrarse<br \/>\n<\/strong>\u201cAunque el exilio no es algo que se desee por diversi\u00f3n, hay una ganancia inesperada en \u00e9l: son muchos los regalos del exilio. Saca la debilidad a golpes, hace desaparecer los pla\u00f1idos, habilita la percepci\u00f3n interna aguda, acrecienta la intuici\u00f3n, otorga el poder de la observaci\u00f3n penetrante.\u201d<br \/>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/uth.hn\/wp-content\/uploads\/2020\/01\/LOBOS-2-300x300.jpg\" \/><\/li>\n<li><strong>Aprender el amor profundo<br \/>\n<\/strong>La diferencia entre vivir desde el alma y vivir s\u00f3lo desde el ego radica en tres cosas: la habilidad de percibir y aprender nuevas maneras, la tenacidad de atravesar senderos turbulentos y la paciencia de aprender el amor profundo con el tiempo.<\/li>\n<li><strong>Coraz\u00f3n dispuesto<br \/>\n<\/strong>Ser\u00eda un error pensar que se necesita ser un h\u00e9roe endurecido para lograrlo. No es as\u00ed. Se necesita un coraz\u00f3n que est\u00e9 dispuesto a morir y nacer y morir y nacer una y otra vez.<\/li>\n<li><strong>Construir puentes<br \/>\n<\/strong>Independientemente de las afiliaciones o influencias colectivas, nuestro reto a favor del alma salvaje y de nuestro esp\u00edritu creativo es no fusionarnos con colectividad alguna, sino distinguirnos de quienes nos rodean, construyendo puentes para regresar a ellos seg\u00fan elijamos.<\/li>\n<li><strong>Aprender a ver<br \/>\n<\/strong>Para poder ver la direcci\u00f3n correcta, debemos ser capaces de ver las equivocadas.<\/li>\n<li><strong> Recuperar la vida<br \/>\n<\/strong>No podemos controlar qui\u00e9n nos trae al mundo. No podemos influir en la fluidez con que nos educan. No podemos obligar a la cultura a volverse instant\u00e1neamente hospitalaria. Pero las buenas noticias son que, a\u00fan despu\u00e9s de ser heridos, a\u00fan en un estado fetal, a\u00fan incluso en un estado hasta el momento de captura, podemos recuperar nuestras vidas.<\/li>\n<li><strong> Apostar a lo que se quiere<br \/>\n<\/strong>Si permanecemos s\u00f3lo como sobrevivientes sin avanzar hacia el florecimiento, nos limitamos y cortamos la energ\u00eda hacia nosotros y nuestro poder en el mundo a menos de la mitad. A veces las personas temen avanzar m\u00e1s all\u00e1 del status de sobreviviente, por ser exactamente eso \u2014un status, una marca de distinci\u00f3n, un logro de \u201c\u00a1Maldita sea! \u00a1Apuesta lo que quieras! \u00a1M\u00e1s vale que lo creas!\u201d<br \/>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/uth.hn\/wp-content\/uploads\/2020\/01\/LOBO6-300x223.jpg\" \/><\/li>\n<li><strong>Sostenerse y vivir<br \/>\n<\/strong>Ser fuerte no significa hacer brotar m\u00fasculos y flexi\u00f3n. Significa encontrarse con lo numinoso de uno sin huir, viviendo activamente con la naturaleza salvaje de una manera propia.<\/li>\n<li><strong>Aprender m\u00e1s all\u00e1 del momento presente<br \/>\n<\/strong>Quienes no encuentran deleite en aprender, quienes no pueden sentirse atra\u00eddos por nuevas ideas o experiencias, no podr\u00e1n desarrollarse m\u00e1s all\u00e1 del punto en el camino donde descansan ahora.<\/li>\n<li><strong>El fracaso es el mejor maestro del \u00e9xito<br \/>\n<\/strong>En nuestra vida, aun cuando un episodio resulte en una ca\u00edda fuerte o una quemadura seria, siempre hay otro episodio esper\u00e1ndonos, y luego otro. El fracaso es mejor maestro que el \u00e9xito. Escucha, aprende, sigue adelante.<\/li>\n<li><strong>Una nueva vida<br \/>\n<\/strong>Se nos ha ense\u00f1ado que a la muerte siempre le sigue m\u00e1s muerte. Simplemente no es as\u00ed. La muerte siempre est\u00e1 en proceso de incubar nueva vida, aun cuando nuestra existencia haya sido cortada hasta los huesos.<\/li>\n<li><strong>Nuevo comienzo<br \/>\n<\/strong>La \u00fanica confianza requerida es saber que cuando hay un final habr\u00e1 otro comienzo.<\/li>\n<li><strong>Ir hacia adelante<br \/>\n<\/strong>Por lo general cada miedo tiene tres partes: una parte es un residuo del pasado (siendo esto a menudo una fuente de verg\u00fcenza), otra parte es una carencia de certidumbre en el presente, y otra parte es miedo a un resultado deficiente o a consecuencias negativas en el futuro.<br \/>\n<img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/uth.hn\/wp-content\/uploads\/2020\/01\/LOBOS-4-247x300.jpg\" \/><\/li>\n<li><strong>Buscar lo que se quiere<br \/>\n<\/strong>Es peor quedarse donde uno no pertenece en absoluto, que vagar perdido por un tiempo y buscar el parentesco ps\u00edquico y espiritual que uno requiere. Nunca es un error buscar lo que uno requiere. Nunca.<\/li>\n<li><strong>Intuici\u00f3n<br \/>\n<\/strong>\u00bfCon qu\u00e9 alimenta uno a la intuici\u00f3n para que est\u00e9 consistentemente nutrida y que responda a nuestras peticiones de escudri\u00f1ar el ambiente? Uno la alimenta de vida, uno la alimenta de vida mediante escucharla.<\/li>\n<li><strong>Instinto<br \/>\n<\/strong>La naturaleza instintiva tiene la milagrosa habilidad de sobrevivir a todo beneficio positivo, a toda consecuencia negativa, manteniendo con todo, una relaci\u00f3n con el yo y con otro.<\/li>\n<li><strong>Amar<br \/>\n<\/strong>\u201cPara amar a una mujer, el hombre tiene que amar tambi\u00e9n su naturaleza ind\u00f3mita\u201d<\/li>\n<li><strong>Encarar<br \/>\n<\/strong>Fuerte es quien encara, quien no huye, quien muestra sin miedo su identidad, no se rinde y es capaz de vivir con alegr\u00eda y coraje.<\/li>\n<li><strong>A\u00f1adir su sabor especial<br \/>\n<\/strong>La mujer que trabaja en una universidad pertenece a una colectividad acad\u00e9mica. No deber\u00e1 fundirse con cualquier cosa que le ofrezca el ambiente de dicha colectividad, sino a\u00f1adirle su propio sabor especial. Como criatura integral, a menos que haya creado en su vida otras fuerzas capaces de impedirlo, no puede permitirse el lujo de convertirse en un tipo de persona desequilibrada e irritable, de \u201chago mi trabajo, me voy a casa, vuelvo\u2026 \u201c.<\/li>\n<li><strong>Indagar<br \/>\n<\/strong>Cuando una mujer intenta formar parte de una asociaci\u00f3n, organizaci\u00f3n o familia que desde\u00f1a examinarla por dentro para ver de qu\u00e9 est\u00e1 hecha, que no pregunta \u201c\u00bfQu\u00e9 induce a esta persona a correr?\u201d y que no se esfuerza en absoluto en plantearle retos o en animarla en toda la medida de sus posibilidades, su capacidad de prosperar y crear disminuye considerablemente.<\/li>\n<li><strong>Mujeres que corren con los lobos<br \/>\n<\/strong>\u201cLa loba, la vieja, la que sabe, est\u00e1 dentro de nosotras. Florece en la m\u00e1s profunda psique del alma de las mujeres, la antigua y vital Mujer Salvaje. Ella describe su hogar como ese lugar en el tiempo donde el esp\u00edritu de las mujeres y el esp\u00edritu de los lobos hacen contacto. Es el punto donde el Yo y el T\u00fa se besan, el lugar donde las mujeres corren con los lobos (\u2026)\u201d. Clarissa Pinkola.<br \/>\n<strong><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/uth.hn\/wp-content\/uploads\/2020\/01\/LOBOS1-300x300.jpg\" \/><\/strong><\/li>\n<\/ol>\n<\/li>\n<\/ol>\n<p><strong>(*) <\/strong>Periodista feminista abolicionista, directora\/editora de Diario Digital Femenino. Co coordinadora de la Red Internacional de Periodistas con Visi\u00f3n de G\u00e9nero de Argentina\u00a0<a href=\"https:\/\/www.instagram.com\/redperiodistasgenero\">RIPVGAr<\/a>. Titular de la web de Asesoramiento y Capacitaci\u00f3n\u00a0<a href=\"https:\/\/lennycaceres.com.ar\/\">https:\/\/lennycaceres.com.ar\/<\/a>\u00a0Autora del libro\u00a0<a href=\"https:\/\/diariofemenino.com.ar\/df\/la-transversalidad-del-genero-espacios-y-disputas\/\"><em>La transversalidad del g\u00e9nero: espacios y disputas<\/em>.<\/a>(Ed.\u00a0<a href=\"https:\/\/www.libreriasudestada.com.ar\/search\/?q=Lenny+C%C3%A1ceres\">Sudestada<\/a>)<\/p>\n<p><strong>Referencias<\/strong><\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\">[1]<\/a> https:\/\/es.wikipedia.org\/wiki\/Mujeres_que_corren_con_los_lobos}<\/p>\n<p><a href=\"#_ftnref2\" name=\"_ftn2\">[2]<\/a> Hacia el a\u00f1o 1000,\u00a0la cultura Thule dio origen al pueblo inuit, que se extendi\u00f3 hacia oriente a lo largo del \u00c1rtico, desde Alaska hasta Groenlandia. En peque\u00f1as poblaciones aisladas, los inuit se distribuyeron en veinti\u00fan grupos tribales, convirti\u00e9ndose en la etnia m\u00e1s extendida geogr\u00e1ficamente.<\/p>\n<p><a href=\"#_ftnref3\" name=\"_ftn3\">[3]<\/a> https:\/\/www.uth.hn\/25-frases-del-libro-mujeres-que-corren-con-los-lobos\/<\/p>\n<p>&nbsp;<\/p>\n<blockquote><p><strong>Seguinos en Instagram. Diario Digital Femenino:\u00a0<a href=\"https:\/\/www.instagram.com\/diariodigitalfemenino_\/\">@diariodigitalfemenino_<\/a><br \/>\n<\/strong><strong>Lenny C\u00e1ceres:\u00a0<\/strong><strong><a href=\"https:\/\/www.instagram.com\/lennycaceres69\/\">@lennycaceres69<\/a><\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Mujeres que corren con los lobos, de Clarissa Pinkola Est\u00e9s Creo que la primera edici\u00f3n la tuve en mis manos a principios de los 90\u2019, mucho tiempo despu\u00e9s supe que Pinkola Est\u00e9s hab\u00eda estado produciendo cintas de audio populares de sus historias e investigaciones cuando los editores le sugirieron que las convirtiera en un libro, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":75753,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":12790,"footnotes":""},"categories":[1],"tags":[7059,957,7056,7063,4372,7060,2593,7057,7062,7058,7055,4812,6956,7061],"class_list":["post-73730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-amor-profundo","tag-ancestras","tag-clarissa-pinkola-estes","tag-cuentos-de-hadas","tag-destacada","tag-fortaleza","tag-historias","tag-intuicion","tag-mitos-interculturales","tag-mujer-salvaje","tag-mujeres-que-corren-por-los-lobos","tag-reconocimiento","tag-te-cuento-un-libro","tag-tocar-fondo"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-15T09:47:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T14:35:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"Hoy te cuento: Mujeres que corren con los lobos\",\"datePublished\":\"2024-08-15T09:47:54+00:00\",\"dateModified\":\"2026-04-17T14:35:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/\"},\"wordCount\":2449,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/mujeres-que-corren-con-los-lobos-portada.webp\",\"keywords\":[\"amor profundo\",\"Ancestras\",\"Clarissa Pinkola Est\u00e9s\",\"cuentos de hadas\",\"Destacada\",\"fortaleza\",\"Historias\",\"intuici\u00f3n\",\"mitos interculturales\",\"mujer salvaje\",\"mujeres que corren por los lobos\",\"Reconocimiento\",\"Te cuento un libro\",\"tocar fondo\"],\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/\",\"name\":\"Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/mujeres-que-corren-con-los-lobos-portada.webp\",\"datePublished\":\"2024-08-15T09:47:54+00:00\",\"dateModified\":\"2026-04-17T14:35:39+00:00\",\"description\":\"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/mujeres-que-corren-con-los-lobos-portada.webp\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/mujeres-que-corren-con-los-lobos-portada.webp\",\"width\":900,\"height\":716,\"caption\":\"Hoy te cuento: Mujeres que corren con los lobos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hoy te cuento: Mujeres que corren con los lobos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino","description":"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/","og_locale":"es_ES","og_type":"article","og_title":"Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino","og_description":"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.","og_url":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2024-08-15T09:47:54+00:00","article_modified_time":"2026-04-17T14:35:39+00:00","og_image":[{"width":900,"height":716,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","type":"image\/webp"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"12 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"Hoy te cuento: Mujeres que corren con los lobos","datePublished":"2024-08-15T09:47:54+00:00","dateModified":"2026-04-17T14:35:39+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/"},"wordCount":2449,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","keywords":["amor profundo","Ancestras","Clarissa Pinkola Est\u00e9s","cuentos de hadas","Destacada","fortaleza","Historias","intuici\u00f3n","mitos interculturales","mujer salvaje","mujeres que corren por los lobos","Reconocimiento","Te cuento un libro","tocar fondo"],"articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/","url":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/","name":"Hoy te cuento: Mujeres que corren con los lobos - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","datePublished":"2024-08-15T09:47:54+00:00","dateModified":"2026-04-17T14:35:39+00:00","description":"Mujeres que corren con los lobos \u00bfPor qu\u00e9 leerlo? Nos brinda claves para saber reconocer, rescatar del olvido un instinto femenino primitivo.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","width":900,"height":716,"caption":"Hoy te cuento: Mujeres que corren con los lobos"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/hoy-te-cuento-mujeres-que-corren-con-los-lobos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Hoy te cuento: Mujeres que corren con los lobos"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp","jetpack_sharing_enabled":true,"rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada-150x150.webp",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada-300x239.webp",300,239,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2024\/08\/mujeres-que-corren-con-los-lobos-portada.webp",900,716,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","rttpg_excerpt":"Mujeres que corren con los lobos, de Clarissa Pinkola Est\u00e9s Creo que la primera edici\u00f3n la tuve en mis manos a principios de los 90\u2019, mucho tiempo despu\u00e9s supe que Pinkola Est\u00e9s hab\u00eda estado produciendo cintas de audio populares de sus historias e investigaciones cuando los editores le sugirieron que las convirtiera en un libro,&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/73730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=73730"}],"version-history":[{"count":1,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/73730\/revisions"}],"predecessor-version":[{"id":75754,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/73730\/revisions\/75754"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/75753"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=73730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=73730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=73730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}