{"id":69145,"date":"2023-05-17T07:06:40","date_gmt":"2023-05-17T10:06:40","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/df\/?p=69145"},"modified":"2023-05-17T07:06:40","modified_gmt":"2023-05-17T10:06:40","slug":"mujeres-protagonistas-en-la-construccion-de-la-historia-nacional","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/","title":{"rendered":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional"},"content":{"rendered":"<p>Mujeres protagonistas.<\/p>\n<p>Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds, es el episodio conocido como la guerra civil protagonizada por unitarios y federales que dio origen a la construcci\u00f3n de la Ciudad de Buenos Aires como epicentro pol\u00edtico y econ\u00f3mico de las Provincias Unidas del Rio de la Plata. Siempre que se habla de sus pr\u00f3ceres, aparecen nombres como Bernardino Rivadavia, Juan Lavalle, Manuel Dorrego, Jos\u00e9 Gervasio de Artigas, Juan Manuel de Rosas y otros hombres relacionados con el caudillaje, tales como Felipe Varela, o el Chacho \u00c1ngel Vicente Pe\u00f1aloza. Y las mujeres\u2026 \u00bfd\u00f3nde estaban?<\/p>\n<p>Por\u00a0<em><a href=\"https:\/\/diariofemenino.com.ar\/df\/?s=Mar%C3%ADa+In%C3%A9s+Alvarado\">Mar\u00eda In\u00e9s Alvarado<\/a>*<br \/>\npara\u00a0<a href=\"https:\/\/www.instagram.com\/diariodigitalfemenino_\/\">Diario Digital Femenino<\/a><\/em><\/p>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Seg\u00fan la \u201chistoria oficial\u201d, aparecen silenciadas en sus hogares, haciendo tareas dom\u00e9sticas o cuidando de sus familias. Sin embargo, y gracias a la importancia que en los \u00faltimos tiempos ha tenido el revisionismo hist\u00f3rico desde las nuevas perspectivas, se puede comenzar a pensar otra mirada de c\u00f3mo sucedieron los acontecimientos. En el art\u00edculo <em><a href=\"https:\/\/www.redalyc.org\/journal\/200\/20060770004\/html\/\">Mujeres de la \u201cbarbarie\u201d, resistencia a la organizaci\u00f3n del Estado nacional argentino, 1861-1870<\/a><\/em>, la historiadora Ana Teresa\u00a0Fanchin, de la Universidad Nacional de San Juan,\u00a0plantea que entre <em>\u201cestos<\/em><em> caudillos federales fueron caratulados como crueles, sanguinarios y salvajes, (\u2026) estigmatizados como hordas de varones aguerridos, resulta dif\u00edcil reconocer la presencia de sujetos femeninos\u201d. <\/em>Aunque, agrega, que <em>\u201cLa participaci\u00f3n de las mujeres pod\u00eda ser m\u00e1s audaz y comprometida, (\u2026) Dolores D\u00edaz \u2013la compa\u00f1era de Felipe Varela- apodada La Tigra, desempe\u00f1\u00f3 un importante papel en las acciones de los montoneros<\/em>.\u201d Sin salir de su \u00e1mbito hogare\u00f1o, -cuenta la historiadora- que fue una de las principales agentes que los montoneros ten\u00edan en la ciudad de La Rioja ocultando en su casa art\u00edculos de guerra que ella misma hab\u00eda transportado.<\/p>\n<figure id=\"attachment_69152\" aria-describedby=\"caption-attachment-69152\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-69152\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Unitarios-y-Federales-300x225.jpg\" alt=\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional\" width=\"300\" height=\"225\" \/><figcaption id=\"caption-attachment-69152\" class=\"wp-caption-text\">Mujeres protagonistas en la construcci\u00f3n de la historia nacional<\/figcaption><\/figure>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Aparecen tambi\u00e9n en esta investigaci\u00f3n, otros nombres de mujeres implicadas en revueltas revolucionarias. Una de ellas, Rosa Torres, apodada \u201cel sanjuanino\u201d, actu\u00f3 desde el anonimato en la sublevaci\u00f3n de Jachal, el 6 de diciembre de 1866 al mando de Juan Arce <em>\u201cno es descabellado suponer que el sanjuanino no ser\u00eda otro que una mujer travestida de var\u00f3n. Quiz\u00e1s, algunos montoneros lo desconoc\u00edan, pero los que s\u00ed lo sab\u00edan procuraron resguardarla; m\u00e1s que nada porque como el propio Arce declar\u00f3, no ten\u00edan consigo armas porque el tal Rosa se las hab\u00eda llevado\u201d<\/em>, describe Fanchin. A ella se suman Francisca Manrique, pareja de Antonio Alcaraz, Br\u00edgida Ferreira, Tomasa Robledo y Mar\u00eda Maldonado, por nombrar algunas de las mujeres implicadas en revueltas, que quedaron registradas en expedientes judiciales. <em>\u201c(\u2026) las referencias sobre algunas de ellas son suficientes como para reconocer que no formaron parte de ese imaginario construido a partir de la consolidaci\u00f3n nacional decimon\u00f3nica en que la mujer quedaba relegada al hogar, asumiendo una actitud pasiva y cumpliendo exclusivamente un rol reproductivo y de cuidados\u201d<\/em>, agrega la historiadora.<\/p>\n<figure id=\"attachment_69151\" aria-describedby=\"caption-attachment-69151\" style=\"width: 260px\" class=\"wp-caption alignright\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-69151\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Encarnacion_Ezcurra_1835.jpg\" alt=\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional\" width=\"260\" height=\"311\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Encarnacion_Ezcurra_1835.jpg 834w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Encarnacion_Ezcurra_1835-250x300.jpg 250w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Encarnacion_Ezcurra_1835-768x921.jpg 768w\" sizes=\"auto, (max-width: 260px) 100vw, 260px\" \/><figcaption id=\"caption-attachment-69151\" class=\"wp-caption-text\">Mujeres protagonistas en la construcci\u00f3n de la historia nacional<\/figcaption><\/figure>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pero, en este recuento hist\u00f3rico de mujeres silenciadas por la historia oficial, no se puede dejar de mencionar a Mar\u00eda de la Encarnaci\u00f3n Ezcurra esposa de Juan Manuel de Rosas y Hero\u00edna de la Federaci\u00f3n, una de las mujeres que m\u00e1s poder tuvo en el territorio de las Provincias Unidas del R\u00edo de la Plata, entre 1833 y 1835, per\u00edodo en el que Rosas estuvo alejado del escenario pol\u00edtico, y Encarnaci\u00f3n desarroll\u00f3 un papel crucial. Nacida en una familia que pertenec\u00eda a la \u00e9lite de comerciantes, fingi\u00f3 un embarazo a los 18 a\u00f1os para poder contraer matrimonio con el Restaurador de las leyes. Encarnaci\u00f3n se mostr\u00f3 como ladera, compa\u00f1era y aliada, de quien fuera su marido durante 25 a\u00f1os. La historia la retrata como una mujer de car\u00e1cter fuerte, impetuosa y que pod\u00eda llegar a ser impiadosa. Fue protagonista de la pol\u00edtica cuando \u00e9sta era patrimonio exclusivo de los varones, describe Daniel Giarone en la nota <em><a href=\"https:\/\/www.telam.com.ar\/notas\/202202\/583847-rosa-encarnacion-ezcurra-amores-historia.html\">Encarnaci\u00f3n, Juan Manuel y la pasi\u00f3n en tiempos de c\u00f3lera<\/a><\/em>, publicada en el portal de noticias T\u00e9lam.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u201c<em>Las unitarias van detr\u00e1s de los maridos y de lo que se cuchichea en los salones. Ellas tienen la monarqu\u00eda en la cabeza, entre las piernas, y en esa manera de dirigirse a la pueblada. Siempre mandando y nunca dando ni prometiendo nada\u201d <\/em>escribi\u00f3 en alg\u00fan momento de su corta vida<em>.<\/em>\u00a0 Al finalizar el primer mandato de su marido y alejado del escenario pol\u00edtico, su papel fue crucial para derrotar a la facci\u00f3n de federales antirrosistas y conseguir apoyo para que le otorgasen a su marido facultades extraordinarias. Obtuvo el respaldo pol\u00edtico de sectores populares para encauzar la movilizaci\u00f3n popular a favor de Rosas en la Revoluci\u00f3n de los Restauradores. <em>\u201cA ellas no les gusta ser del pueblo y al pueblo no le gusta tanta do\u00f1a afrancesada. El pueblo es otra cosa: el pueblo es Federal, el pueblo es mondongo, candombe, mozambique, molemb\u00f3s y, desde luego, balazos y cuchilladas, y yo, soy del pueblo. Las unitarias nacieron para esconderse en la frontera. Y yo nac\u00ed para mandar entre los m\u00edos. Y los m\u00edos me obedecen y los ajenos me temen\u201d- agreg\u00f3 tambi\u00e9n.\u00a0\u00a0 <\/em><\/p>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Y en este breve paso de mujeres de esa \u00e9poca de la historia que vale la pena destacar, es preciso recordar a Camila O\u2019Gorman, cuya tr\u00e1gica muerte por haberse enamorado del hombre equivocado, dio lugar a una emblem\u00e1tica pel\u00edcula del cine nacional dirigida por <a href=\"http:\/\/www.marialuisabemberg.com\/camila.html\">Mar\u00eda Luisa Bemberg<\/a>. En ella se narra la historia de amor real de Camila y el joven sacerdote jesuita, Ladislao Guti\u00e9rrez, ocurrida bajo el gobierno de Juan Manuel de Rosas, \u00e9poca donde \u201cEl abuso del poder, la arbitrariedad, la represi\u00f3n, constituyen moneda corriente (\u2026) donde el acatamiento a las virtudes dom\u00e9sticas es un mandato\u201d describe la sinopsis del guion. Camila, amiga \u00edntima y confidente de la hija de Juan Manuel Rosas, la popular Manuelita, \u201c<em>ten\u00eda asegurado un destino de dama central en la alta sociedad argentina de entonces: la esperaban un casamiento inolvidable, una vida acomodada y confortable, un mundo rodeado de sirvientes y amanuenses\u201d, <\/em>describe Carlos Polimeni en el art\u00edculo <a href=\"https:\/\/www.elliberal.com.ar\/noticia\/viceversa\/629282\/la-constitucin-de-1949-ms-que-una-reforma?utm_campaign=ScrollInfinitoDesktop&amp;utm_medium=scroll&amp;utm_source=nota\">La maldici\u00f3n de Camila, una feminista temprana<\/a>.<\/p>\n<p style=\"padding-left: 30px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Poder llevar a las aulas estas historias de luchas, de amor y transgresi\u00f3n tambi\u00e9n es una forma de contar otra versi\u00f3n de la realidad, esa versi\u00f3n de la historia donde las mujeres formaron parte de las revoluciones y no solo circunscrib\u00edan sus actividades a tareas hogare\u00f1as. Una versi\u00f3n de la historia en la cual el protagonismo no es solo de varones.<\/p>\n<p><strong>(*)<\/strong>\u00a0Docente, comunicadora. Co-directora de\u00a0<strong><a href=\"https:\/\/laesienjuego.com.ar\/\">La ESI en juego<\/a>.<\/strong><br \/>\nColumnista\u00a0de\u00a0<strong><a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-esi-si-se-habla\/\">Diario Digital Femenino<\/a><\/strong>\u2013\u00a0<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-esi-si-se-habla\/\">De ESI S\u00ed Se Habla<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds, es el episodio conocido como la guerra civil protagonizada por unitarios y federales que dio origen a la construcci\u00f3n de la Ciudad de Buenos Aires como epicentro pol\u00edtico y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":69150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":184,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1067,178,9,3,21],"tags":[567,4372,5952,341,5950,568,130,5949,5951],"class_list":["post-69145","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-feminista","category-articulos-y-comunicados","category-de-esi-si-se-habla","category-de-la-revolucion-al-reaprendizaje","category-noticias","tag-de-esi-si-se-habla","tag-destacada","tag-federales","tag-historia","tag-invisibilidad","tag-maria-ines-alvarado","tag-mujeres","tag-protagonismo","tag-unitarios"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T10:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"850\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional\",\"datePublished\":\"2023-05-17T10:06:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/\"},\"wordCount\":1202,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Camila-OGorman.jpg\",\"keywords\":[\"De ESI s\u00ed se habla\",\"Destacada\",\"Federales\",\"Historia\",\"Invisibilidad\",\"Mar\u00eda In\u00e9s Alvarado\",\"Mujeres\",\"Protagonismo\",\"Unitarios\"],\"articleSection\":[\"Agenda Feminista\",\"Art\u00edculos y Comunicados\",\"De ESI S\u00ed Se Habla\",\"De la Revoluci\u00f3n al Reaprendizaje\",\"Noticias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/\",\"name\":\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Camila-OGorman.jpg\",\"datePublished\":\"2023-05-17T10:06:40+00:00\",\"description\":\"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Camila-OGorman.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Camila-OGorman.jpg\",\"width\":1500,\"height\":850,\"caption\":\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mujeres protagonistas en la construcci\u00f3n de la historia nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino","description":"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/","og_locale":"es_ES","og_type":"article","og_title":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino","og_description":"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.","og_url":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2023-05-17T10:06:40+00:00","og_image":[{"width":1500,"height":850,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional","datePublished":"2023-05-17T10:06:40+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/"},"wordCount":1202,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","keywords":["De ESI s\u00ed se habla","Destacada","Federales","Historia","Invisibilidad","Mar\u00eda In\u00e9s Alvarado","Mujeres","Protagonismo","Unitarios"],"articleSection":["Agenda Feminista","Art\u00edculos y Comunicados","De ESI S\u00ed Se Habla","De la Revoluci\u00f3n al Reaprendizaje","Noticias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/","url":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/","name":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","datePublished":"2023-05-17T10:06:40+00:00","description":"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","width":1500,"height":850,"caption":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/mujeres-protagonistas-en-la-construccion-de-la-historia-nacional\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Mujeres protagonistas en la construcci\u00f3n de la historia nacional"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg","jetpack_sharing_enabled":true,"rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg",1500,850,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg",1500,850,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg",1500,850,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman-300x170.jpg",300,170,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman-1024x580.jpg",1024,580,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg",1500,850,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/05\/Camila-OGorman.jpg",1500,850,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/agenda-feminista\/\" rel=\"category tag\">Agenda Feminista<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/articulos-y-comunicados\/\" rel=\"category tag\">Art\u00edculos y Comunicados<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-esi-si-se-habla\/\" rel=\"category tag\">De ESI S\u00ed Se Habla<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-la-revolucion-al-reaprendizaje\/\" rel=\"category tag\">De la Revoluci\u00f3n al Reaprendizaje<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a>","rttpg_excerpt":"Mujeres protagonistas. Uno de los temas para pensar la ESI desde la perspectiva de g\u00e9nero en relaci\u00f3n a la historia de la construcci\u00f3n de nuestro pa\u00eds, es el episodio conocido como la guerra civil protagonizada por unitarios y federales que dio origen a la construcci\u00f3n de la Ciudad de Buenos Aires como epicentro pol\u00edtico y&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/69145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=69145"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/69145\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/69150"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=69145"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=69145"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=69145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}