{"id":68952,"date":"2023-04-28T09:25:02","date_gmt":"2023-04-28T12:25:02","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/df\/?p=68952"},"modified":"2023-04-28T09:25:02","modified_gmt":"2023-04-28T12:25:02","slug":"de-nominaciones-instituciones-y-perspectiva-de-genero","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/","title":{"rendered":"De nominaciones, instituciones y perspectiva de g\u00e9nero"},"content":{"rendered":"<div><span style=\"font-family: arial narrow, sans-serif;\">Un oto\u00f1o, estaci\u00f3n del a\u00f1o con melod\u00eda propia nos encontr\u00f3 en 2022 haciendo historia en la hoy denominada Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos de la Rep\u00fablica Argentina, el 23 de abril de ese a\u00f1o\u00a0 y por decisi\u00f3n un\u00e1nime de delegadas y delegados de la FePRA (entidad que re\u00fane a las entidades de primer grado de cada una de las jurisdicciones del pa\u00eds a efectos de representar a\u00a0 psic\u00f3logas y psic\u00f3logos dentro y fuera del pa\u00eds, que tiene como misi\u00f3n impulsar la plena inserci\u00f3n laboral de las\/os psic\u00f3logas\/os jerarquizando a la psicolog\u00eda desde el punto de vista cient\u00edfico y desde el ejercicio profesional, en cada \u00e1rea de aplicaci\u00f3n, consensuando criterios actualizados de la \u00e9tica y la regulaci\u00f3n del ejercicio profesional, se vot\u00f3 el cambio de nominaci\u00f3n de la instituci\u00f3n.<\/span><\/div>\n<div><span style=\"font-family: arial narrow, sans-serif;\">Haciendo historia vamos a repasar algunos fragmentos del proyecto presentado oportunamente para tal fin.<\/span><\/div>\n<div>\n<figure id=\"attachment_68955\" aria-describedby=\"caption-attachment-68955\" style=\"width: 279px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-68955\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/images-27.jpg\" alt=\"De nominaciones - FePRA\" width=\"279\" height=\"180\" \/><figcaption id=\"caption-attachment-68955\" class=\"wp-caption-text\">De nominaciones &#8211; <a href=\"https:\/\/gestionfepra.com.ar\/\">FePRA<\/a><\/figcaption><\/figure>\n<\/div>\n<div><\/div>\n<div>Por\u00a0<a href=\"https:\/\/diariofemenino.com.ar\/df\/generos-y-salud-mental\/\"><strong>M\u00f3nica Vaccaro<\/strong><\/a>*<\/div>\n<div><span style=\"font-family: arial narrow, sans-serif;\">\u00a0<\/span><\/div>\n<div>\n<p dir=\"ltr\">\u00ab&#8230;El 3 de diciembre de 1977 se constituy\u00f3 una Asociaci\u00f3n Civil sin fines de lucro con la denominaci\u00f3n de FEDERACI\u00d3N DE PSIC\u00d3LOGOS DE LA REP\u00daBLICA ARGENTINA.<\/p>\n<p dir=\"ltr\">Es necesario enmarcar el contexto pa\u00eds de ese momento, plena dictadura c\u00edvico-militar, donde por el solo acto de pensar se era reprimido, y quienes se expresar\u00e1n perseguidas\/os, secuestradas\/os, torturadas\/os, desaparecidas\/os, tama\u00f1o desaf\u00edo el que asumieron las y los colegas que nos precedieron al poner en marcha instituciones que impulsaran las leyes de ejercicio profesional, cabe recordar que en ese momento psic\u00f3logas y psic\u00f3logos eran auxiliares de la medicina.<\/p>\n<p dir=\"ltr\">Serias preocupaciones las de ese tiempo que quedan reflejadas en el texto del documento de octubre de 1974 surgido en el encuentro de colegas y estudiantes de psicolog\u00eda en C\u00f3rdoba.<\/p>\n<p dir=\"ltr\">\u00bfPARA QU\u00c9 Y PORQU\u00c9 QUEREMOS LA LEY DE EJERCICIO PROFESIONAL? &#8211; 1\u00b0- Porque necesitamos un reconocimiento jur\u00eddico y un enmarque espec\u00edfico dentro de lo legal, para el desempe\u00f1o, tanto en instituciones oficiales como centros privados. 2\u00b0- Para poder controlar nuestro ejercicio profesional. 3\u00b0- Para poder defender nuestro ejercicio profesional. 4\u00b0- Para poder lograr una Psicolog\u00eda al servicio de las reales necesidades de nuestro pueblo y contar con la garant\u00eda de la defensa de nuestro ejercicio.<\/p>\n<p dir=\"ltr\">Situarnos en este contexto nos permite historizar en relaci\u00f3n a la importancia de la nominaci\u00f3n psic\u00f3logo y como se parti\u00f3 desde ah\u00ed para dar sustento a las luchas colectivas. En esos momentos no se discut\u00eda lenguaje inclusivo, mucho menos con el patriarcado con ropaje de botas, secuestro, tortura, desaparici\u00f3n y muerte.<\/p>\n<p dir=\"ltr\">Muchos a\u00f1os pasaron en el mientras tanto de la construcci\u00f3n de memoria colectiva y la deconstrucci\u00f3n de posicionamientos en relaci\u00f3n a c\u00f3mo nombrar nuestras instituciones, hoy habitadas en un 86% por mujeres. Interpelar el orden establecido no es tarea sencilla y volvemos a convocar al recuerdo y a la historia, parafraseando a Galeano \u201ccon hilos de palabras vamos diciendo, con hilos de tiempo vamos viviendo\u2026\u201den esos hilos de tiempo recordamos que la primera presidenta de FePRA fue Beatriz Perosio, mujer, militante pol\u00edtica, quien fue secuestrada el 8 de agosto de 1978 del jard\u00edn de infantes que hab\u00eda fundado con una compa\u00f1era con el objetivo de acompa\u00f1ar ni\u00f1eces a desarrollar pensamiento cr\u00edtico entre muchas otros legados acerca del compromiso social y los proyectos colectivos, en otros hilos de tiempo en 2009, en asamblea de delegadas y delegados se propone instaurar en esta sala el nombre de Beatriz Perosio y declarar el 8 de agosto como d\u00eda Nacional de las\/os psic\u00f3logas\/os v\u00edctimas del terrorismo de estado. Tambi\u00e9n se resolvi\u00f3 otorgar el \u201cPremio Beatriz Perosio\u201d en los Congresos Argentinos de Psicolog\u00eda a partir del a\u00f1o 2012 al mejor trabajo cient\u00edfico que aborde las tem\u00e1ticas de Salud Mental y Derechos Humanos.<\/p>\n<p dir=\"ltr\">En estos 45 a\u00f1os de camino al andar comprometidas colegas tambi\u00e9n fueron presidentas en una instituci\u00f3n que no las incluye en su nominaci\u00f3n, y seguir\u00e1n\/mos siendo protagonistas en el tejido de la historia de nuestra federaci\u00f3n, de las entidades que nos agrupan y del compromiso \u00e9tico-social con el ejercicio de la profesi\u00f3n. Con el impulso de la Comisi\u00f3n Nacional de Derechos Humanos y retomando esos hilos de voces se avanz\u00f3 hacia la nominaci\u00f3n de las Jornadas Nacionales de Psicolog\u00eda y Derechos Humanos con el nombre de la querida colega\/compa\u00f1era Mirta Clara.<\/p>\n<p dir=\"ltr\">Los pendientes de la nominaci\u00f3n nos desaf\u00edan e incomodan cada d\u00eda, y el reclamo se torna urgente.<\/p>\n<p dir=\"ltr\">En distintos \u00e1mbitos se debate, se toman posiciones, se produce conocimiento, tal as\u00ed que tomamos algunas consideraciones:<\/p>\n<p dir=\"ltr\">\u00a0\u201cEs necesario tomar conciencia sobre el uso del lenguaje. En la medida en que el lenguaje representa y construye el mundo en el que vivimos, puede ser tanto reproductor de estereotipos como una herramienta de cambio, un instrumento fundamental para la construcci\u00f3n de una sociedad igualitaria\u201d (INADI, 2015, p. 57).<\/p>\n<p dir=\"ltr\">\u201cEl lenguaje, como sabemos, es una convenci\u00f3n social y su uso es un reflejo de las pr\u00e1cticas culturales y las relaciones de poder existentes en la sociedad\u2026Fueron los movimientos sociales y los feminismos quienes comenzaron a evidenciar, hace ya varias d\u00e9cadas, el car\u00e1cter pol\u00edtico del uso del lenguaje, visibilizando y problematizando la reproducci\u00f3n de estereotipos de g\u00e9nero y sus implicaciones sexistas y androc\u00e9ntricas\u2026 El uso del g\u00e9nero gramatical masculino como gen\u00e9rico y como referencia para designar a hombres y mujeres, a ni\u00f1as y ni\u00f1os, oculta la realidad de una consideraci\u00f3n y un trato desigual. (SENAF,2020, p.4)<\/p>\n<p dir=\"ltr\">\u201cSe entiende por lenguaje inclusivo entonces, o por lenguaje no sexista, aquel que no oculte, ni subordine, ni excluya a ninguno de los g\u00e9neros y sea responsable al considerar, respetar y hacer visible a todas las personas, reconociendo la diversidad sexual y de g\u00e9nero. Cambiar el uso del lenguaje implica tambi\u00e9n un cambio cultural, y nos convoca a construir otro sistema de valores, otra forma de entender, de pensar y de representar al mundo\u201d (HCDN, Gu\u00eda sobre lenguaje Inclusivo, p.10)<\/p>\n<p dir=\"ltr\">Y cabe la pregunta \u00bfC\u00f3mo salvamos el tema del binarismo, en un pa\u00eds donde hay una Ley de Identidad de G\u00e9nero, pionera en el mundo y que reconoce el derecho a la identidad de g\u00e9nero de las personas, y la define en funci\u00f3n de la propia autopercepci\u00f3n? Este proceso de deconstrucci\u00f3n del binarismo se vio reflejado en el uso del lenguaje inclusivo en los \u00faltimos a\u00f1os, con propuestas como el uso del @ o la x que no llegan a instalarse por las dificultades en la lectura. Entonces la e como deriva a las formas anteriores aparece como una salida al binarismo a partir de una pr\u00e1ctica oral discursiva, si bien su utilizaci\u00f3n da cuenta de la diversidad sexual y de g\u00e9nero, su incorporaci\u00f3n forma parte de un proceso cultural m\u00e1s amplio que se encuentra a\u00fan en desarrollo.<\/p>\n<p dir=\"ltr\">Debemos perder el miedo a la modificaci\u00f3n del lenguaje, a la creaci\u00f3n de nuevas formas discursivas. El lenguaje ha ido evolucionando y lo seguir\u00e1 haciendo, m\u00e1s lo importante es que ese camino irreversible lo sea de manera inclusiva.\u00a0La neutralidad no hace desaparecer a los individuos, todo lo contrario, permite que la diversidad aflore y sea incluida, que fluya, que se nomine, que nadie quede afuera&#8230;\u00bb<\/p>\n<p><span style=\"color: #333333;\"><i>Historizando para construir memoria colectiva haciendo base en que, <b>nominar es pol\u00edtico y no hacerlo tambi\u00e9n<\/b>, fuimos desandando camino con la convicci\u00f3n firme que las estructuras tienen que moverse para promover la deconstrucci\u00f3n, que el orden establecido debe ser interpelado, incomodado, que as\u00ed como a nuestro paso el oto\u00f1o vivo se despoja de sus ropajes el patriarcado debe crujir tan fuerte que las modificaciones sean sustanciales y no maquillaje para presentar una \u00absalida\u00bb acorde a las urgencias \u00e9pocales. <\/i><\/span><\/p>\n<p><span style=\"color: #333333;\"><i>Hablemos de lenguaje inclusivo como el que tiene como objetivo nombrar para dar visibilidad a las diversas existencias que tiene la humanidad; por ejemplo: las personas con discapacidad, pueblos originarios, mujeres y disidencias. Es decir, el lenguaje inclusivo supone un campo sem\u00e1ntico bien amplio y abarca muchas realidades, luchas e identidades. (Lenny Cac\u00e9res,2022) <\/i><\/span><\/p>\n<p>Cabe hacer menci\u00f3n a destacadas y destacados colegas que incansablemente desde hace ya largo tiempo teorizan y construyen conocimiento con otras, otros y otres acerca de las cuestiones de g\u00e9nero y diversidad, su interpelaci\u00f3n e implicancia en el campo Psi. HOY nos convocan debates pol\u00edticos en y con los territorios, el llamado es URGENTE!!!<\/p>\n<p><span style=\"color: #333333;\"><i>Si bien hace un a\u00f1o hicimos historia <\/i><\/span>\u00a0cambiando la nominaci\u00f3n de nuestra querida <a href=\"https:\/\/cpvirn.org.ar\/fepra-federacion-de-psicologos-de-la-republica-argentina\/\">FePRA<\/a> a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos, y\u00a0<b>ahora a las psic\u00f3logas argentinas SI NOS LEEN\u00a0<\/b>es solo el comienzo, falta mucho a\u00fan para que esa visibilizaci\u00f3n y reconocimiento trascienda todos los \u00e1mbitos rompiendo barreras y techos de cristal. Seguiremos recordando este hecho hist\u00f3rico tantas y suficientes veces como sea necesario.<\/p>\n<p><span style=\"color: #1c1e21;\">Seguimos en camino, bregando\u00a0por condiciones dignas de trabajo para todas las colegas que conformamos el 86 %de la poblaci\u00f3n Psi en nuestro pa\u00eds ,percibiendo remuneraciones de un 16% menos que los colegas varones.<\/span><\/p>\n<p><span style=\"color: #1c1e21;\">Seguimos en camino instando a que todos los Colegios y Asociaciones de Psic\u00f3logas\u00a0y Psic\u00f3logos modifiquen su nominaci\u00f3n.<\/span><\/p>\n<p>Seguimos en camino con el compromiso \u00e9tico e insoslayable que implica ejercer nuestra profesi\u00f3n con compromiso social con perspectiva de g\u00e9neros y en clave de derechos humanos!!!<\/p>\n<p><span style=\"color: #1c1e21;\">Seguimos en camino invitando a que colegios de otras profesiones e instituciones a lo largo y ancho del pais, en todos los \u00e1mbitos p\u00fablicos y privados se sumen al desaf\u00edo y ampl\u00eden\u00a0sus nominaciones.\u00a0<\/span><\/p>\n<figure id=\"attachment_68954\" aria-describedby=\"caption-attachment-68954\" style=\"width: 479px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-68954\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n-1016x1024.jpg\" alt=\"Hablemos de nominaciones, instituciones y perspectiva de g\u00e9nero\" width=\"479\" height=\"483\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n-1016x1024.jpg 1016w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n-150x150.jpg 150w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n-298x300.jpg 298w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n-768x774.jpg 768w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n.jpg 1080w\" sizes=\"auto, (max-width: 479px) 100vw, 479px\" \/><figcaption id=\"caption-attachment-68954\" class=\"wp-caption-text\">De nominaciones, instituciones y perspectiva de g\u00e9nero<\/figcaption><\/figure>\n<p>Seguimos en camino hacia la construcci\u00f3n de una mejor humanidad .<\/p>\n<p>LO QUE NO SE NOMBRA NO EXISTE!!!<\/p>\n<p>AHORA A LAS PSIC\u00d3LOGAS ARGENTINAS SI NOS LEEN!!!<\/p>\n<p>NOMINAR ES POL\u00cdTICO, NO HACERLO TAMBI\u00c9N!!!<\/p>\n<p>Fuentes consultadas<\/p>\n<p>Bolet\u00edn fechado en San Luis en noviembre de 1974. Encuentro Nacional de Psic\u00f3logos y Estudiantes de Psicolog\u00eda.<\/p>\n<p><span style=\"color: #1c1e21;\">*Documento Nominaci\u00f3n Inclusiva FePRA. Lic.\u00a0M\u00f3nica Vaccaro (2022)\u00a0<\/span><\/p>\n<p><span style=\"color: #1c1e21;\">\u00a0\u00ab<a href=\"https:\/\/diariofemenino.com.ar\/df\/la-transversalidad-del-genero-espacios-y-disputas\/\">La transversalidad del g\u00e9nero: espacios y disputas<\/a>\u00ab, Lenny C\u00e1ceres.<\/span><\/p>\n<div>\n<div>\n<div>\n<div>\n<div>\n<div>(*) Trabajadora de la Salud Mental y activista de\u00a0<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/genero-y-derechos-humanos\/\">Derechos Humanos<\/a>.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Un oto\u00f1o, estaci\u00f3n del a\u00f1o con melod\u00eda propia nos encontr\u00f3 en 2022 haciendo historia en la hoy denominada Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos de la Rep\u00fablica Argentina, el 23 de abril de ese a\u00f1o\u00a0 y por decisi\u00f3n un\u00e1nime de delegadas y delegados de la FePRA (entidad que re\u00fane a las entidades de primer grado de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":68953,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":8,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7,1067,178,3,627],"tags":[3274,133,5911,4372,5912,62,5910,5913,2187],"class_list":["post-68952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades","category-agenda-feminista","category-articulos-y-comunicados","category-de-la-revolucion-al-reaprendizaje","category-genero-y-derechos-humanos","tag-construccion","tag-cultura","tag-denominacion","tag-destacada","tag-federacion","tag-lenguaje","tag-nominacion","tag-psicologas","tag-psicologos"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-28T12:25:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1075\" \/>\n\t<meta property=\"og:image:height\" content=\"601\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"De nominaciones, instituciones y perspectiva de g\u00e9nero\",\"datePublished\":\"2023-04-28T12:25:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/\"},\"wordCount\":1773,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/342707549_3655751524652467_8023833020604330533_n1.jpg\",\"keywords\":[\"Construcci\u00f3n\",\"Cultura\",\"Denominaci\u00f3n\",\"Destacada\",\"Federaci\u00f3n\",\"Lenguaje\",\"Nominaci\u00f3n\",\"Psic\u00f3logas\",\"psicologos\"],\"articleSection\":[\"Actividades\",\"Agenda Feminista\",\"Art\u00edculos y Comunicados\",\"De la Revoluci\u00f3n al Reaprendizaje\",\"Inst. Interdisciplinario de Estudios de G\u00e9neros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/\",\"name\":\"De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/342707549_3655751524652467_8023833020604330533_n1.jpg\",\"datePublished\":\"2023-04-28T12:25:02+00:00\",\"description\":\"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/342707549_3655751524652467_8023833020604330533_n1.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/342707549_3655751524652467_8023833020604330533_n1.jpg\",\"width\":1075,\"height\":601,\"caption\":\"De nominaciones, instituciones y perspectiva de g\u00e9nero\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/de-nominaciones-instituciones-y-perspectiva-de-genero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De nominaciones, instituciones y perspectiva de g\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino","description":"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/","og_locale":"es_ES","og_type":"article","og_title":"De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino","og_description":"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.","og_url":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2023-04-28T12:25:02+00:00","og_image":[{"width":1075,"height":601,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"De nominaciones, instituciones y perspectiva de g\u00e9nero","datePublished":"2023-04-28T12:25:02+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/"},"wordCount":1773,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","keywords":["Construcci\u00f3n","Cultura","Denominaci\u00f3n","Destacada","Federaci\u00f3n","Lenguaje","Nominaci\u00f3n","Psic\u00f3logas","psicologos"],"articleSection":["Actividades","Agenda Feminista","Art\u00edculos y Comunicados","De la Revoluci\u00f3n al Reaprendizaje","Inst. Interdisciplinario de Estudios de G\u00e9neros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/","url":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/","name":"De nominaciones, instituciones y perspectiva de g\u00e9nero - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","datePublished":"2023-04-28T12:25:02+00:00","description":"De nominaciones. Si bien hace un a\u00f1o hicimos historia \u00a0cambiando la nominaci\u00f3n de nuestra querida FePRA a Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","width":1075,"height":601,"caption":"De nominaciones, instituciones y perspectiva de g\u00e9nero"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/de-nominaciones-instituciones-y-perspectiva-de-genero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"De nominaciones, instituciones y perspectiva de g\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg","rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg",1075,601,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg",1075,601,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg",1075,601,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1-300x168.jpg",300,168,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1-1024x572.jpg",1024,572,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg",1075,601,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2023\/04\/342707549_3655751524652467_8023833020604330533_n1.jpg",1075,601,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/agenda-feminista\/\" rel=\"category tag\">Agenda Feminista<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/articulos-y-comunicados\/\" rel=\"category tag\">Art\u00edculos y Comunicados<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-la-revolucion-al-reaprendizaje\/\" rel=\"category tag\">De la Revoluci\u00f3n al Reaprendizaje<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/genero-y-derechos-humanos\/\" rel=\"category tag\">Inst. Interdisciplinario de Estudios de G\u00e9neros<\/a>","rttpg_excerpt":"Un oto\u00f1o, estaci\u00f3n del a\u00f1o con melod\u00eda propia nos encontr\u00f3 en 2022 haciendo historia en la hoy denominada Federaci\u00f3n de Psic\u00f3logas y Psic\u00f3logos de la Rep\u00fablica Argentina, el 23 de abril de ese a\u00f1o\u00a0 y por decisi\u00f3n un\u00e1nime de delegadas y delegados de la FePRA (entidad que re\u00fane a las entidades de primer grado de&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/68952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=68952"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/68952\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/68953"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=68952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=68952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=68952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}