{"id":60012,"date":"2021-08-07T09:32:13","date_gmt":"2021-08-07T12:32:13","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/df\/?p=60012"},"modified":"2021-08-07T09:35:35","modified_gmt":"2021-08-07T12:35:35","slug":"el-banco-provincia-instala-lactarios-en-sus-edificios-centrales","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/","title":{"rendered":"El Banco Provincia instala lactarios en sus edificios centrales"},"content":{"rendered":"<p><b>Como parte de las actividades por la Semana Mundial de la Lactancia Materna, <a href=\"https:\/\/www.bancoprovincia.com.ar\/web\">Banco Provincia<\/a> de Buenos Aires inaugur\u00f3 tres lactarios en sus edificios centrales para que las trabajadoras cuenten con un \u00e1mbito adecuado donde extraer y conservar la leche materna. Juan Cuattromo, presidente de la entidad, visit\u00f3 uno de estos espacios junto a la directora Juliana di Tullio y el Gerente General Rub\u00e9n Gonz\u00e1lez Ocantos.\u00a0<\/b><\/p>\n<figure id=\"attachment_60014\" aria-describedby=\"caption-attachment-60014\" style=\"width: 642px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-60014\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Juliana-di-Tullio-Rub\u00e9n-Gonz\u00e1lez-Ocantos-y-Juan-Cuattromo-durante-la-inauguraci\u00f3n-de-uno-de-los-lactarios.-1024x683.jpg\" alt=\"El Banco Provincia instala lactarios en sus edificios centrales \" width=\"642\" height=\"428\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Juliana-di-Tullio-Rub\u00e9n-Gonz\u00e1lez-Ocantos-y-Juan-Cuattromo-durante-la-inauguraci\u00f3n-de-uno-de-los-lactarios.-1024x683.jpg 1024w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Juliana-di-Tullio-Rub\u00e9n-Gonz\u00e1lez-Ocantos-y-Juan-Cuattromo-durante-la-inauguraci\u00f3n-de-uno-de-los-lactarios.-300x200.jpg 300w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Juliana-di-Tullio-Rub\u00e9n-Gonz\u00e1lez-Ocantos-y-Juan-Cuattromo-durante-la-inauguraci\u00f3n-de-uno-de-los-lactarios.-768x512.jpg 768w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><figcaption id=\"caption-attachment-60014\" class=\"wp-caption-text\">El Banco Provincia instala lactarios en sus edificios centrales<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>\u201cInstalar estos espacios para que nuestras trabajadoras puedan extraerse la leche en el horario laboral con dignidad y en un entorno c\u00f3modo y relajado es una forma de acompa\u00f1ar el desarrollo profesional de las mujeres\u201d, asegur\u00f3 Cuattromo. Y a\u00f1adi\u00f3: \u201cqueremos que las mam\u00e1s que eligen amamantar no encuentren obst\u00e1culos en el \u00e1mbito de trabajo y puedan hacerlo de la mejor manera\u201d.<\/p>\n<p>El presidente de Banco Provincia tambi\u00e9n sostuvo que \u201cestos lactarios son posibles gracias el di\u00e1logo permanente con todos los trabajadores y trabajadoras y con sus representantes sindicales\u201d. Y asegur\u00f3 que \u201cla definici\u00f3n de nuestro proyecto pol\u00edtico y de nuestro gobernador es reivindicar y reconocer la dignidad del trabajo que las personas hacen todos los d\u00edas\u201d.<\/p>\n<p>Por su parte, Juliana di Tullio, quien dentro del Directorio coordina la Comisi\u00f3n de Mujeres, Pol\u00edticas de G\u00e9nero y Diversidad Sexual, se\u00f1al\u00f3 que \u201clos lactarios son una necesidad que conocemos muy bien las mujeres, porque es muy espec\u00edfica.\u00a0\u00a0En Argentina, las mujeres somos libres de elegir si queremos o no queremos lactar. Y si elegimos lactar, debemos poder hacerlo en nuestros trabajos\u201d.<\/p>\n<p>\u201cPor eso hay que tener espacios realmente seguros, dignos, donde no nos toquen la puerta para que nos apuremos\u201d, indic\u00f3 la directora. Y agreg\u00f3: \u201cdesde la conducci\u00f3n del Banco sentimos que con estas cosas les mejoramos un poco la vida a las mujeres que trabajan en la instituci\u00f3n. Que les hacemos un cachito menos dif\u00edcil la tarea cotidiana a las compa\u00f1eras que necesitan de nuestra ayuda, porque tienen beb\u00e9s que amamantar\u201d.<\/p>\n<p>Finalmente, el gerente general Rub\u00e9n Gonz\u00e1lez Ocantos, expres\u00f3 su satisfacci\u00f3n por los cambios en materia de g\u00e9nero que vive la instituci\u00f3n financiera m\u00e1s antigua de Hispanoam\u00e9rica: \u201cdespu\u00e9s de casi 37 a\u00f1os de estar en el Banco me pone muy contento poder inaugurar un espacio de este tipo, que en otro momento era inimaginable\u201d. Y a\u00f1adi\u00f3 que \u201cla decisi\u00f3n pol\u00edtica fue fundamental para poder llevar adelante una iniciativa como los lactarios\u201d.<\/p>\n<p>Los lactarios son ambientes equipados para la extracci\u00f3n y conservaci\u00f3n adecuada de la leche materna durante el horario de trabajo, que re\u00fanen las condiciones para garantizar la privacidad, comodidad, higiene, y el respeto a la dignidad y la salud integral de las trabajadoras lactantes.<\/p>\n<p>Ya se habilitaron los primeros tres y en las pr\u00f3ximas semanas se abrir\u00e1n otros dos en la Casa Matriz La Plata y en la Departamental Mar del Plata. En los cinco edificios donde se instalaron hay actualmente 175 trabajadoras lactantes que podr\u00e1n utilizar los nuevos espacios.<\/p>\n<p><b>La <a href=\"https:\/\/www.argentina.gob.ar\/noticias\/semana-mundial-de-la-lactancia-materna-2021\">Semana Mundial<\/a> de la Lactancia Materna 2021<\/b>\u00a0se celebra del 1 al 7 de agosto, con el objetivo de proteger, promover y respaldar la decisi\u00f3n de amamantar. El lema elegido para este a\u00f1o es: \u201cProteger la lactancia materna: una responsabilidad compartida\u201d. Con estas palabras se busca se\u00f1alar a la lactancia como un hecho cultural y colectivo, que involucra a toda la sociedad.<\/p>\n<div>\n<div dir=\"ltr\">\n<div>\n<p><b>Algunos beneficios de la <a href=\"https:\/\/diariofemenino.com.ar\/df\/proteger-la-lactancia-materna-una-responsabilidad-compartida\/\">lactancia<\/a> materna que destaca la Organizaci\u00f3n Panamericana de la Salud:\u00a0<\/b><\/p>\n<ul>\n<li>Protege contra la neumon\u00eda, la diarrea, las infecciones del o\u00eddo y el asma, entre otras enfermedades.<\/li>\n<\/ul>\n<ul>\n<li>Es la \u201cprimera vacuna\u201d porque el sistema inmunitario de los reci\u00e9n nacidos a\u00fan no est\u00e1 maduro.<\/li>\n<\/ul>\n<ul>\n<li>Contribuye a prevenir el sobrepeso y ayuda al desarrollo cognitivo de ni\u00f1os y ni\u00f1as.<\/li>\n<\/ul>\n<ul>\n<li>Est\u00e1 asociada a la seguridad emocional que brinda el v\u00ednculo.<\/li>\n<\/ul>\n<ul>\n<li>Disminuye en las madres el riesgo de padecer c\u00e1ncer de ovario y de mama.<\/li>\n<\/ul>\n<ul>\n<li>Es <a href=\"https:\/\/diariofemenino.com.ar\/df\/semana-mundial-de-la-lactancia-materna-pensar-en-una-perspectiva-del-buen-vivir\/\">ecol\u00f3gica<\/a>, ya que la leche materna es un alimento natural y renovable que no necesita packaging, ni log\u00edstica para distribuirse.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Como parte de las actividades por la Semana Mundial de la Lactancia Materna, Banco Provincia de Buenos Aires inaugur\u00f3 tres lactarios en sus edificios centrales para que las trabajadoras cuenten con un \u00e1mbito adecuado donde extraer y conservar la leche materna. Juan Cuattromo, presidente de la entidad, visit\u00f3 uno de estos espacios junto a la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":60013,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":13,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[7,32,23,1],"tags":[2860,3421,18],"class_list":["post-60012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actividades","category-mujeres","category-salud","category-uncategorized","tag-banco-provincia","tag-lactancia","tag-politicas-publicas"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Banco Provincia de Buenos Aires.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Banco Provincia de Buenos Aires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-07T12:32:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-07T12:35:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"3012\" \/>\n\t<meta property=\"og:image:height\" content=\"2008\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"El Banco Provincia instala lactarios en sus edificios centrales\",\"datePublished\":\"2021-08-07T12:32:13+00:00\",\"dateModified\":\"2021-08-07T12:35:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/\"},\"wordCount\":718,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg\",\"keywords\":[\"Banco provincia\",\"lactancia\",\"Pol\u00edticas p\u00fablicas\"],\"articleSection\":[\"Actividades\",\"Mujeres\",\"Salud\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/\",\"name\":\"El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg\",\"datePublished\":\"2021-08-07T12:32:13+00:00\",\"dateModified\":\"2021-08-07T12:35:35+00:00\",\"description\":\"Banco Provincia de Buenos Aires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg\",\"width\":3012,\"height\":2008,\"caption\":\"El Banco Provincia instala lactarios en sus edificios centrales\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Banco Provincia instala lactarios en sus edificios centrales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino","description":"Banco Provincia de Buenos Aires.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/","og_locale":"es_ES","og_type":"article","og_title":"El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino","og_description":"Banco Provincia de Buenos Aires.","og_url":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2021-08-07T12:32:13+00:00","article_modified_time":"2021-08-07T12:35:35+00:00","og_image":[{"width":3012,"height":2008,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"El Banco Provincia instala lactarios en sus edificios centrales","datePublished":"2021-08-07T12:32:13+00:00","dateModified":"2021-08-07T12:35:35+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/"},"wordCount":718,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","keywords":["Banco provincia","lactancia","Pol\u00edticas p\u00fablicas"],"articleSection":["Actividades","Mujeres","Salud","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/","url":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/","name":"El Banco Provincia instala lactarios en sus edificios centrales - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","datePublished":"2021-08-07T12:32:13+00:00","dateModified":"2021-08-07T12:35:35+00:00","description":"Banco Provincia de Buenos Aires.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","width":3012,"height":2008,"caption":"El Banco Provincia instala lactarios en sus edificios centrales"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/el-banco-provincia-instala-lactarios-en-sus-edificios-centrales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"El Banco Provincia instala lactarios en sus edificios centrales"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg","rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg",3012,2008,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg",3012,2008,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg",3012,2008,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia-300x200.jpg",300,200,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia-1024x683.jpg",1024,683,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg",1536,1024,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/08\/Sala-de-Lactancia-en-uno-de-los-edifcios-de-Banco-Provincia.jpg",2048,1365,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/actividades\/\" rel=\"category tag\">Actividades<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/mujeres\/\" rel=\"category tag\">Mujeres<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/salud\/\" rel=\"category tag\">Salud<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","rttpg_excerpt":"Como parte de las actividades por la Semana Mundial de la Lactancia Materna, Banco Provincia de Buenos Aires inaugur\u00f3 tres lactarios en sus edificios centrales para que las trabajadoras cuenten con un \u00e1mbito adecuado donde extraer y conservar la leche materna. Juan Cuattromo, presidente de la entidad, visit\u00f3 uno de estos espacios junto a la&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/60012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=60012"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/60012\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/60013"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=60012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=60012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=60012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}