{"id":56115,"date":"2021-02-27T10:01:15","date_gmt":"2021-02-27T13:01:15","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/?p=56115"},"modified":"2021-02-27T10:01:15","modified_gmt":"2021-02-27T13:01:15","slug":"situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/","title":{"rendered":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina"},"content":{"rendered":"<p><a href=\"http:\/\/www.crisalidatucuman.org\/about\/\"><strong>Cris\u00e1lida<\/strong><\/a> nos acerca el informe de la encuesta elaborada junto a <a href=\"https:\/\/centralespaciodeideas.org.ar\/\">Central<\/a> y <a href=\"http:\/\/www.institutomatria.org\/p\/blog-page.html\">Matria<\/a>.\u00a0Esta encuesta busca promover la visibilidad de personas mayores LGBTI+ con el deseo de sumar al dise\u00f1o de propuestas para garantizar sus derechos por parte de Comunas y Municipios.<\/p>\n<div>\n<p><strong>INTRODUCCI\u00d3N<\/strong><\/p>\n<p><span style=\"color: #808080;\">(descargar en imagen)<\/span><\/p>\n<figure id=\"attachment_56119\" aria-describedby=\"caption-attachment-56119\" style=\"width: 389px\" class=\"wp-caption alignleft\"><a href=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/Informe-Concejalas.pdf\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-56119\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT1.jpg\" alt=\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina \" width=\"389\" height=\"293\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT1.jpg 639w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT1-300x226.jpg 300w\" sizes=\"auto, (max-width: 389px) 100vw, 389px\" \/><\/a><figcaption id=\"caption-attachment-56119\" class=\"wp-caption-text\">Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina<\/figcaption><\/figure>\n<p>La encuesta a la Red de Concejalas de Argentina estuvo activa en la plataforma online questionpro de octubre 2020 a febrero 2021 busca promover a la visibilidad de personas mayores LGBTI+ con el deseo de sumar al dise\u00f1o de propuestas para garantizar sus derechos por parte de Comunas y Municipios.<\/p>\n<p>Matria, instituto sobre cuestiones de g\u00e9nero; Central espacio de ideas y la biblioteca popular Cris\u00e1lida de g\u00e9nero y diversidad afectivo sexual, se unen en una campa\u00f1a que busca visibilizar la situaci\u00f3n de las personas mayores LGBTI+ (Lesbianas, Gais, Bisexuales, Trans\/Travestis\/Transexuales\/<wbr \/>Transgeneros, Intersex, Queer, No Binarios).<\/p>\n<p>Y lo hacemos desde la convicci\u00f3n de que podemos alcanzar ese objetivo uniendo esfuerzos entre diferentes actores\/actrices sociales que buscamos su bienestar y autonom\u00eda.<\/p>\n<p>Parece un tema \u201cnuevo\u201d pero LGBTI+ que envejecen ocurre desde siempre. En Argentina, en este momento dos personas cumplen 60 a\u00f1os. Una de esas personas posiblemente sea LGBTI+.<\/p>\n<p>Creemos que hay que celebrar que somos una sociedad envejecida y celebrar esto porque es producto de pol\u00edticas que combatieron y erradicaron las causales de muerte. Lo que se viene es la revoluci\u00f3n de la longevidad y esto nos lleva a reflexionar sobre el rol de los gobiernos locales en el bienestar y autonom\u00eda de las personas mayores LGBTI+.<\/p>\n<p>La poblaci\u00f3n de personas mayores LGBTI+ vienen de historias de vida con fuertes vivencias de discriminaci\u00f3n, expulsi\u00f3n de sus hogares, rupturas de sus v\u00ednculos familiares, afectivos, prejuicios, la clandestinidad de sus deseos para poder sobrevivir o no perder el trabajo, postergar proyectos de vida y una contin\u00faa vulneraci\u00f3n que se profundiza con la vejez. Un Estado presente debe contar con sensibilizaci\u00f3n sobre sus identidades y sus derechos para que no sufran una nueva victimizaci\u00f3n.<\/p>\n<p>Desarrollar encuestas en este momento fue pensado como un modo estrat\u00e9gico\u00a0<span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, Times New Roman, serif;\"><span style=\"font-size: medium;\"><span lang=\"es-ES\">para<\/span><\/span><\/span><\/span>\u00a0conocer indicadores sociales sobre la situaci\u00f3n de personas mayores LGBTI+. Con los datos obtenidos en estas encuestas pudimos tener un aproximado a esta poblaci\u00f3n desde las miradas locales.<\/p>\n<p>La encuesta a la Red de Concejalas de Argentina busc\u00f3 caracterizar su percepci\u00f3n de las din\u00e1micas y v\u00ednculos con la poblaci\u00f3n de personas mayores LGBTI+ en t\u00e9rminos de:<\/p>\n<p>\u2022 Su vinculaci\u00f3n con los gobiernos locales.<\/p>\n<p>\u2022 Su inserci\u00f3n en la comunidad.<\/p>\n<p>\u2022 Su participaci\u00f3n en la comunidad y programas sociales.<\/p>\n<p>\u2022 La percepci\u00f3n de gobiernos locales sobre este grupo<\/p>\n<p>Esta encuesta es un muestreo que suma datos a seguir pensando acciones para el bienestar y la autonom\u00eda de las personas mayores LGBTI+ en Comunas y Municipios pero no podemos tomarla como una presentaci\u00f3n de la totalidad de realidades que all\u00ed habitan y las din\u00e1micas\u00a0<span style=\"color: #000000;\"><span style=\"font-family: Liberation Serif, Times New Roman, serif;\"><span style=\"font-size: medium;\"><span lang=\"es-ES\">resultantes<\/span><\/span><\/span><\/span>.A los fines de facilitar el trabajo de la comunidad acad\u00e9mica, de las organizaciones interesadas en trabajar la tem\u00e1tica y de la ciudadan\u00eda en general, el resultante de la presente encuesta quedar\u00e1 a disposici\u00f3n en nuestra <a href=\"https:\/\/diariofemenino.com.ar\/category\/biblioteca\/\">Biblioteca virtual<\/a> para su consulta. <a href=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/Informe-Concejalas.pdf\">Seguir leyendo&#8230;\u00a0<\/a><\/p>\n<figure id=\"attachment_56121\" aria-describedby=\"caption-attachment-56121\" style=\"width: 715px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-56121\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg\" alt=\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina \" width=\"715\" height=\"507\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg 715w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT-300x213.jpg 300w\" sizes=\"auto, (max-width: 715px) 100vw, 715px\" \/><figcaption id=\"caption-attachment-56121\" class=\"wp-caption-text\">Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina<\/figcaption><\/figure>\n<p><strong>\u00abComprender la diversidad comunitaria marca la diferencia\u00bb.<\/strong><\/p>\n<\/div>\n<div style=\"text-align: left;\">A partir de las encuestas, entrevistas y trabajos territoriales, podemos entrar en un mundo nunca imaginado para quienes tenemos vivencias diferentes tambi\u00e9n desde una otra identidad u orientaci\u00f3n sexual. Sin embargo hay un tema en com\u00fan, que es el avance de los a\u00f1os sobre nuestros cuerpos y la mirada que nos devuelve la sociedad toda a partir de los 65 a\u00f1os, sobre esos mitos y prejuicios que nos hacen parecer personas no deseantes, no enamoradas y que la sexualidad pasa solamente por la genitalidad.-<\/p>\n<p>Esta mirada discriminadora, se profundiza y se agudiza cuando se trata especialmente de las personas mayores de la comunidad LGBTI+.<\/p>\n<p>Es ah\u00ed en d\u00f3nde podemos ver la importancia de los gobiernos locales, comunas y municipios, que conocen sus comunidades diversas, que tienen como principal objetivo satisfacer las necesidades de las mismas, asegurando su participaci\u00f3n en el progreso econ\u00f3mico, social y cultural. Comprender la diversidad comunitaria marca la diferencia para llevar adelante pol\u00edticas p\u00fablicas no homogeneizadoras, evitando as\u00ed, la reproducci\u00f3n de las desigualdades que generan las mismas propuestas igualadoras, sin entender que no todxs necesitan lo mismo.<\/p>\n<p>En la b\u00fasqueda de conocer c\u00f3mo es la vinculaci\u00f3n de los gobiernos locales con la problem\u00e1tica de las personas mayores LGBTI+, es que nos encontramos con respuestas que nos deben incomodar, nos debe cuestionar y movilizar para ser parte de la ampliaci\u00f3n de todos los derechos.<\/p>\n<p>Mi pensamiento se basa en que s\u00ed podemos intentar ponernos desde el lugar del otro, de la otra, podremos multiplicar estas opiniones hasta que el tiempo y las propuestas que necesitan de muchas escuchas, lo permitan.<\/p>\n<p>No son temas f\u00e1ciles, claro que no, porque todav\u00eda nos cuesta cumplir con la Ley de Educaci\u00f3n Sexual Integral en muchas provincias; con las metas de la Ley Micaela, que s\u00f3lo sientan las bases, no son las \u00fanicas, para poder avanzar en la necesidad de reconocer las diversidades, de promover una vida sin violencias y con un Estado presente, de conocer a partir de las propias experiencias realidades dif\u00edciles de v\u00ednculos familiares, y tambi\u00e9n solidaridad para construir desde el acompa\u00f1amiento en todos los \u00f3rdenes de la vida.<\/p>\n<p>Y digo que el acompa\u00f1amiento de los gobiernos locales, no es la \u00fanica medida a llevar adelante, porque debe complementarse con pol\u00edticas publicas desde los otros ministerios y programas que garanticen calidad de vida para todxs y especialmente para quienes son parte del sector de personas mayores y no debemos profundizar las arbitrariedades que muchas veces acompa\u00f1an al ejercicio de estas pol\u00edticas, que aun existen en nuestro pa\u00eds. Es por esto imprescindible articular las diversas propuestas a nivel gubernamental con los tres poderes del estado y realizar propuestas concretas que surjan desde cada comunidad para as\u00ed realmente ir construyendo ese empoderamiento necesario, que da el conocimiento, la experiencia y la participaci\u00f3n.<\/p>\n<p>El desaf\u00edo es avanzar en dar a conocer, socializar informaci\u00f3n sobre estas realidades y ampliar las bases sobre los derechos de todxs. Es siempre el Estado quien tiene las herramientas para comenzar y la sociedad toda comprometerse con estas banderas.-<\/p>\n<p>No debemos dejar que estas realidades, sentimientos, derechos disminuidos, violencias recibidas, no nos impacten. A trabajar sobre ello.<\/p><\/div>\n<div><\/div>\n<div style=\"text-align: right;\"><strong>Prof. Silvia Rojkes<\/strong><br \/>\nPresidenta de Central espacio de ideas<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/diariofemenino.com.ar\/\">Diario Digital Femenino<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0Esta encuesta busca promover la visibilidad de personas mayores LGBTI+ con el deseo de sumar al dise\u00f1o de propuestas para garantizar sus derechos por parte de Comunas y Municipios. INTRODUCCI\u00d3N (descargar en imagen) La encuesta a la Red de Concejalas de Argentina [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":56121,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":4,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1067,19,182,21,23,592],"tags":[4160,2338,4159,4158,596,4157],"class_list":["post-56115","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-feminista","category-biblioteca","category-informes","category-noticias","category-salud","category-violencias","tag-central","tag-concejalas","tag-crisalida","tag-encuenta","tag-matria","tag-personas-lgbti"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-27T13:01:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"715\" \/>\n\t<meta property=\"og:image:height\" content=\"507\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina\",\"datePublished\":\"2021-02-27T13:01:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/\"},\"wordCount\":1176,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/EncuestaLGBT.jpg\",\"keywords\":[\"Central\",\"Concejalas\",\"Cris\u00e1lida\",\"Encuenta\",\"Matria\",\"Personas LGBTI+\"],\"articleSection\":[\"Agenda Feminista\",\"Biblioteca Virtual\",\"Informes\",\"Noticias\",\"Salud\",\"Violencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/\",\"name\":\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/EncuestaLGBT.jpg\",\"datePublished\":\"2021-02-27T13:01:15+00:00\",\"description\":\"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/EncuestaLGBT.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/EncuestaLGBT.jpg\",\"width\":715,\"height\":507,\"caption\":\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino","description":"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino","og_description":"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0","og_url":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2021-02-27T13:01:15+00:00","og_image":[{"width":715,"height":507,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina","datePublished":"2021-02-27T13:01:15+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/"},"wordCount":1176,"commentCount":1,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","keywords":["Central","Concejalas","Cris\u00e1lida","Encuenta","Matria","Personas LGBTI+"],"articleSection":["Agenda Feminista","Biblioteca Virtual","Informes","Noticias","Salud","Violencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/","url":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/","name":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","datePublished":"2021-02-27T13:01:15+00:00","description":"Situaci\u00f3n de las personas mayores LGBTI+. Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","width":715,"height":507,"caption":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/situacion-de-las-personas-mayores-lgbti-en-comunas-y-municipios-de-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Situaci\u00f3n de las personas mayores LGBTI+ en Comunas y Municipios de Argentina"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg","rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT-300x213.jpg",300,213,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2021\/02\/EncuestaLGBT.jpg",715,507,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":1,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/agenda-feminista\/\" rel=\"category tag\">Agenda Feminista<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/biblioteca\/\" rel=\"category tag\">Biblioteca Virtual<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/informes\/\" rel=\"category tag\">Informes<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/salud\/\" rel=\"category tag\">Salud<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/violencias\/\" rel=\"category tag\">Violencias<\/a>","rttpg_excerpt":"Cris\u00e1lida nos acerca el informe de la encuesta elaborada junto a Central y Matria.\u00a0Esta encuesta busca promover la visibilidad de personas mayores LGBTI+ con el deseo de sumar al dise\u00f1o de propuestas para garantizar sus derechos por parte de Comunas y Municipios. INTRODUCCI\u00d3N (descargar en imagen) La encuesta a la Red de Concejalas de Argentina&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/56115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=56115"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/56115\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/56121"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=56115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=56115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=56115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}