{"id":51411,"date":"2020-08-19T11:55:12","date_gmt":"2020-08-19T14:55:12","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/?p=51411"},"modified":"2020-08-19T11:57:48","modified_gmt":"2020-08-19T14:57:48","slug":"nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/","title":{"rendered":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia"},"content":{"rendered":"<header>\n<p class=\"nota-detalle-titulo\" style=\"text-align: center;\"><strong>Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia<\/strong><\/p>\n<\/header>\n<p class=\"lead nota-detalle-bajada\">Desde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n de Maternidad e Infancia funcionan los programas Salud Integral en la Adolescencia y <a href=\"https:\/\/diariofemenino.com.ar\/los-efectos-de-la-cuarentena-en-la-salud-sexual-y-reproductiva\/\">Salud Sexual y Reproductiva<\/a>, donde se ofrece un dispositivo de consulta, orientaci\u00f3n y\/o derivaci\u00f3n.<\/p>\n<div class=\"nota-detalle-cuerpo\">La estrategia tiene como objetivo favorecer la continuidad de la atenci\u00f3n en este contexto tan particular. La misma est\u00e1 dirigida a toda la poblaci\u00f3n, pero se har\u00e1 especial hincapi\u00e9 en adolescentes, con el objetivo de preservar la <a href=\"https:\/\/diariofemenino.com.ar\/valeria-isla\/\">salud integral<\/a> de esta poblaci\u00f3n. La imposibilidad de desarrollar las asesor\u00edas cara a cara en las escuelas y centros de salud, transform\u00f3 la comunicaci\u00f3n virtual en el recurso por excelencia para mantener contacto con los\/las adolescentes, quienes a trav\u00e9s de la l\u00ednea 2954-595392 pueden realizar consultas vinculadas a distintos aspectos de la salud de manera confidencial.<br \/>\nEl dispositivo se cre\u00f3 y desarroll\u00f3 desde una perspectiva de g\u00e9nero y derechos, de acuerdo al marco normativo vigente, siempre considerando a la Salud desde una perspectiva integral (como estado de bienestar f\u00edsico, emocional y social) y amplia, teniendo en cuenta sus determinantes sociales.<br \/>\nTiene el objetivo de brindar atenci\u00f3n personalizada y oportuna para facilitar el acceso a los servicios de salud sexual y salud reproductiva de la Provincia.<br \/>\nLa l\u00ednea y el chat son atendidos por profesionales de la salud que pueden escuchar, contener, informar, asesorar y derivar a la poblaci\u00f3n en el marco del respeto y ejercicio de los <a href=\"https:\/\/diariofemenino.com.ar\/renovando-apuntes-de-educacion-sexual-integral\/\">derechos<\/a> sexuales y reproductivos. Es importante recordar que la consulta es an\u00f3nima y confidencial.<\/div>\n<div><\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-51412\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/educacion-sexual-1-638.jpg\" alt=\"\" width=\"638\" height=\"359\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/educacion-sexual-1-638.jpg 638w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/educacion-sexual-1-638-300x169.jpg 300w\" sizes=\"auto, (max-width: 638px) 100vw, 638px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia Desde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n de Maternidad e Infancia funcionan los programas Salud Integral en la Adolescencia y Salud Sexual y Reproductiva, donde se ofrece un dispositivo de consulta, orientaci\u00f3n y\/o derivaci\u00f3n. La estrategia tiene como objetivo favorecer la [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":51413,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":""},"categories":[21,23],"tags":[112,3465,130,18,14],"class_list":["post-51411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-salud","tag-adolescencia","tag-educacion-sexual-integr","tag-mujeres","tag-politicas-publicas","tag-salud-sexual-y-reproductiva"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[3],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-19T14:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-19T14:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"820\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\"},\"headline\":\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia\",\"datePublished\":\"2020-08-19T14:55:12+00:00\",\"dateModified\":\"2020-08-19T14:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg\",\"keywords\":[\"Adolescencia\",\"educaci\u00f3n sexual integr\",\"Mujeres\",\"Pol\u00edticas p\u00fablicas\",\"Salud Sexual y Reproductiva\"],\"articleSection\":[\"Noticias\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/\",\"name\":\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg\",\"datePublished\":\"2020-08-19T14:55:12+00:00\",\"dateModified\":\"2020-08-19T14:57:48+00:00\",\"description\":\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg\",\"width\":1240,\"height\":820},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/sofiperez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino","description":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/","og_locale":"es_ES","og_type":"article","og_title":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino","og_description":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n","og_url":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2020-08-19T14:55:12+00:00","article_modified_time":"2020-08-19T14:57:48+00:00","og_image":[{"width":1240,"height":820,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f"},"headline":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia","datePublished":"2020-08-19T14:55:12+00:00","dateModified":"2020-08-19T14:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","keywords":["Adolescencia","educaci\u00f3n sexual integr","Mujeres","Pol\u00edticas p\u00fablicas","Salud Sexual y Reproductiva"],"articleSection":["Noticias","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/","url":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/","name":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","datePublished":"2020-08-19T14:55:12+00:00","dateModified":"2020-08-19T14:57:48+00:00","description":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y AdolescenciaDesde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","width":1240,"height":820},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/nueva-linea-de-asesoramiento-en-salud-sexual-reproductiva-y-adolescencia-desde-el-ministerio-de-salud-y-a-traves-de-la-direccion-de-maternidad-e-infancia-funcionan-los-programas-salud-integral-en-la\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"}]}},"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg","jetpack_sharing_enabled":true,"rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg",1240,820,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg",1240,820,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg",1240,820,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40-150x150.jpeg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40-300x198.jpeg",300,198,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40-1024x677.jpeg",1024,677,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg",1240,820,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/157777_whatsapp-image-2020-08-19-at-10.31.40.jpeg",1240,820,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/noticias\/\" rel=\"category tag\">Noticias<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/salud\/\" rel=\"category tag\">Salud<\/a>","rttpg_excerpt":"Nueva l\u00ednea de asesoramiento en Salud Sexual, Reproductiva y Adolescencia Desde el Ministerio de Salud y a trav\u00e9s de la Direcci\u00f3n de Maternidad e Infancia funcionan los programas Salud Integral en la Adolescencia y Salud Sexual y Reproductiva, donde se ofrece un dispositivo de consulta, orientaci\u00f3n y\/o derivaci\u00f3n. La estrategia tiene como objetivo favorecer la&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/51411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=51411"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/51411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/51413"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=51411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=51411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=51411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}