{"id":51348,"date":"2020-08-14T17:40:36","date_gmt":"2020-08-14T20:40:36","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/?p=51348"},"modified":"2020-08-15T11:25:05","modified_gmt":"2020-08-15T14:25:05","slug":"gomez-alcorta-losardo-y-frederic","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/","title":{"rendered":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias"},"content":{"rendered":"<div>\n<div>\n<div><strong>La articulaci\u00f3n entre todos los niveles del Estado es una condici\u00f3n ineludible para un abordaje eficaz de las Violencias extremas por motivos de g\u00e9nero<\/strong><\/div>\n<div><\/div>\n<div>Este viernes, en el Sal\u00f3n de las Mujeres de la Casa Rosada, con la participaci\u00f3n de la <a href=\"https:\/\/www.argentina.gob.ar\/generos\">ministra<\/a> de las Mujeres, G\u00e9neros y Diversidad, Elizabeth G\u00f3mez Alcorta; la ministra de <a href=\"https:\/\/www.argentina.gob.ar\/seguridad\/plataformavirtual\">Seguridad<\/a>, Sabina Frederic y la ministra de <a href=\"https:\/\/www.argentina.gob.ar\/justicia\">Justicia y Derechos Humanos<\/a>, Marcela Losardo, se puso en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias Extremas por Motivos de G\u00e9nero, que forma parte del Plan Nacional de Acci\u00f3n Contra las Violencias por Motivos de G\u00e9nero 2020-2022.<\/div>\n<\/div>\n<div>\n<figure id=\"attachment_51349\" aria-describedby=\"caption-attachment-51349\" style=\"width: 900px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-51349 size-large\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-4-1024x683.jpeg\" alt=\"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias por Razones Extremas\" width=\"900\" height=\"600\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-4-1024x683.jpeg 1024w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-4-300x200.jpeg 300w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-4-768x512.jpeg 768w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-4.jpeg 1280w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><figcaption id=\"caption-attachment-51349\" class=\"wp-caption-text\">G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias por Razones Extremas<\/figcaption><\/figure>\n<\/div>\n<div>\n<div>La creaci\u00f3n del Programa de Abordaje Integral de la Violencias Extremas se oficializ\u00f3 esta ma\u00f1ana en el Bolet\u00edn Oficial. Si bien desde el 2019 existe el Plan Nacional de Seguridad para la Reducci\u00f3n de Femicidios, el nuevo programa se propone dejar atr\u00e1s el paradigma estrictamente securitario. Desde el actual gobierno se considera que frente a situaciones complejas no corresponde reducir la intervenci\u00f3n exclusivamente al sistema penal, sino que frente a un fen\u00f3meno multicausal, multidimensional y complejo, como el de los femcidios, travesticidios y transfemicidios, es necesario establecer mecanismos de coordinaci\u00f3n y articulaci\u00f3n que aseguren un abordaje interagencial y transversal. En ese contexto, a trav\u00e9s del Programa Interministerial se buscar\u00e1 dar respuestas m\u00e1s amplias que permitan abordar los fen\u00f3menos de manera integral.<\/div>\n<div><\/div>\n<div>En la reuni\u00f3n que mantuvieron en la Casa Rosada, la ministra G\u00f3mez Alcorta destac\u00f3 el proceso de conformaci\u00f3n del programa que forma parte de los avances en materia de pol\u00edticas de g\u00e9nero que se vienen llevando adelante desde diciembre: \u201cNo casualmente somos tres ministras mujeres\u201d, se\u00f1al\u00f3. \u201cEste programa retoma una agenda del movimiento de mujeres y de la diversidad que a partir del 3 de junio de 2015 con el Ni Una Menos se convirti\u00f3 en una bandera\u201d.<\/div>\n<div><\/div>\n<div>Adem\u00e1s detall\u00f3 que el trabajo interministerial es la manera de\u00a0 \u201cmejorar el acceso y las respuestas estatales\u201d y que este programa \u201ccrea nuevas formas de intervenci\u00f3n, articula las acciones con el fin de dar respuestas m\u00e1s eficaces y sobre todo para pensar pol\u00edticas reparatorias\u201d. En ese contexto explicit\u00f3: \u201cProponemos una ingenier\u00eda institucional que implica articular, no solamente las pol\u00edticas y acciones de tres ministerios, sino la posibilidad que los tres trabajemos con los respectivos consejos federales, para que las acciones se puedan coordinar a nivel provincial\u201d.<\/div>\n<div><\/div>\n<div>Por su parte Sabina Frederic expres\u00f3: \u201cEl Ministerio de Seguridad, en este espacio de trabajo que conformamos con el el Ministerio de las Mujeres, G\u00e9neros y Diversidad y el Ministerio de Justicia y Derechos Humanos, profundiza su compromiso en la lucha por la erradicaci\u00f3n de las violencias extremas por motivos de g\u00e9nero entendiendo el fen\u00f3meno en su dimensi\u00f3n estructural y a las fuerzas policiales de seguridad como agentes fundamentales en la protecci\u00f3n de la ciudadan\u00eda para que todas, todos y todes puedan desarrollar sus proyectos de vida libres de violencia\u201d.<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-51352\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-2-1024x682.jpeg\" alt=\"\" width=\"900\" height=\"599\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-2-1024x682.jpeg 1024w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-2-300x200.jpeg 300w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-2-768x512.jpeg 768w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-2.jpeg 1280w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div>\n<div><\/div>\n<div>\u201cEl abordaje integral de las violencias extremas por razones de g\u00e9nero debe encararse desde la perspectiva del empoderamiento de la mujer, ocup\u00e1ndonos de la prevenci\u00f3n, el rescate y el despu\u00e9s. El desaf\u00edo es cambiar los presupuestos psicol\u00f3gicos para erradicar cualquier tipo de violencias\u201d, se\u00f1al\u00f3 Marcela Losardo.<\/div>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-51350\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-3-1024x682.jpeg\" alt=\"\" width=\"900\" height=\"599\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-3-1024x682.jpeg 1024w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-3-300x200.jpeg 300w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-3-768x512.jpeg 768w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-3.jpeg 1280w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div>\n<div>\n<div>Participaron de la reuni\u00f3n por parte del MMGyD, la secretaria de Pol\u00edticas Contra las Violencias por Razones de G\u00e9nero, Josefina Kelly Neila; Carolina Varsky\u200b, Subsecretaria de Programas Especiales contra la Violencia por Razones de Ge\u0301nero y Laurana Malacalza, subsecretaria de Abordaje Integral de las Violencias por Motivos de G\u00e9nero; por parte del Ministerio de Seguridad estuvieron Cecilia Rodri\u0301guez\u200b, Jefa de Gabinete; Sabrina Calandro\u0301n\u200b, Subsecretaria de Derecho, Bienestar y Ge\u0301nero; Carolina Justo Von Lurzer, Directora de Poli\u0301tica de Ge\u0301nero y Soledad Laplace, Directora de Monitoreo de Gestio\u0301n y del Ministerio de Justicia y Derechos Humanos participaron\u00a0 la secretaria general Laura Marrazzo, y la directora del INADI, Victoria Donda.<\/div>\n<\/div>\n<div><\/div>\n<\/div>\n<div>\n<div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/><strong>\u00a0VIOLENCIAS EXTREMAS POR RAZONES DE G\u00c9NERO:<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f;Por violencias extremas nos referimos a\u00a0<em><strong>tentativas y homicidios<\/strong><\/em>\u00a0contra mujeres cis, trans, travestis y aquellas personas que sufrieran violencia\u00a0<em><strong>por su identidad y\/o expresi\u00f3n de g\u00e9nero u orientaci\u00f3n sexual<\/strong>.<\/em><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Las\u00a0<strong><em>violencias extrema<\/em>s<\/strong>\u00a0son un fen\u00f3meno producto de las\u00a0<em><strong>relaciones desiguales<\/strong><\/em><strong><em>y jer\u00e1rquicas de poder entre los g\u00e9neros<\/em>.<\/strong><\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/>\u00a0<strong>EL PROGRAMA INTERMINISTERIAL DE ABORDAJE INTEGRAL DE LAS VIOLENCIAS EXTREMAS POR MOTIVOS DE G\u00c9NERO<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Es uno de los componentes espec\u00edficos del\u00a0<em><strong>Plan Nacional de Acci\u00f3n contra las Violencias por Motivos de G\u00e9nero 2020-2022.<\/strong><\/em><\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/>\u00a0<strong>QUIENES<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Ministerio de las Mujeres, G\u00e9neros y Diversidad de la Naci\u00f3n<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Ministerio de Seguridad de la Naci\u00f3n<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Ministerio de Justicia y Derechos Humanos de la Naci\u00f3n<\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/>\u00a0<strong>QU\u00c9<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Se trata de una\u00a0<em><strong>pol\u00edtica focalizada y articulada<\/strong><\/em>\u00a0entre los tres ministerios\u00a0<em><strong>contra los femicidios, travesticidios y transfemicidios<\/strong><\/em>;<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Es la\u00a0<em><strong>primera vez<\/strong><\/em>\u00a0que se crea una\u00a0<em><strong>estructura gubernamental integrada<\/strong><strong>por equipos especializados<\/strong><\/em>\u00a0de los tres ministerios para\u00a0<em><strong>gestionar el abordaje integral de las violencias extremas de manera conjunta<\/strong><\/em>.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/>\u00a0<strong>POR QU\u00c9<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque las violencias extremas son\u00a0<em><strong>delitos de competencia ordinaria<\/strong><\/em>\u00a0desde el derecho penal. Cuando se judicializan\u00a0<em><strong>tramitan en las respectivas administraciones de justicia de cada provincia.<\/strong><\/em>\u00a0Es decir, intervienen los Poderes Judiciales de cada jurisdicci\u00f3n y no la justicia federal. En la<em><strong>\u00a0recepci\u00f3n de las denuncias<\/strong><\/em>, en las\u00a0<em><strong>acciones de prevenci\u00f3n policial<\/strong><\/em>\u00a0o en su rol de\u00a0<em><strong>auxiliar de la justicia<\/strong><\/em>\u00a0intervienen\u00a0<em><strong>fuerzas de seguridad provinciales<\/strong><\/em>. Hasta ahora\u00a0<em><strong>las intervenciones no se realizan de manera coordinada ni responden a lineamientos rectores comune<\/strong><\/em>s, utilizan<em><strong>\u00a0criterios diferentes<\/strong><\/em>\u00a0y\u00a0<em><strong>act\u00faan de modo fragmentado y paralelo<\/strong><\/em>. A partir de esta situaci\u00f3n es necesario\u00a0<em><strong>articular y coordinar estrat\u00e9gicament<\/strong><strong>e<\/strong><\/em>\u00a0las acciones que se llevan adelante desde las\u00a0<em><strong>distintas agencias del Estado<\/strong><\/em>, en sus\u00a0<em><strong>diferentes niveles<\/strong><\/em>, exigencia de\u00a0<em><strong>mejorar esas acciones<\/strong><\/em>\u00a0y crear\u00a0<em><strong>nuevas formas de intervenci\u00f3n<\/strong><\/em>\u00a0sobre el fen\u00f3meno de las violencias extremas.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque es necesario abordar la problem\u00e1tica desde\u00a0<em><strong>pol\u00edticas p\u00fablicas integrales<\/strong><\/em>\u00a0que articulen las diversas iniciativas estatales.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque es necesario crear un\u00a0<em><strong>sistema de gesti\u00f3n de la informaci\u00f3n integrado<\/strong><\/em>\u00a0que permita obtener datos fundamentales para mejorar las respuestas preventivas, para evaluar los d\u00e9ficits en las acciones estatales y monitorear el alcance de su eficacia<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque es necesario considerar el\u00a0<em><strong>car\u00e1cter federal de las pol\u00edticas<\/strong><\/em>\u00a0y construir\u00a0<em><strong>modelos de gesti\u00f3n integrada<\/strong><\/em>\u00a0y\u00a0<em><strong>flexible<\/strong><\/em>entre\u00a0<em><strong>Nac<wbr \/>i\u00f3n<\/strong><\/em>,\u00a0<em><strong>Provincias<\/strong><\/em>y\u00a0<em><strong>Municipios<\/strong><\/em>.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque la\u00a0<em><strong>descoordinaci\u00f3n<\/strong><\/em>, l<em><strong>a duplicaci\u00f3n de recursos<\/strong><\/em>,\u00a0<em><strong>la disparidad de criterios y la generaci\u00f3n de m\u00faltiples instancias de asistencia<\/strong><\/em>\u00a0muchas veces\u00a0<em><strong>reproducen esquemas revictimizantes<\/strong><\/em>\u00a0y dan cuenta de la falta de di\u00e1logo y consensos dentro de los gabinetes nacionales.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Porque la\u00a0<em><strong>articulaci\u00f3n<\/strong><\/em>, el\u00a0<em><strong>di\u00e1logo<\/strong><\/em>y la\u00a0<em><strong>definici\u00f3n de objetivos<\/strong><strong>comunes<\/strong><\/em>entre los organismos p\u00fablicos\u00a0<em><strong>permiten implementar intervenciones m\u00e1s efectivas<\/strong><\/em>.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/>\u00a0<strong>C\u00d3MO<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; A trav\u00e9s de un\u00a0<em><strong>abordaje integral<\/strong><\/em>, que se propone dejar atr\u00e1s el paradigma estrictamente securitario ya que se entiende que frente a situaciones complejas no corresponde reducir la intervenci\u00f3n exclusivamente al sistema penal.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; A trav\u00e9s de\u00a0<em><strong>mecanismos de coordinaci\u00f3n y articulaci\u00f3n<\/strong><\/em>\u00a0que aseguren un\u00a0<em><strong>abordaje interagencial y transversal<\/strong><\/em>para abordar un fen\u00f3meno que es multicausal, multidimensional y complejo.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; A trav\u00e9s de\u00a0<em><strong>una \u00fanica estrategia desde el Poder Ejecutivo Nacional<\/strong><\/em>\u00a0que potencie la capacidad instalada de los tres ministerios intervinientes.<\/div>\n<div><\/div>\n<div>Distintas l\u00edneas de trabajo:<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f;\u00a0<strong>Prevenci\u00f3n<\/strong><\/div>\n<div><\/div>\n<div>&#x2705; Desarrollo de un\u00a0<em><strong>Sistema de Alertas Tempranas<\/strong><\/em>;<\/div>\n<div>&#x2705; Desarrollo de\u00a0<em><strong>herramientas de detecci\u00f3n temprana<\/strong><\/em>\u00a0para la prevenci\u00f3n de las violencias extremas por motivos de g\u00e9nero que\u00a0<em><strong>eviten la escalada de violencia<\/strong><\/em>;<\/div>\n<div>&#x2705;\u00a0Implementaci\u00f3n de\u00a0<strong><em>capacitaciones<\/em><\/strong>en materia de violencias extremas por motivos de g\u00e9nero.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f;\u00a0<strong>Asistencia<\/strong><\/div>\n<div><\/div>\n<div>&#x2705; Articulaci\u00f3n de las L\u00edneas 144, 911 y 137;<\/div>\n<div>&#x2705; Profundizaci\u00f3n de la articulaci\u00f3n de las \u00e1reas de g\u00e9nero de las Fuerzas Policiales y de Seguridad para la asistencia a personas en situaci\u00f3n de violencia de g\u00e9nero.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f;\u00a0<strong>Fortalecimiento de acceso a la justicia,\u00a0 protecci\u00f3n y reparaci\u00f3n<\/strong><\/div>\n<div><\/div>\n<div>&#x2705; Desarrollo de acciones espec\u00edficas para la prevenci\u00f3n y restricci\u00f3n de la portaci\u00f3n y tenencia de armamento reglamentario y civil a los agresores;<\/div>\n<div>&#x2705; Fortalecimiento del acceso a la justicia;<\/div>\n<div>&#x2705; Ampliaci\u00f3n de pol\u00edticas de reparaci\u00f3n para familiares y personas allegadas de v\u00edctimas de violencias extremas por razones de g\u00e9nero.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f;\u00a0<strong>Gesti\u00f3n de la informaci\u00f3n<\/strong><\/div>\n<div><\/div>\n<div>&#x2705; Desarrollo e implementaci\u00f3n del\u00a0<em><strong>Sistema \u00danico de Registro de Denuncias por Violencia de G\u00e9nero<\/strong><\/em>;<\/div>\n<div>&#x2705;\u00a0<em><strong>Sistema Nacional de Gesti\u00f3n de la Informaci\u00f3n en materia de Violencias Extremas<\/strong><\/em>.<\/div>\n<div><\/div>\n<div><img decoding=\"async\" class=\"CToWUd\" src=\"https:\/\/mail.google.com\/mail\/e\/1f4cc\" alt=\"&#x1f4cc;\" data-goomoji=\"1f4cc\" data-image-whitelisted=\"\" \/><strong>\u00a0LA UNIDAD EJECUTORA DEL PROGRAMA<\/strong><\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Tiene como objetivo\u00a0<em><strong>garantizar que las medidas y acciones<\/strong><\/em>\u00a0incluidas en este programa\u00a0<em><strong>sean efectivamente implementadas conforme a los criterios unificados<\/strong><\/em>.<\/div>\n<div><\/div>\n<div>&#x25b6;&#xfe0f; Est\u00e1 integrada por\u00a0<em><strong>equipos especializados de los tres ministerios<\/strong><\/em>\u00a0designados por las m\u00e1ximas autoridades de los mismos.<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div><a href=\"https:\/\/diariofemenino.com.ar\/category\/agenda-feminista\/\">Agenda Feminista<\/a><\/div>\n<div><a href=\"https:\/\/diariofemenino.com.ar\/\">Diario Digital Femenino<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La articulaci\u00f3n entre todos los niveles del Estado es una condici\u00f3n ineludible para un abordaje eficaz de las Violencias extremas por motivos de g\u00e9nero Este viernes, en el Sal\u00f3n de las Mujeres de la Casa Rosada, con la participaci\u00f3n de la ministra de las Mujeres, G\u00e9neros y Diversidad, Elizabeth G\u00f3mez Alcorta; la ministra de Seguridad, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":51351,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":""},"categories":[1067,32,592],"tags":[3454,3453,3455],"class_list":["post-51348","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-feminista","category-mujeres","category-violencias","tag-abordaje-integral","tag-unidad-ejecutora","tag-violencias-extremas"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-14T20:40:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-15T14:25:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias\",\"datePublished\":\"2020-08-14T20:40:36+00:00\",\"dateModified\":\"2020-08-15T14:25:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/\"},\"wordCount\":1661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg\",\"keywords\":[\"Abordaje Integral\",\"Unidad Ejecutora\",\"Violencias Extremas\"],\"articleSection\":[\"Agenda Feminista\",\"Mujeres\",\"Violencias\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/\",\"name\":\"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg\",\"datePublished\":\"2020-08-14T20:40:36+00:00\",\"dateModified\":\"2020-08-15T14:25:05+00:00\",\"description\":\"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/gomez-alcorta-losardo-y-frederic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino","description":"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/","og_locale":"es_ES","og_type":"article","og_title":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino","og_description":"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias","og_url":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2020-08-14T20:40:36+00:00","article_modified_time":"2020-08-15T14:25:05+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias","datePublished":"2020-08-14T20:40:36+00:00","dateModified":"2020-08-15T14:25:05+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/"},"wordCount":1661,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","keywords":["Abordaje Integral","Unidad Ejecutora","Violencias Extremas"],"articleSection":["Agenda Feminista","Mujeres","Violencias"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/","url":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/","name":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","datePublished":"2020-08-14T20:40:36+00:00","dateModified":"2020-08-15T14:25:05+00:00","description":"G\u00f3mez Alcorta, Losardo y Frederic. Articulaci\u00f3n en los niveles del Estado como condici\u00f3n ineludible para un abordaje eficaz de las Violencias","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/gomez-alcorta-losardo-y-frederic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"G\u00f3mez Alcorta, Losardo y Frederic pusieron en funcionamiento la Unidad Ejecutora del Programa Interministerial de Abordaje Integral de las Violencias"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg","jetpack_sharing_enabled":true,"rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg",1280,853,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg",1280,853,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg",1280,853,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1-150x150.jpeg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1-300x200.jpeg",300,200,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1-1024x682.jpeg",1024,682,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg",1280,853,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2020\/08\/Unidad-Ejecutora-del-Programa-Interministerial-2020-08-14-1.jpeg",1280,853,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/agenda-feminista\/\" rel=\"category tag\">Agenda Feminista<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/mujeres\/\" rel=\"category tag\">Mujeres<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/violencias\/\" rel=\"category tag\">Violencias<\/a>","rttpg_excerpt":"La articulaci\u00f3n entre todos los niveles del Estado es una condici\u00f3n ineludible para un abordaje eficaz de las Violencias extremas por motivos de g\u00e9nero Este viernes, en el Sal\u00f3n de las Mujeres de la Casa Rosada, con la participaci\u00f3n de la ministra de las Mujeres, G\u00e9neros y Diversidad, Elizabeth G\u00f3mez Alcorta; la ministra de Seguridad,&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/51348","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=51348"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/51348\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/51351"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=51348"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=51348"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=51348"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}