{"id":43532,"date":"2019-11-23T10:01:50","date_gmt":"2019-11-23T13:01:50","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/?p=43532"},"modified":"2019-11-23T10:01:50","modified_gmt":"2019-11-23T13:01:50","slug":"claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/","title":{"rendered":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n"},"content":{"rendered":"<p><strong class=\"bajada\">Claudia Sbdar fue elegida tras una votaci\u00f3n realizada en horas de la ma\u00f1ana por los miembros del <a href=\"https:\/\/www.justucuman.gov.ar\/\">Tribunal<\/a>.<\/strong><\/p>\n<p>La magistrada Claudia Sbdar ocupar\u00e1 la presidencia del m\u00e1ximo \u00f3rgano de justicia de la provincia hasta el a\u00f1o 2021, en reemplazo del presidente saliente Daniel Posse, quien ocupa el cargo desde noviembre de 2017 y cuyo mandato vence el pr\u00f3ximo 25 de noviembre.<\/p>\n<figure id=\"attachment_43535\" aria-describedby=\"caption-attachment-43535\" style=\"width: 800px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-43535\" src=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/f800x450-94245_145691_23.jpg\" alt=\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n\" width=\"800\" height=\"450\" srcset=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/f800x450-94245_145691_23.jpg 800w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/f800x450-94245_145691_23-300x169.jpg 300w, https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/f800x450-94245_145691_23-768x432.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><figcaption id=\"caption-attachment-43535\" class=\"wp-caption-text\">Claudia Sbdar<\/figcaption><\/figure>\n<p>Ayer jueves, la flamante primera presidenta de la CSJ de la historia de la provincia, particip\u00f3 como conferencista del Seminario de Aspectos Legales \u201cMujeres del Derecho que rompieron el techo de cristal\u201d, organizado por la Universidad del CEMA. En esa oportunidad, la magistrada subray\u00f3 que \u00a0\u201cesta Corte se fund\u00f3 en 1908 y reci\u00e9n cien a\u00f1os despu\u00e9s ingres\u00e9 como la primera mujer Vocal\u201d.<\/p>\n<p>\u201cLa desigualdad entre mujeres y hombres se inscribe en el marco de los grupos vulnerables. Aunque las mujeres no seamos un grupo minoritario, ya que constituimos el 50% de la poblaci\u00f3n, s\u00ed lo somos en t\u00e9rminos de derechos. La \u00fanica forma de generar una cultura de la igualdad, de respeto y \u00a0de tolerancia por las diferencias es \u00a0vivir de acuerdo a los principios de nuestra Constituci\u00f3n y transmitirlos, efectivamente, de generaci\u00f3n en generaci\u00f3n\u201d, reflexion\u00f3 Sbdar ante el auditorio.<\/p>\n<p>Y se\u00f1al\u00f3 en la misma l\u00ednea que \u00abel d\u00eda que no se organicen seminarios sobre esta tem\u00e1tica ni se se\u00f1ale &#8216;se trata de la primera mujer que&#8230;&#8217; habremos superado la desigualdad\u201d<\/p>\n<p>Fuente: El\u00a0Tucumano<\/p>\n<hr \/>\n<p>En 2014 accedi\u00f3 a una vocal\u00eda en la Corte\u00a0Suprema de Justicia de<a href=\"https:\/\/derecho.unt.edu.ar\/\"> Tucum\u00e1n\u00a0<\/a><\/p>\n<h3 class=\"nttit flab entry-title\" style=\"text-align: center;\">Reflexiones de una mujer en la cumbre de la Justicia<\/h3>\n<div class=\"ntbaj entry-summary\">La primera miembro de la Corte Suprema de Justicia de la Provincia habl\u00f3 desde la mirada femenina. Tiene un profuso curr\u00edculum que la justifica en ese lugar.<\/div>\n<div class=\"nttxt entry-content\">\n<p>La primera <a href=\"https:\/\/diariofemenino.com.ar\/mujeres-en-la-justicia-minoria-en-los-maximos-cargos-y-mayoria-entre-el-personal-administrativo\/\">mujer<\/a> que llega a una vocal\u00eda de la Corte Suprema de Justicia de Tucum\u00e1n es Claudia Sbdar. Tiene un largo itinerario en el derecho que se inicia como ayudante estudiantil, \u201cborrando pizarrones\u201d hasta su doctorado en la Universidad Complutense de Madrid, con el tema Amparo. La primera parte de su carrera como abogada la hizo en el estudio jur\u00eddico de un docente que la invit\u00f3 a trabajar con \u00e9l. Su primer concurso lo rinde en 1985 y llega al cargo de Jefa de Trabajos Pr\u00e1cticos en la c\u00e1tedra de Derecho Procesal II.<\/p>\n<p>El a\u00f1o pasado gan\u00f3 la titularidad en la materia.\u00a0<em>\u201cPero yo ten\u00eda el coraz\u00f3n puesto en el Poder Judicial, en el servicio de Justicia\u201d<\/em>. Cuando se constituy\u00f3 en el a\u00f1o 1992 el primer Consejo de la Magistratura,\u00a0<em>\u201cme present\u00e9 y fui designada Juez en lo Civil y Comercial Com\u00fan de la IV\u00b0 Nominaci\u00f3n del Centro Judicial de la Capital. Era muy joven, ten\u00eda 29 a\u00f1os. Fue una experiencia muy interesante, muy fuerte\u201d<\/em>.<\/p>\n<p>Lleg\u00f3 a un juzgado que hab\u00eda tenido una vacancia larga por lo que ten\u00eda un atraso muy importante,\u00a0<em>\u201cnos pusimos a trabajar fuertemente con todo el equipo y pusimos al d\u00eda\u201d<\/em>.<\/p>\n<p>Su itinerario discurriendo entre los pasillos universitarios y de los tribunales advirti\u00f3 que el sistema judicial no daba las respuestas que le hubieran gustado para satisfacer a los ciudadanos.<\/p>\n<p>Sbdar va a la Corte que en ese momento estaba presidida por el doctor Ren\u00e9 Padilla, lo refiere como un gran amigo, una gran persona. Integraba el cuerpo tambi\u00e9n el doctor Arturo Ponsati, amigo m\u00edo, tuve la suerte y el gusto de compartir esa amistad y el doctor Goane.<\/p>\n<p>En ese momento invitaron a incorporarse como relatora de la Corte.\u00a0<em>\u201cLo pens\u00e9: bueno, esto est\u00e1 muy ligado a lo que ten\u00eda ganas de hacer: investigar, estudiar los casos que llegan a la Corte por la naturaleza de las cuestiones\u201d<\/em>.<\/p>\n<p>Qued\u00f3 muchos a\u00f1os trabajando como relatora de la Corte paralelamente desarrollando una fuerte vida acad\u00e9mica en la Facultad. Defendi\u00f3 su tesis en el a\u00f1o 2004; hoy quien fue su director de tesis es el actual decano de la Facultad de Derecho de la Universidad Complutense de Madrid,\u00a0<em>un gran profesor y tuve la dicha de que ha presidido mi tribunal de tesis don Pablo Lucas Verd\u00fa que ha sido uno de los mejores constitucionalistas europeos<\/em>.<\/p>\n<p>En el a\u00f1o 2007, en septiembre, estaba inclin\u00e1ndose por una fuerte actividad acad\u00e9mica con la posibilidad de incorporarse en una c\u00e1tedra de la Universidad de Buenos Aires y la Universidad de El Salvador,\u00a0<em>cuando estaba cerrando ese trabajo para el a\u00f1o siguiente, 2008, se produjo la vacante en la Corte. En ese momento -a fines de marzo a principios de abril- me cit\u00f3 el gobernador de la provincia y me dijo si me interesaba ocupar ese cargo en la Corte y le dije que para m\u00ed era un honor enorme y as\u00ed se dio esta situaci\u00f3n. En abril de 2008 ingres\u00e9 a formar parte de este tribunal<\/em>.<\/p>\n<p><strong>\u00bfC\u00f3mo es ser mujer en la Corte?<\/strong><\/p>\n<p>Creo que es muy importante la participaci\u00f3n de la <a href=\"https:\/\/diariofemenino.com.ar\/category\/genero-y-derechos-humanos\/\">mujer<\/a> en los espacios de poder donde se toman decisiones porque efectivamente hay diferencia entre el hombre y la mujer. Es muy bueno y muy rico compartir miradas distintas del hombre y la mujer.<\/p>\n<p>Dec\u00eda el otro d\u00eda, a prop\u00f3sito de un acto que hizo la Asociaci\u00f3n de Prensa, donde me invitaron, que sent\u00eda una alegr\u00eda muy grande por esto que ya no se va a decir nunca m\u00e1s que es la primera mujer. A partir de ahora se naturaliza la participaci\u00f3n femenina. Le da otra din\u00e1mica. Sinceramente creo que han obtenido \u2013en ese aspecto- importantes logros, es frutos de luchas de muchos a\u00f1os.<\/p>\n<p>Creo que el ordenamiento jur\u00eddico argentino est\u00e1 a la vanguardia en materia de derechos de la mujer. Sin embargo hay innumerables casos de discriminaci\u00f3n que se viven todos los d\u00edas y uno se sigue asombrando. Es un trabajo que hay que dar.<\/p>\n<p><strong>\u00bfQu\u00e9 se puede hacer para modificar la cultura de la descalificaci\u00f3n a la mujer?<\/strong><\/p>\n<p>Hay que trabajar mucho en educaci\u00f3n. Creo que es la herramienta m\u00e1s importante para modificar la cultura, para que en todos los sectores de la sociedad haya conciencia y no se permitan actos de discriminaci\u00f3n, en primer lugar.<\/p>\n<p>En segundo lugar porque creo que la \u00fanica exigencia es la idoneidad para ocupar funciones y desarrollar actividades para que las mujeres podamos ocupar los espacios importante y seguir apostando fuertemente a la sociedad. La formaci\u00f3n como herramienta para eliminar y prevenir este tipo de conductas que est\u00e1n instaladas en la cultura.<\/p>\n<p><strong>\u00bfQui\u00e9n tiene m\u00e1s peso en la decisi\u00f3n de la Justicia: el poder o la ley?<\/strong><\/p>\n<p>La Constituci\u00f3n es el acuerdo que organiza un Estado y es la ley madre, que debe ser aplicada todo los d\u00edas y en todos los \u00e1mbitos p\u00fablicos y privados. No es el poder el que regula las relaciones entre las personas.<\/p>\n<p><strong>\u00bfEs cierto lo que refiere el vulgo que hay dos bibliotecas para resolver asuntos en la Justicia?<\/strong><\/p>\n<p>El ser humano hace interpretaciones de las normas de derecho y puede haber interpretaciones distintas en ese sentido. Si las interpretaciones se ajusten a la Constituci\u00f3n son razonables y coherentes, son aceptables. La \u00faltima palabra la tiene la Corte Suprema de la Naci\u00f3n en el control difuso de constitucionalidad. Finalmente ese criterio, de la Corte Suprema, dir\u00e1 cu\u00e1l es la interpretaci\u00f3n de la norma, (siempre que se trate del derecho federal) y cu\u00e1l no. Esa es la \u00faltima palabra.<\/p>\n<p><strong>\u00bfQu\u00e9 es la jurisprudencia?<\/strong><\/p>\n<p>Es una ciencia del derecho, un criterio sobre un problema jur\u00eddico establecido por una pluralidad de sentencias concordes. Pero no existe una norma que diga que son obligatorios para que los jueces inferiores tomen esas decisiones de la Corte. Lo que existe es, sin embargo, una costumbre \u2013dir\u00eda- de que apliquen esa jurisprudencia de muchos a\u00f1os que se ha establecido. Si hay razones fundadas pueden apartarse explicando esas razones. Lo que no se puede es apartarse caprichosamente de esa interpretaci\u00f3n.<\/p>\n<p><strong>\u00bfQu\u00e9 hace la Justicia cuando otro poder del Estado no da satisfacci\u00f3n a las demandas de los ciudadanos?<\/strong><\/p>\n<p>Creo que hay un \u00e1mbito de decisi\u00f3n del poder administrador que tiene que ver con razones de m\u00e9rito, e implementar pol\u00edticas p\u00fablicas que es propio del \u00e1mbito de la administraci\u00f3n respecto de lo cual el Poder Judicial no puede tener injerencia. Ahora hay algunas cuestiones que han ido generando alg\u00fan tipo de decisiones judiciales. Por ejemplo se ha echado mano a un tipo de sentencias que se llaman Exhortativas que son sentencias judiciales, que act\u00faan solo cuando hay un inter\u00e9s de alguien que lo plant\u00e9. Cuando se han hecho esos planteos en algunos casos las respuestas de la justicia, por ejemplo, en la causa del Riachuelo ha sido una exhortaci\u00f3n que est\u00e1 se\u00f1alando la necesidad de ciertas modificaciones y ha establecido \u2013en esa causa- determinadas obligaciones que el Poder Ejecutivo tiene que cumplir para sanear esa cuenca. Creo que hay un \u00e1mbito del Poder Ejecutivo donde el Poder Judicial no puede ni debe ingresar. Creo tambi\u00e9n que no hay que perder de vista que no se le puede exigir que sustituya lo que es propio.<\/p>\n<p><strong>\u00bfEl Derecho Procesal no incide negativamente en la resoluci\u00f3n de los conflictos?<\/strong><\/p>\n<p>Todo lo contrario. El Derecho Procesal es instrumental, es una garant\u00eda constitucional, es la senda por donde deben transitar los conflictos que est\u00e1n los derechos de fondo. Esas reglas de debate del conflicto tienen que constituirse en una garant\u00eda para el ciudadano. Cuando hay que hacer un reclamo ante Poder Judicial no se hace sino a trav\u00e9s de un mecanismo procesal: la igualdad de las partes, la oportunidad. Esto hace a lo que se llama el Derecho a la Jurisdicci\u00f3n. El derecho a que uno toque la puerta del Poder Judicial y se abra. El derecho no solamente a transitar un debido proceso a obtener una sentencia en tiempo, justa, a que haya mecanismos para objetar y discutir esa sentencia. Para que haya mecanismos para ejecutar esa sentencia. Eso es el derecho a la jurisdicci\u00f3n y eso es el derecho procesal como herramienta. El Proceso Civil escrito est\u00e1 puesto en cuesti\u00f3n tal como lo concebimos y como lo tenemos vigente. Hay una tendencia muy fuerte a la oralizaci\u00f3n, en sentar una modificaci\u00f3n sustancial en relaci\u00f3n al proceso civil: acortando actos y oralizando actos lo que significa un cambio muy importante.<\/p>\n<p><strong>\u00bfQu\u00e9 hace la Oficina de Gesti\u00f3n Judicial?<\/strong><\/p>\n<p>Con la Oficina de Gesti\u00f3n Judicial que hemos establecido en el Poder Judicial y se han hecho cambios muy importantes, de organizaci\u00f3n, de actitud, de clima laboral de manejo de recursos inform\u00e1ticos dentro de la unidad jurisdiccional.<\/p>\n<p><strong>\u00bfIncide la presi\u00f3n ciudadana en la Justicia?<\/strong><\/p>\n<p>Lo primero que hay que decir es que el juez o la jueza toma una resoluci\u00f3n de acuerdo a lo que ha ocurrido, a la realidad del expediente y a la interpretaci\u00f3n que hace de los hechos y del derecho aplicable en el caso. En segundo lugar me parece que esto de que los jueces s\u00f3lo hablan por su sentencia no es tan as\u00ed que es muy importante la adecuada comunicaci\u00f3n. Es una responsabilidad obvia de la justicia de organizar la comunicaci\u00f3n y, la responsabilidad de los medios de comunicar adecuadamente las resoluciones judiciales. No obstante creo que en general un juez o una jueza no pueden ser ajenos y no pensar las consecuencias que traen aparejada su decisi\u00f3n aunque nunca se sabe hasta que no se conoce la resoluci\u00f3n. Me estoy refiriendo a decisiones que tienen que ver con el \u00e1mbito socioecon\u00f3mico que tipo de consecuencias podr\u00eda acarrear el dictado de una sentencia y ah\u00ed hay como una puerta de la responsabilidad social en las decisiones que creo que eso tampoco debe perderse de vista.<\/p>\n<p><strong>\u00bfQu\u00e9 hace la Justicia cuando hay una investigaci\u00f3n mal hecha por los auxiliares?<\/strong><\/p>\n<p>Hay much\u00edsimas personas que trabajan muy seriamente, han puesto idoneidad, responsabilidad, pasi\u00f3n por el trabajo porque esto es un servicio p\u00fablico y hay que tener vocaci\u00f3n para esto y as\u00ed desarrollarlo. Hay equipos de personas muy, muy serios. Es un an\u00e1lisis particular en cada caso habr\u00e1 que ver cu\u00e1l es la situaci\u00f3n y hay un r\u00e9gimen administrativo de revisi\u00f3n, si alguien se queja y hay un planteo por v\u00eda de superintendencia y el asunto llega a la Corte se dispone hacer un sumario para investigar lo que ha ocurrido en el caso puntual. Creo que los equipos t\u00e9cnicos no tienen el n\u00famero adecuado de personas para funcionar o por ah\u00ed faltan algunos profesionales que puedan desarrollar algunas pr\u00e1cticas que no se hacen en el \u00e1mbito judicial y hay que remitirlos a otros lugares para que se hagan. Bueno hay que aspirar a que en alg\u00fan momento se hagan para que nosotros podamos resolverlos adecuadamente.<\/p>\n<p><strong>F\u00e9lix Justiniano Mothe<\/strong><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Claudia Sbdar fue elegida tras una votaci\u00f3n realizada en horas de la ma\u00f1ana por los miembros del Tribunal. La magistrada Claudia Sbdar ocupar\u00e1 la presidencia del m\u00e1ximo \u00f3rgano de justicia de la provincia hasta el a\u00f1o 2021, en reemplazo del presidente saliente Daniel Posse, quien ocupa el cargo desde noviembre de 2017 y cuyo mandato [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":43533,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":121,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[32,6],"tags":[2423,2424,39,130],"class_list":["post-43532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mujeres","category-articulos","tag-claudia-sbdar","tag-corte-suprema-de-tucuman","tag-justicia","tag-mujeres"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[4],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-23T13:01:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"732\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\"},\"headline\":\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n\",\"datePublished\":\"2019-11-23T13:01:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/\"},\"wordCount\":2225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/3_1530883207_B.jpg\",\"keywords\":[\"Claudia Sbdar\",\"Corte Suprema de Tucum\u00e1n\",\"Justicia\",\"Mujeres\"],\"articleSection\":[\"Mujeres\",\"Mujeres en Palabras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/\",\"name\":\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/3_1530883207_B.jpg\",\"datePublished\":\"2019-11-23T13:01:50+00:00\",\"description\":\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/3_1530883207_B.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/3_1530883207_B.jpg\",\"width\":1200,\"height\":732,\"caption\":\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/bf6199e8158c657ea6f789b11ec85509\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/lenny\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino","description":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/","og_locale":"es_ES","og_type":"article","og_title":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino","og_description":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.","og_url":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2019-11-23T13:01:50+00:00","og_image":[{"width":1200,"height":732,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509"},"headline":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n","datePublished":"2019-11-23T13:01:50+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/"},"wordCount":2225,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","keywords":["Claudia Sbdar","Corte Suprema de Tucum\u00e1n","Justicia","Mujeres"],"articleSection":["Mujeres","Mujeres en Palabras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/","url":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/","name":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","datePublished":"2019-11-23T13:01:50+00:00","description":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n. Fue elegida ayer tras una votaci\u00f3n realizada por los miembros del Tribunal.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","width":1200,"height":732,"caption":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/claudia-sbdar-es-la-primera-mujer-en-presidir-la-corte-suprema-de-tucuman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Claudia Sbdar es la primera mujer en presidir la Corte Suprema de Tucum\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/bf6199e8158c657ea6f789b11ec85509","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg","rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg",1200,732,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg",1200,732,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg",1200,732,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B-300x183.jpg",300,183,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B-1024x625.jpg",1024,625,true],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg",1200,732,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/11\/3_1530883207_B.jpg",1200,732,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/lenny\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/mujeres\/\" rel=\"category tag\">Mujeres<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/articulos\/\" rel=\"category tag\">Mujeres en Palabras<\/a>","rttpg_excerpt":"Claudia Sbdar fue elegida tras una votaci\u00f3n realizada en horas de la ma\u00f1ana por los miembros del Tribunal. La magistrada Claudia Sbdar ocupar\u00e1 la presidencia del m\u00e1ximo \u00f3rgano de justicia de la provincia hasta el a\u00f1o 2021, en reemplazo del presidente saliente Daniel Posse, quien ocupa el cargo desde noviembre de 2017 y cuyo mandato&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/43532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=43532"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/43532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/43533"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=43532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=43532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=43532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}