{"id":33798,"date":"2019-04-03T15:02:06","date_gmt":"2019-04-03T18:02:06","guid":{"rendered":"https:\/\/diariofemenino.com.ar\/?p=33798"},"modified":"2019-04-03T15:02:06","modified_gmt":"2019-04-03T18:02:06","slug":"las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/","title":{"rendered":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos"},"content":{"rendered":"<figure id=\"figure_2882944\" class=\"XL caja-destacada epigrafe\" data-is=\"imagen\"><figcaption><strong>Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo de carrera.<\/strong><\/figcaption><\/figure>\n<div class=\"barra\">\n<section class=\"autores\">\n<section><\/section>\n<section class=\"autor\"><a href=\"https:\/\/www.lanacion.com.ar\/autor\/delfina-torres-cabreros-11898\">Delfina Torres Cabreros<\/a>\u00a0<\/section>\n<\/section>\n<div class=\"datos-nota\">\n<section class=\"herramientas\">\n<div class=\"group-share\"><\/div>\n<div class=\"group-share\">Evocar el recuerdo de una maestra o una empleada dom\u00e9stica es un ejercicio mental de lo m\u00e1s sencillo: las hemos visto por todos lados.\u00a0M\u00e1s dif\u00edcil resulta imaginar plomeras, mujeres electricistas, operadoras de montacargas, desarrolladoras de software. Los casos son tan excepcionales que es posible pasarse la vida entera sin conocer a una.<\/div>\n<\/section>\n<\/div>\n<\/div>\n<p>Las mujeres acceden predominantemente a los puestos m\u00e1s alejados del poder de decisi\u00f3n y que implican una prolongaci\u00f3n de los h\u00e1bitos hogare\u00f1os, teniendo menor participaci\u00f3n en los empleos con mejores perspectivas de desarrollo. Esta situaci\u00f3n tiene consecuencias no solo a nivel social -la perpetuaci\u00f3n de una situaci\u00f3n de desigualdad-, sino en el plano econ\u00f3mico.<\/p>\n<p>\u00abAdem\u00e1s de ser moralmente exigible, la igualdad es econ\u00f3micamente rentable\u00bb, resumen en el\u00a0Instituto Nacional de las Mujeres\u00a0y agregan que, seg\u00fan estimaciones del\u00a0FMI\u00a0, si los pa\u00edses de Am\u00e9rica Latina aumentaran la participaci\u00f3n laboral femenina hasta el nivel de los pa\u00edses n\u00f3rdicos (que ronda el 60%), el PIB per c\u00e1pita podr\u00eda ser hasta un 10% m\u00e1s alto.<\/p>\n<p>En este marco, y bajo el paraguas del\u00a0Plan de Igualdad de Oportunidades y Derechos (PIOD)\u00a0que lanz\u00f3 en diciembre pasado la cartera de\u00a0Carolina Stanley\u00a0, la\u00a0Secretar\u00eda de Trabajo\u00a0impuls\u00f3 el Programa de Formaci\u00f3n para la Equidad de G\u00e9nero (Forgen). Esta iniciativa tiene como antecedente el Programa Nuevos Oficios para Mujeres de la gesti\u00f3n kirchnerista y busca promover la presencia femenina en aquellos trabajos tradicionalmente considerados \u00abde hombres\u00bb, ofreciendo capacitaciones en esas \u00e1reas. La meta es incorporar dentro de la poblaci\u00f3n participante de los cursos de formaci\u00f3n de los sectores m\u00e1s masculinizados un porcentaje de mujeres no menor al 10% en 2019 y al 20% en 2020.<\/p>\n<h2 id=\"\u00bfcuales-son-los-oficios-en-los-que-hay-menos-mujeres\" class=\"subtitulo-1\">\u00bfCu\u00e1les son los oficios en los que hay menos mujeres?<\/h2>\n<p>Seg\u00fan datos oficiales a los que accedi\u00f3\u00a0<b>LA NACION<\/b>, la presencia femenina es marginal en reparaci\u00f3n de electrodom\u00e9sticos, donde representa solo el 1,6% del total de trabajadores. Tambi\u00e9n hay muy pocas mujeres en plomer\u00eda (6,1%) y menos a\u00fan en tareas de electricidad (1,9% del total). Sin embargo, las pocas que existen buscan la manera de construir redes y as\u00ed surgi\u00f3 el grupo de Facebook Mujeres Trabajando, que acompa\u00f1ando las demandas sociales de la \u00e9poca cambi\u00f3 luego su nombre a Transfeministas Trabajando.<\/p>\n<p>Yami Naza es una de las electricistas del grupo y estudi\u00f3 en el marco de los programas de formaci\u00f3n del gobierno anterior. \u00abEn un comienzo lo hab\u00eda pensado solamente para hacerlo en mi casa, despu\u00e9s me pidi\u00f3 que le haga un arreglo una amiga, ella me recomend\u00f3 a otra amiga y as\u00ed se fue girando la bola hasta que lleg\u00f3 el momento en que ten\u00eda mi p\u00e1gina y mi cartera de clientes, que se conforma solo de mujeres e identidades disidentes\u00bb, aclara.<\/p>\n<figure id=\"figure_2882661\" class=\"L epigrafe\" data-is=\"imagen\"><picture><source srcset=\"\/\/bucket1.glanacion.com\/anexos\/fotos\/61\/2882661w740.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"\/\/bucket1.glanacion.com\/anexos\/fotos\/61\/2882661w768.jpg\" media=\"(min-width: 380px)\" \/><img decoding=\"async\" src=\"https:\/\/bucket1.glanacion.com\/anexos\/fotos\/61\/2882661w380.jpg\" alt=\"Yami Naza est\u00e1 dentro del 1,9% de mujeres que realizan tareas de electricidad\" \/><\/picture><figcaption>Yami Naza est\u00e1 dentro del 1,9% de mujeres que realizan tareas de electricidad\u00a0<span class=\"fuente\">Fuente: LA NACION &#8211; Cr\u00e9dito: Hern\u00e1n Zenteno<\/span><\/figcaption><\/figure>\n<p>El n\u00famero de mujeres dedicadas a la reparaci\u00f3n de bicicletas tambi\u00e9n es bajo (20,8%) y no es habitual recibir la asistencia de t\u00e9cnicas en\u00a0<i>service<\/i>\u00a0de lavarropas o en instalaci\u00f3n y reparaci\u00f3n de aires acondicionados (2,2%).<\/p>\n<p>Es una misi\u00f3n casi imposible encontrar operadoras de montacargas moviendo palets de mercader\u00eda y tampoco suelen operar retroexcavadoras ni guinches en el puerto. Seg\u00fan los registros de la Secretar\u00eda de Trabajo, las mujeres son solo 18,7% en el rubro de log\u00edstica.<\/p>\n<p>Daniel Amarante, secretario adjunto del Sindicato de Guincheros y Maquinistas de Gr\u00faas M\u00f3viles explica que si bien hay mujeres encuadradas dentro de su convenio colectivo de trabajo, no conoce ninguna que se desempe\u00f1e en esas tareas en particular. \u00abS\u00ed manejan autos en la terminal de Z\u00e1rate, pero gr\u00faas no. Incluso en los cursos que damos de otras tareas portuarias como apuntadores, amarradores o trincadores nunca se acercaron mujeres\u00bb, dice Amarante, y asegura que \u00ablas terminales portuarias de contenedores nunca pidieron trabajadoras guincheras\u00bb. Sin embargo, es un trabajo que no requiere fuerza ni cualidades f\u00edsicas excepcionales: las gr\u00faas son semi autom\u00e1ticas y se manejan con\u00a0<i>joystiks<\/i>\u00a0similares a los de los videojuegos.<\/p>\n<figure id=\"figure_2882946\" class=\"L epigrafe\" data-is=\"imagen\"><picture><source srcset=\"\/\/bucket3.glanacion.com\/anexos\/fotos\/46\/2882946w740.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"\/\/bucket3.glanacion.com\/anexos\/fotos\/46\/2882946w768.jpg\" media=\"(min-width: 380px)\" \/><img decoding=\"async\" src=\"https:\/\/bucket3.glanacion.com\/anexos\/fotos\/46\/2882946w380.jpg\" alt=\"Una acci\u00f3n judicial iniciada por \u00c9rica Borda contribuir\u00e1 a ampliar el 3,2% de presencia femenina entre los choferes de colectivo\" \/><\/picture><figcaption>Una acci\u00f3n judicial iniciada por \u00c9rica Borda contribuir\u00e1 a ampliar el 3,2% de presencia femenina entre los choferes de colectivo\u00a0<span class=\"fuente\">Cr\u00e9dito: Victoria Gesualdi\/AFV<\/span><\/figcaption><\/figure>\n<p>Otro \u00e1rea casi exclusivamente masculina es la de conducci\u00f3n de colectivos, donde hay apenas un 3,2% de presencia femenina. Sin embargo, esto comenz\u00f3 a cambiar en el \u00faltimo tiempo a partir del reclamo judicial de\u00a0\u00c9rica Borda, una colectivera que tras sufrir un accidente en 2010 fue rechazada sistem\u00e1ticamente en todas las l\u00edneas de transporte en las que solicit\u00f3 trabajo. La resoluci\u00f3n judicial con que culmin\u00f3 su caso orden\u00f3 a las empresas del sector contratar al menos un 30% de conductoras y, a ra\u00edz de eso,\u00a0el Gobierno cre\u00f3 en enero pasado el Listado de Mujeres Aspirantes a Choferes de Colectivo\u00a0para facilitar su multiplicaci\u00f3n en el rubro.<\/p>\n<p>Seg\u00fan consta en los registros oficiales, tampoco hay mujeres como operadoras en plantas de procesamiento de agua, cloacas o en las cuadrillas de reparaciones. En el rubro de los medios de comunicaci\u00f3n, las mujeres son menos de un tercio (29,3%) entre los operadores de c\u00e1maras, iluminaci\u00f3n y sonido.<\/p>\n<p>Dentro del sector de inform\u00e1tica, desde la Secretar\u00eda detectaron una falta de desarrolladoras\u00a0<i>web<\/i>\u00a0orientadas a videojuegos y de programadoras. Tampoco es habitual encontrar mujeres ocupadas como\u00a0<i>testers<\/i>, es decir, en la tarea de control de calidad de los sistemas.<\/p>\n<figure id=\"figure_2836516\" class=\"L epigrafe\" data-is=\"imagen\"><picture><source srcset=\"\/\/bucket3.glanacion.com\/anexos\/fotos\/16\/2836516w740.jpg\" media=\"(min-width: 768px)\" \/><source srcset=\"\/\/bucket3.glanacion.com\/anexos\/fotos\/16\/2836516w768.jpg\" media=\"(min-width: 380px)\" \/><img decoding=\"async\" src=\"https:\/\/bucket3.glanacion.com\/anexos\/fotos\/16\/2836516w380.jpg\" alt=\"Durante los \u00faltimos cinco a\u00f1os las carreras vinculadas con programaci\u00f3n tuvieron solo 16% de matr\u00edcula femenina\" \/><\/picture><figcaption>Durante los \u00faltimos cinco a\u00f1os las carreras vinculadas con programaci\u00f3n tuvieron solo 16% de matr\u00edcula femenina\u00a0<span class=\"fuente\">Fuente: LA NACION<\/span><\/figcaption><\/figure>\n<p>Seg\u00fan los datos recopilados por la organizaci\u00f3n Chicas en Tecnolog\u00eda, que busca cerrar la brecha de g\u00e9nero en este rubro, solo el 6% de las aplicaciones m\u00f3viles que usamos fueron desarrolladas por mujeres y en las carreras vinculadas con programaci\u00f3n solo el 16% de la matr\u00edcula es femenina. \u00abDeber\u00eda haber una deconstrucci\u00f3n de lo que significa estudiar una carrera de este tipo y las habilidades t\u00e9cnicas que se necesitan. Trabajamos para que formadores y familias puedan inspirar y acompa\u00f1ar a estas mujeres que hoy no est\u00e1n trabajando en el sector\u00bb, apunta Melina Masnatta, directora ejecutiva de la organizaci\u00f3n.<\/p>\n<p>La secretaria de Transformaci\u00f3n Productiva, Paula Szenkman, resume esta situaci\u00f3n con una frase contundente: \u00abEn la Argentina el talento de las mujeres est\u00e1 desaprovechado\u00bb, asegura. Seg\u00fan explica, las mujeres representan el 60% de los graduados universitarios del pa\u00eds y se reciben en menos tiempo y con mejores notas. \u00abEs necesario que accedan al trabajo en las mismas condiciones que los hombres y no solamente por un tema de equidad, sino porque est\u00e1 comprobado que aumenta la productividad de la econom\u00eda -se\u00f1ala-. La evidencia muestra, por ejemplo, que un cuarto del crecimiento de la productividad en Estados Unidos entre 1960 y 2010 se explic\u00f3 por la incorporaci\u00f3n de la mujer al \u00e1mbito laboral\u00bb.<\/p>\n<div class=\"firma\"><\/div>\n<div>Fuente:<a href=\"https:\/\/www.lanacion.com.ar\/economia\/empleos\/el-plan-oficial-mejorar-productividad-del-pais-nid2223689\"> La Naci\u00f3n\u00a0<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo de carrera. Delfina Torres Cabreros\u00a0 Evocar el recuerdo de una maestra o una empleada dom\u00e9stica es un ejercicio mental de lo m\u00e1s sencillo: las hemos visto por todos lados.\u00a0M\u00e1s dif\u00edcil resulta imaginar plomeras, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":33811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":79,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[32],"tags":[34,130,45],"class_list":["post-33798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mujeres","tag-machismo","tag-mujeres","tag-trabajo"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[3],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T18:02:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\"},\"headline\":\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos\",\"datePublished\":\"2019-04-03T18:02:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/\"},\"wordCount\":1230,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/2882944w768.jpg\",\"keywords\":[\"Machismo\",\"Mujeres\",\"Trabajo\"],\"articleSection\":[\"Mujeres\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/\",\"name\":\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/2882944w768.jpg\",\"datePublished\":\"2019-04-03T18:02:06+00:00\",\"description\":\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/2882944w768.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/2882944w768.jpg\",\"width\":768,\"height\":512},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/sofiperez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino","description":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/","og_locale":"es_ES","og_type":"article","og_title":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino","og_description":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo","og_url":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2019-04-03T18:02:06+00:00","og_image":[{"width":768,"height":512,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","type":"image\/jpeg"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f"},"headline":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos","datePublished":"2019-04-03T18:02:06+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/"},"wordCount":1230,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","keywords":["Machismo","Mujeres","Trabajo"],"articleSection":["Mujeres"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/","url":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/","name":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#primaryimage"},"thumbnailUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","datePublished":"2019-04-03T18:02:06+00:00","description":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#primaryimage","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","width":768,"height":512},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/las-mujeres-tienen-menor-participacion-que-los-varones-en-los-empleos-tecnicos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg","rttpg_featured_image_url":{"full":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false],"landscape":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false],"portraits":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false],"thumbnail":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768-150x150.jpg",150,150,true],"medium":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768-300x200.jpg",300,200,true],"large":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false],"1536x1536":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false],"2048x2048":["https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2019\/04\/2882944w768.jpg",768,512,false]},"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/mujeres\/\" rel=\"category tag\">Mujeres<\/a>","rttpg_excerpt":"Las mujeres tienen menor participaci\u00f3n que los varones en los empleos t\u00e9cnicos, con alto contenido tecnol\u00f3gico o con mejores perspectivas de desarrollo de carrera. Delfina Torres Cabreros\u00a0 Evocar el recuerdo de una maestra o una empleada dom\u00e9stica es un ejercicio mental de lo m\u00e1s sencillo: las hemos visto por todos lados.\u00a0M\u00e1s dif\u00edcil resulta imaginar plomeras,&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/33798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=33798"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/33798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media\/33811"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=33798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=33798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=33798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}