{"id":29784,"date":"2018-11-01T18:40:22","date_gmt":"2018-11-01T21:40:22","guid":{"rendered":"http:\/\/diariofemenino.com.ar\/v2\/?p=29740"},"modified":"2018-11-01T18:40:22","modified_gmt":"2018-11-01T21:40:22","slug":"29740-2","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/","title":{"rendered":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d"},"content":{"rendered":"<h3>La activista feminista Analba Braz\u00e3o Teixeira analiza el triunfo de Bolsonaro en Brasil y alerta sobre los riesgos a los que se enfrenta la poblaci\u00f3n.<\/h3>\n<p>El domingo por la noche el Tribunal Supremo Electoral dio a conocer una noticia, no querida por muchos, pero esperada: la dupla de militares retirados Jair Bolsonaro \u2013 Hamilton Mour\u00e3o asumir\u00e1n el pr\u00f3ximo 1 de enero la presidencia y vicepresidencia del Brasil.\u00a0<strong>Los candidatos del Partido Social Liberal (PSL) se impusieron con el 55,13 por ciento de los votos, contra el 44,87 que supieron cosechar sus contrincantes del Partido de los Trabajadores (PT), Fernando Haddad y Manuela D\u00e1vila.<\/strong><br \/>\nA las pocas horas de conocido el triunfo, se difundieron v\u00eda redes sociales videos de personas celebrando con armas en las calles, militares de fajina aplaudidos y ataques a militantes de izquierda.<br \/>\n<strong>Analba Braz\u00e3o Teixeira<\/strong>, educadora del SOS Corpo-Instituto Feminista para la Democracia y militante de la Articulaci\u00f3n de Mujeres Brasile\u00f1as, cuenta en entrevista con\u00a0<em>Nodal<\/em>\u00a0cu\u00e1les son las sensaciones y las lecturas ante este nuevo panorama para los feminismos y los movimientos sociales.<br \/>\n<em>\u2014Tras el triunfo de Bolsonaro se registraron varios hechos de violencia e incluso se difundi\u00f3 un video de una caravana de militares celebrando en las calles. \u00bfEse es el clima que se vive por estas horas en Brasil?<\/em><br \/>\n\u2014El clima estaba ya bastante tenso en las \u00faltimas semanas.\u00a0<strong>Hubo muchas denuncias de situaciones de violencia contra militantes que apostaban por la candidatura de Haddad.<\/strong>\u00a0El s\u00e1bado, antes de la elecci\u00f3n, el hijo de una militante, la secretaria de la Mujer de la Central \u00danica de los Trabajadores, en la ciudad del Estado de Cear\u00e1, fue asesinado por un seguidor de Bolsonaro.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-67028\" src=\"https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-movilizacion-contra-Jair-Bolsonaro-la-tinta.jpg\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" srcset=\"https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-movilizacion-contra-Jair-Bolsonaro-la-tinta.jpg 900w, https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-movilizacion-contra-Jair-Bolsonaro-la-tinta-300x200.jpg 300w, https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-movilizacion-contra-Jair-Bolsonaro-la-tinta-768x512.jpg 768w\" alt=\"Brasil movilizacion contra Jair Bolsonaro la-tinta\" width=\"900\" height=\"600\" \/><br \/>\nEl clima es de mucho miedo, porque ellos est\u00e1n propagando el terror. Por otro lado,<strong>\u00a0los movimientos sociales estamos firmes en la resistencia, no vamos a salir de las calles.<\/strong>\u00a0El miedo no nos va a paralizar. La lucha ser\u00e1 ardua, pero m\u00e1s vamos a salir adelante.<\/p>\n<hr \/>\n<h4><em>Ahora es el momento de repensar estrategias de seguridad. Estamos aconsejando no salir solos con camisetas o prendedores que los identifiquen como de izquierda, de estar juntos, reunidos, abraz\u00e1ndonos, cuid\u00e1ndonos para fortalecernos. No vamos a desistir de la lucha, permaneceremos en la calle.<\/em><\/h4>\n<hr \/>\n<p><strong>Ya hab\u00eda un genocidio de los j\u00f3venes negros, ahora puede aumentar bastante la barbarie. La misoginia, el racismo, la legtfobia fue tambi\u00e9n contenido del discurso del Bolsonaro.<\/strong>\u00a0Los movimientos de mujeres negras, el movimiento feminista, el movimiento de la colectividad LGBTs, el Movimiento sin Tierra, el Movimiento de Trabajadores Sin Techo que estuvieron al frente en esta lucha, van a continuar juntos para combatir el fascismo que se est\u00e1 extendiendo. No nos vamos a contener.<br \/>\n<em>\u2014Bolsonaro tom\u00f3 un discurso m\u00e1s \u201cconciliador\u201d desde la campa\u00f1a para el segundo turno y el domingo por la noche cuando dio su mensaje. \u00bfCu\u00e1l fue la clave para su triunfo? \u00bfPodr\u00e1 contener la violencia cuando asuma como presidente?<\/em><br \/>\n\u2014Ser\u00e1 muy dif\u00edcil contener la violencia, ya que toda su campa\u00f1a se bas\u00f3 en la violencia. Toda su campa\u00f1a estuvo basada en una falsa noci\u00f3n de seguridad, prometiendo armar a la poblaci\u00f3n, prometiendo condecorar a los polic\u00edas que maten durante su servicio a los llamados bandidos, prometiendo prohibir en Brasil los activismos y los movimientos sociales. Se instal\u00f3 un clima de violencia enorme.\u00a0<strong>Sus partidarios ya iniciaron una campa\u00f1a en las universidades para denunciar a los profesores que hablen mal del presidente electo.<\/strong>\u00a0Ser\u00e1 necesario y urgente que los ministros del Supremo Tribunal Federal se posicionen.<br \/>\n<em>\u2014En el norte el PT tuvo una buena elecci\u00f3n, \u00bfpor qu\u00e9, qu\u00e9 diferencias hay con el sur?<\/em><br \/>\n\u2014El Nordeste de Brasil fue el que logr\u00f3 llevar a Haddad a la segunda vuelta, donde la votaci\u00f3n fue m\u00e1s ampliada. El Nordeste es la regi\u00f3n m\u00e1s pobre de Brasil y durante el per\u00edodo del PT en el gobierno Brasil logr\u00f3 salir de la l\u00ednea de pobreza. Es la regi\u00f3n que tiene la mayor poblaci\u00f3n negra y las pol\u00edticas de inclusi\u00f3n para estas poblaciones han sido reales. Como la creaci\u00f3n de las universidades en ciudades del interior. Muchos j\u00f3venes que no ten\u00edan acceso entraron en la universidad. Programas como Bolsa Familiar o Luz para Todos benefici\u00f3 al pueblo nordestino. Tambi\u00e9n la poblaci\u00f3n del Sur y Sudeste se han beneficiado, pero no le dan reconocimiento.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-66920\" src=\"https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-Bolsonaro-fascismo-la-tinta.jpg\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" srcset=\"https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-Bolsonaro-fascismo-la-tinta.jpg 900w, https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-Bolsonaro-fascismo-la-tinta-300x169.jpg 300w, https:\/\/latinta.com.ar\/wp-content\/uploads\/2018\/10\/Brasil-Bolsonaro-fascismo-la-tinta-768x432.jpg 768w\" alt=\"Brasil Bolsonaro fascismo la-tinta\" width=\"900\" height=\"506\" \/><br \/>\n<em>\u2014Los movimientos feministas, de mujeres y LGBTI+ han tenido un rol muy importante en esta elecci\u00f3n. \u00bfCu\u00e1l es su lectura al respecto? \u00bfC\u00f3mo ser\u00e1 su organizaci\u00f3n de ahora en adelante?<\/em><br \/>\n\u2014El movimiento feminista brasile\u00f1o demostr\u00f3 que nuestra fuerza pol\u00edtica crece. Salimos miles de mujeres a las calles de Brasil en lucha contra el \u201ccoso\u201d\u00a0<em>(N de R: forma en la que llaman a Bolsonaro)<\/em>\u00a0durante el #Elen\u00e3o. Y fue en ese momento que conseguimos desenmascarar el car\u00e1cter fascista de Bolsonaro y de sus seguidores. Fuimos las mujeres las que impulsamos la segunda vuelta. Siempre en las calles, desde el golpe mis\u00f3gino que recibi\u00f3 la ex presidenta Dilma Rousseff. En ese momento, fue a favor de la democracia, y en estos \u00faltimos meses contra el fascismo, que s\u00f3lo ha crecido. Somos las mujeres las que estamos al frente de estas luchas, llevando nuestra manera de hacer y ser feminista. Y es junto con los movimientos de mujeres negras, ind\u00edgenas, quilombolas, LGBTs, entre otros.\u00a0<strong>Nuestra fuerza es nuestra resistencia. Y en estas tres semanas de campa\u00f1a para la segunda vuelta nuestra fuerza y \u200b\u200bcreatividad sumaron a la resistencia.<\/strong>\u00a0Tomamos libros para votar en lugar de armas, por ejemplo. Ese es el mensaje de amor que continuaremos emanando.<br \/>\nAhora tenemos que pensar mucho sobre nuestra seguridad. El riesgo es real, para unas m\u00e1s que para otras. Las mujeres negras, los j\u00f3venes negros, los LGBTs, la poblaci\u00f3n de la periferia est\u00e1 en riesgo. Lo importante ahora es protegernos, organizarnos con seguridad y no desistir de la lucha. Es hora de calmar el coraz\u00f3n, reunirnos, estar juntos y juntar todo lo que acumulamos en este per\u00edodo para ampliar, para traer a m\u00e1s gente a la lucha. Nosotras, las feministas, continuaremos apostando. Nuestro nombre es resistencia y nuestro lugar est\u00e1 en la calle.<br \/>\n&nbsp;<br \/>\n<strong>Por Carla Perell\u00f3 para\u00a0<a href=\"https:\/\/www.nodal.am\/2018\/10\/triunfo-de-bolsonaro-analba-brazao-teixeira-educadora-y-militante-feminista-estamos-firmes-en-la-resistencia\/\" target=\"_blank\" rel=\"noopener\">Nodal<\/a><\/strong><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La activista feminista Analba Braz\u00e3o Teixeira analiza el triunfo de Bolsonaro en Brasil y alerta sobre los riesgos a los que se enfrenta la poblaci\u00f3n. El domingo por la noche el Tribunal Supremo Electoral dio a conocer una noticia, no querida por muchos, pero esperada: la dupla de militares retirados Jair Bolsonaro \u2013 Hamilton Mour\u00e3o [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":29741,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":5,"footnotes":""},"categories":[8],"tags":[53,26],"class_list":["post-29784","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas","tag-derechos-de-las-mujeres","tag-feminismo"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/29740-2\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"La activista feminista Analba Braz\u00e3o Teixeira analiza el triunfo de Bolsonaro en Brasil y alerta sobre los riesgos a los que se enfrenta la poblaci\u00f3n. El domingo por la noche el Tribunal Supremo Electoral dio a conocer una noticia, no querida por muchos, pero esperada: la dupla de militares retirados Jair Bolsonaro \u2013 Hamilton Mour\u00e3o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/29740-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-01T21:40:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\"},\"headline\":\"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d\",\"datePublished\":\"2018-11-01T21:40:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/\"},\"wordCount\":1085,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"keywords\":[\"Derechos de las mujeres\",\"Feminismo\"],\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/\",\"name\":\"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2018-11-01T21:40:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/29740-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/1c36bc3bf394d8ec320814298b4fdd3f\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/sofiperez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/","og_locale":"es_ES","og_type":"article","og_title":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino","og_description":"La activista feminista Analba Braz\u00e3o Teixeira analiza el triunfo de Bolsonaro en Brasil y alerta sobre los riesgos a los que se enfrenta la poblaci\u00f3n. El domingo por la noche el Tribunal Supremo Electoral dio a conocer una noticia, no querida por muchos, pero esperada: la dupla de militares retirados Jair Bolsonaro \u2013 Hamilton Mour\u00e3o [&hellip;]","og_url":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2018-11-01T21:40:22+00:00","og_image":[{"width":855,"height":319,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f"},"headline":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d","datePublished":"2018-11-01T21:40:22+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/"},"wordCount":1085,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#primaryimage"},"thumbnailUrl":"","keywords":["Derechos de las mujeres","Feminismo"],"articleSection":["Entrevistas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/","url":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/","name":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#primaryimage"},"thumbnailUrl":"","datePublished":"2018-11-01T21:40:22+00:00","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/29740-2\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/29740-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Feministas de Brasil: \u201cNuestro nombre es resistencia y nuestro lugar es la calle\u201d"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/1c36bc3bf394d8ec320814298b4fdd3f","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/sofiperez\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/entrevistas\/\" rel=\"category tag\">Entrevistas<\/a>","rttpg_excerpt":"La activista feminista Analba Braz\u00e3o Teixeira analiza el triunfo de Bolsonaro en Brasil y alerta sobre los riesgos a los que se enfrenta la poblaci\u00f3n. El domingo por la noche el Tribunal Supremo Electoral dio a conocer una noticia, no querida por muchos, pero esperada: la dupla de militares retirados Jair Bolsonaro \u2013 Hamilton Mour\u00e3o&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/29784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=29784"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/29784\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=29784"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=29784"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=29784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}