{"id":2002,"date":"2012-06-16T14:00:16","date_gmt":"2012-06-16T17:00:16","guid":{"rendered":"http:\/\/www.diariofemenino.com.ar\/?p=2002"},"modified":"2012-06-16T14:00:16","modified_gmt":"2012-06-16T17:00:16","slug":"escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/","title":{"rendered":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\nPor Luciana Peker<br \/>\n<em>La Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero junt\u00f3 el saber de muchas feministas acad\u00e9micas para llegar a mujeres de actividad barrial, pueblos originarios, j\u00f3venes, migrantes, sobrevivientes de la dictadura y, espec\u00edficamente, a l\u00edderes de sectores populares. La idea de capacitar a aquellas que no pudieron estudiar o que necesitaban m\u00e1s formaci\u00f3n para replicar en su militancia y vida personal tiene su primer grupo de egresadas con un t\u00edtulo formal a trav\u00e9s de un convenio con la UBA. Buscan respaldo y van por m\u00e1s.<\/em><\/p>\n<div>\n\u201cEn la Amazonia era privilegio de pocas estudiar. Yo no tuve la oportunidad de seguir despu\u00e9s de la secundaria. Era muy dif\u00edcil llegar a la universidad\u201d, relata Nazar\u00e9t de Castro Soares, que de la selva brasile\u00f1a lleg\u00f3 a la Argentina y ac\u00e1 es una de las flamantes graduadas universitarias en g\u00e9nero. Su historia no es la \u00fanica.<br \/>\nUna de ellas naci\u00f3 en La Matanza. Otra en Brasil y otra en Bolivia. Una y m\u00e1s de una militaron en los setenta. Dos se casaron. Una fue candidata a intendenta del conurbano. Una estudi\u00f3 psicolog\u00eda y otra abogac\u00eda. Todas son militantes feministas, pero les faltaba el acceso a una teor\u00eda feminista, a las herramientas de un saber complejo y que tiene toda una historia.<br \/>\nPor eso, Dinora Gebennini, Susana Gamba, Ana Gonz\u00e1lez, Mabel Gabarra, Nina Brugo (que adem\u00e1s don\u00f3 el espacio de su estudio para vislumbrar las clases) formaron el consejo directivo de la Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero, por el que pasaron ya m\u00e1s de cien alumnas. El proyecto estuvo dirigido, especialmente, a capacitar a mujeres de sectores populares y otorgando un diploma \u2013de especializaci\u00f3n en t\u00e9cnica en promoci\u00f3n sociopol\u00edtica de g\u00e9nero\u2013 a trav\u00e9s de la Secretar\u00eda de Extensi\u00f3n de la Facultad de Ciencias Sociales de la UBA.<br \/>\nEn ese marco de educaci\u00f3n popular, con perspectiva intercultural, estuvieron remando todas, incluida Zuni Rold\u00e1n, que tiene 80 a\u00f1os y fue colaboradora o alma mater de la organizaci\u00f3n. El proyecto tuvo el respaldo de un amplio arco del feminismo. La directora acad\u00e9mica fue Dora Barrancos, una maestra clave para convertir las buenas intenciones en una cosa seria. El consejo asesor estuvo coordinado por Blanca Ibarluc\u00eda y conformado por Olga Hammar, Dolores Fenoy, Monique Altschul, Mar\u00eda Elena Naddeo, entre muchas otras. Tambi\u00e9n tuvo el respaldo profesional de Eva Giberti, Nelly Minyersky, M\u00f3nica Tarducci (que adem\u00e1s fue docente), Irene Meler y Mabel Burin.<br \/>\nLas clases se dictaron los s\u00e1bados en la sede del CBC de Barracas con la intenci\u00f3n de ligar a sindicalistas, feministas, mujeres de pueblos originarios sin tantas lecturas pero con mucho que ense\u00f1ar y tambi\u00e9n formarse para poder replicar la perspectiva de g\u00e9nero en sus comunidades. La mayor\u00eda de las alumnas fueron becadas a pesar de que la cuota m\u00e1s alta era de una suma que no superaba los 130 pesos y que s\u00f3lo abon\u00f3 el 10 por ciento de las alumnas. Sin embargo, el \u00fanico apoyo que recibieron \u2013entre los muchos que buscaron\u2013 vino de ONU Mujer \u2013para la parte inicial\u2013 y de Nelly Minyersky, Dolores Fenoy y Laura Garc\u00eda Tu\u00f1\u00f3n, que le pagaron los estudios a una alumna cada una. Todas las docentes trabajaron gratis. Y muchas de las organizadoras pusieron plata de su bolsillo para que la iniciativa terminara con una camada de egresadas.<br \/>\nTodas quisieron unir el saber popular con el saber acad\u00e9mico. Y este a\u00f1o se festej\u00f3 la primera camada de egresadas. Ahora, el proyecto se encuentra en una impasse, para tomar fuerzas y sumar respaldos. No hay estudiantes en el 2012, porque este a\u00f1o lo van a dedicar a buscar ayudas para la organizaci\u00f3n y las becas. En el 2013 otra nueva camada volver\u00e1 a estudiar. Pero la historia de esta historia empieza con la marca de una generaci\u00f3n setentista. \u201cLas que iniciamos esta experiencia fuimos compa\u00f1eras en la d\u00e9cada del 70 y quisimos sintetizar lo te\u00f3rico con lo pr\u00e1ctico en un feminismo latinoamericano, popular y pluralista\u201d, sintetiza la antrop\u00f3loga Ana Gonz\u00e1lez, integrante de la comisi\u00f3n directiva y de la Red de Mujeres de Zona Sur.<br \/>\nLa presidenta de la Fundaci\u00f3n Agenda de las Mujeres, Susana Gamba, es una de las organizadoras de la escuela. Ella logra tomar y dar la palabra y, a su turno, en una entrevista masiva de Las\/12, con quince integrantes que ocuparon distintos lugares en la experiencia, retoma el lazo de sus propias historias: \u201cDos a\u00f1os antes de empezar con la escuela nos pusimos a trabajar y decidimos retomar la corriente 8 de Marzo, que surge a fines de los \u201980 en los Encuentros Nacionales de Mujeres, que era una corriente nacional en donde conflu\u00edamos diferentes compa\u00f1eras\u201d.<br \/>\nPero de tantas ganas de hablar y tantas que hablan Susana pierde la letra. Ah\u00ed es donde el humor mete la lengua y afianza la confianza.<br \/>\n\u2013As\u00ed fue como perdiste la virginidad \u2013le dicen. Y todas comparten la risa.<br \/>\nPero ella retoma la voz de dar m\u00e1s saber a las voces de los barrios: \u201cLa idea fue una escuela destinada a l\u00edderes sociales que no hubieran tenido formaci\u00f3n acad\u00e9mica con un cupo de universitarias que no pasara del treinta por ciento. Quer\u00edamos hacer educaci\u00f3n popular y no un posgrado acad\u00e9mico. Las mujeres que pueden reproducir esta experiencia son de sectores populares\u201d.<\/p>\n<h3>Un balde de agua caliente<\/h3>\n<p>\u201cConoc\u00ed m\u00e1s a mi pa\u00eds desde el punto de vista de las oprimidas\u201d, rescata sobre el punto de vista latinoamericano de la Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero Nazar\u00e9t de Castro Soares, que vive hace once a\u00f1os en La Matanza y fue una militante cristiana (\u201cdonde si dec\u00edas que eras feminista te quitaban la palabra\u201d, subraya), del Partido de los Trabajadores (PT) y de la Pastoral de la Mujer. Ella no les teme a las dificultades. S\u00f3lo hace falta contar que pis\u00f3 suelo argentino en el 2001 justo cuando se iban todos. Pero ten\u00eda sus resquemores con el feminismo o con algunas feministas que m\u00e1s que atraer la expulsaban. Sin embargo, tal vez por la perspectiva de la inclusi\u00f3n, ella hoy se considera feminista. \u201cPero considero que hay que enamorar, por eso hay que ir de a poquito\u201d, dice con su remera violeta y su collar con semillas de colores que se agitan como si sambara. Con los pies apenas levantados del piso, apenas apoyados, pero haciendo un terremoto con el cuerpo y desde el cuerpo. Una visi\u00f3n danzada de la igualdad a partir de la diferencia. Una visi\u00f3n en donde se puede danzar conjuntamente. Su fe tambi\u00e9n es otra muestra de pluralidad. Ni ella dej\u00f3 de creer, ni creer le ceg\u00f3 la vista a la inequidad. \u201cPor ser cristianas no estamos en contra de la despenalizaci\u00f3n del aborto\u201d, remarca.<br \/>\nNelly Borquez, igual que Nazar\u00e9t, es militante cristiana e integra la Red de Mujeres de La Matanza. Tambi\u00e9n fue coordinadora de talleres de la Escuela de Capacitaci\u00f3n. Rescata el valor de las mujeres que pisan la vereda y la tierra siempre que es necesario. \u201cEl gran crecimiento de los Encuentros Nacionales de Mujeres se debe a los sectores populares que tambi\u00e9n quer\u00edamos ba\u00f1arnos con agua caliente y tener asfalto\u201d, remarca. La pol\u00edtica tiene que ver con la vida cotidiana y la vida cotidiana es pol\u00edtica. Y sin agua caliente la teor\u00eda se evapora por ineficaz, pero sin teor\u00eda la lucha por el agua caliente tambi\u00e9n es m\u00e1s ardua. \u201cLas feministas ten\u00edan la teor\u00eda y nosotras las pr\u00e1cticas. Las organizaciones de base necesitaban formaci\u00f3n y las feministas un ba\u00f1o de realidad\u201d, resume Nelly. Sin embargo, era mala palabra en sus barrios porque era sin\u00f3nimo de lesbianas, abortistas y anti hombres, que tambi\u00e9n eran malas palabras. Pero, en el 2000, se autonombraron. \u201cEramos m\u00e1s feministas de lo que cre\u00edamos\u201d, reflexiona.<br \/>\nDaniela Godoy, en cambio, era una de las pocas estudiantes que ya hab\u00eda estudiado en Filosof\u00eda y Letras de la UBA. Pero ella diferencia: \u201cNo se puede comparar con la facultad, all\u00e1 hay m\u00e1s ego\u00edsmo\u201d. Pero tambi\u00e9n devela como militante del Frente de Mujeres K: \u201cMuchas discutimos, nos enojamos y tuvimos que aprender a manejar las diferencias. Hubo mucha tensi\u00f3n en los momentos pol\u00edticos pero todas queremos que este espacio siga\u201d. \u201cEs que no somos \u00e1ngeles, somos brujas\u201d, se suma Nina Brugo, que no puede esperar su turno para poner en orden la reivindicaci\u00f3n de las brujildas o de las diferencias m\u00e1s pol\u00edticamente correctas. Ella es parte de la comisi\u00f3n directiva y de la conducci\u00f3n del partido Buenos Aires para Todos (del FAP). Pero se define como una sobreviviente de la dictadura. Por eso, no pretende homogeneidad sino convivencia en la diferencia. \u201cSe dieron contradicciones pero eso es positivo para un feminismo que luche por una sociedad mejor\u201d, valoriza.<br \/>\nZulema Montero es abogada, militante de derechos humanos y representante de la Asociaci\u00f3n Civil \u201cAyud\u00e9monos\u201d de la comunidad boliviana en Argentina. Ella tambi\u00e9n estudi\u00f3. Pero estudiar derecho fue el principio de su lucha. \u201cDesde que fui ni\u00f1a vi el machismo y el sistema neoliberal en Bolivia, pero siempre para las mujeres y los ni\u00f1os era peor. Mi padre no era tan rico, pero trabajaba en el Registro Civil y por eso se hac\u00eda llamar doctor y maltrataba a la gente\u201d, retrata. \u201cHija, \u00bfc\u00f3mo vas a ser abogada?\u201d, le dijo a Zulema a su pap\u00e1, obstinado en que estudiara auditor\u00eda, un tr\u00e1mite r\u00e1pido antes de casarse y tener hijos. \u201cYo no pod\u00eda estudiar derecho por ser mujer\u201d, recuerda la prohibici\u00f3n, pero se recibi\u00f3 de abogada a los 23 a\u00f1os y lleg\u00f3 a ser jueza. Reconoce que fue por casualidad. Ser mujer le sirvi\u00f3 porque supon\u00edan que, a diferencia de otros magistrados, ella no iba a tomar en el pueblo de San Lucas, departamento de Chuquisaca, donde se produce el vino boliviano. \u201cToda mi vida estuvo relacionada con cuestiones de g\u00e9nero. Pero con la Escuela de Capacitaci\u00f3n reci\u00e9n me di cuenta. All\u00ed, cuando fui jueza, hab\u00eda muchas violaciones que nadie persegu\u00eda hasta que llegu\u00e9 yo\u201d, dice y recuerda que cuando ya sent\u00eda que hab\u00eda podido ser lo que quer\u00eda, su marido se recibi\u00f3 de m\u00e9dico y volvi\u00f3 a querer decidir por ella que dejara de ser jueza y se dedicara a su casa y a los tres hijos que ya ten\u00eda. \u201cEso me choc\u00f3 mucho. Me sent\u00ed muy mal de ser s\u00f3lo ama de casa\u201d, hilvana en un relato que es personal, singular, colectivo y pol\u00edtico.<br \/>\n\u201cYo dije: esto no acaba, e hice un estudio r\u00fastico en mi casa. No recib\u00eda un peso de ganancia sino arroz y fideos, pero trabajaba igual\u201d, se enorgullece. A Buenos Aires lleg\u00f3 hace diez a\u00f1os. Su marido no s\u00f3lo quiso robarle su profesi\u00f3n, tambi\u00e9n le rob\u00f3 a su hijo. Y ella vino para recuperarlo. \u201cMi vida siempre fue as\u00ed: sin darme cuenta estuve buscando la igualdad de derechos de la mujer, trabajando en nuestra visibilizaci\u00f3n\u201d, dice.<br \/>\nIsabel Burgos naci\u00f3 en Chile. Es psic\u00f3loga y fue coordinadora y docente. Se define como feminista pero parte de un feminismo latinoamericano e inclusivo para las migrantes. Las mujeres no nos callamos cuando nos juntamos. El bullicio es parte de nuestra sonoridad. Pero Silvia Noguera introduce otra palabra: sororidad (hermanarse como estrategia pol\u00edtica). Y esa sororidad es la que se hace o\u00edr. \u201cFue una articulaci\u00f3n bell\u00edsima reconocer al feminismo como una manera de reflejar necesidades cotidianas y de instalar el feminismo en el campo popular\u201d, rescata ella, que milita en Entramando, de zona sur.<br \/>\nLa palabra militancia es la que define la vida de Elsa Mura, autodefinida militante de toda la vida, y toda la vida son setenta y siete a\u00f1os, obrera del vestido o de la metalurgia, pero obrera y detenida tres veces, la \u00faltima durante un consejo de guerra en 1976. Al machismo le conoce la cara desde que eran valoradas en la lucha diaria pero los sindicalistas las callaban en las asambleas. Ella trabaj\u00f3 en soldar piezas peque\u00f1as, como la gran fuerza de las mujeres que algunos ven diminuta pero es fundamental en cualquier lucha. Igual que muchas, elige el plural para hablar de ella. \u201cMi generaci\u00f3n estuvo atravesada por la lucha contra las dictaduras.\u201d Y del nosotros pasa a hablar de ella. \u201cPerd\u00ed toda inocencia en el \u201976\u201d, sentencia. Y de ella vuelve al nosotras en un zigzag personal y colectivo que se le concede en una sintaxis sin trabas. \u201cLas mujeres aprendimos a defendernos a nosotras mismas: a enfrentar la burocracia y a la dictadura\u201d, remarca.<\/p>\n<h3>Deudas pendientes<\/h3>\n<p>Tambi\u00e9n remarca una autocr\u00edtica o, m\u00e1s vale, una deuda: \u201cEl feminismo se ocup\u00f3 siempre de los sectores m\u00e1s vulnerables, pero no logr\u00f3 acercarse a ellos\u201d. Por eso, tal vez, igual que los masivos Encuentros de Mujeres \u2013al que ella asisti\u00f3 al primero, en el Centro Cultural General San Mart\u00edn, de la Ciudad de Buenos Aires, en 1986\u2013 la Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero sea una propuesta para sacar de la c\u00e1psula de las tesis doctorales y llevar a los adoquines o las casitas sin espacio para caminar casi de costado la dignidad de las mujeres que miran de frente.<br \/>\nElsa misma es parte de la historia argentina. Sin embargo, la lectura de esa historia es una de las fuentes que m\u00e1s revaloriza de esta travesura por el conocimiento. \u201cCreo que rever la historia nacional me hizo ver cosas que se me escapaban. Est\u00e1bamos tan ocupadas militando que no ve\u00edamos la dimensi\u00f3n del cuento chino que fue la historia que nos contaron\u201d, revela en un saber que se multiplic\u00f3. Pero que viene de lejos.<br \/>\n\u201cAprend\u00ed mucho en la c\u00e1rcel por la gran cantidad de docentes \u2013destaca\u2013, pero tambi\u00e9n en esta escuela por la gran cantidad de herramientas valiosas para enfrentar al patriarcado.\u201d<br \/>\nPero durante el proceso de la Escuela se abrieron nuevas puertas. Dos alumnas \u2013Mar\u00eda Alejandra Beltr\u00e1n y Viviana Caijao\u2013 se casaron durante la cursada y se convirtieron en el primer matrimonio de dos mujeres en Glew (y con todas las chicas atr\u00e1s Mar\u00eda pidi\u00f3 en el juzgado que bajaran el rosario que hab\u00eda en la pared). Todas las acompa\u00f1aron en una despedida de solteras que se transform\u00f3 en marcha y, c\u00f3mo no, en el festejo por la amplitud de derechos. \u201cNuestro matrimonio fue un acto pol\u00edtico\u201d, dice orgullosa, y cuenta que se pelearon contra la Iglesia pero no contra las creyentes que, como cuenta esta nota, eran sus compa\u00f1eras y no las mujeres de la vereda de enfrente. Dice y define: \u201cMe gusta viajar de todas las maneras, y \u00e9ste fue un viaje intelectual\u201d.<br \/>\nLa m\u00e1s chica de todas es Silvana Scali, de 24 a\u00f1os, aunque no se siente una joven tradicional que posa para Facebook sino una estudiante de Trabajo Social que se cri\u00f3 con una mente abierta y siente que en la facultad falta mucha perspectiva de g\u00e9nero. \u201cSe habla mucho de romper las estructuras, pero no de la estructura patriarcal\u201d, delinea.<br \/>\nLa experiencia tambi\u00e9n empoder\u00f3 a Karolina Bobadilla a presentarse como candidata a intendenta (por Nuevo Encuentro) de Jos\u00e9 C. Paz despu\u00e9s de ser piquetera y dejar de serlo, \u201cporque quedaban relegadas nuestras reivindicaciones y s\u00f3lo pod\u00edamos decidir qu\u00e9 le pon\u00edamos al guiso\u201d. Y desentra\u00f1a la lucha puertas adentro de la pol\u00edtica: \u201cLos varones hablan de revoluci\u00f3n pero cuando llegan a su casa marcan tarjeta, no hacen la revoluci\u00f3n\u201d.<br \/>\n\u201cLa escuela gener\u00f3 un sentido de pertenencia muy grande y dio un salto en la idea de una educaci\u00f3n para ricos y pobres. El aprendizaje fue un antes y despu\u00e9s para todas\u201d, valoriza Elsa Schvartzman, docente e integrante del Foro por los Derechos Reproductivos. Susana Gamba cuenta que no quieren terminar en una camada. Con el prendedor en el pecho del logo multicolor \u2013de la interculturalidad, los pueblos originarios y la diversidad\u2013 y la forma de un libro abierto que define a la escuela, ella se esperanza: \u201cLa idea es ver c\u00f3mo se sostiene para relanzarla en el 2013\u201d. El objetivo lo describe la ex alumna Mar\u00eda Alejandra Beltr\u00e1n: \u201cAhora quiero intentar transformar a otras personas como la escuela me transform\u00f3 a m\u00ed\u201d.<br \/>\nM\u00e1s informaci\u00f3n:<br \/>\n<a title=\"\" href=\"http:\/\/www.calandolapiedra.com\/\">http:\/\/www.calandolapiedra.com<\/a><br \/>\nFuente:\u00a0 <a href=\"http:\/\/www.pagina12.com.ar\/diario\/suplementos\/las12\/13-7313-2012-06-16.htmlhttp:\/\/\" target=\"_blank\">P\u00e1gina 12 <\/a><br \/>\n&nbsp;\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Por Luciana Peker La Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero junt\u00f3 el saber de muchas feministas acad\u00e9micas para llegar a mujeres de actividad barrial, pueblos originarios, j\u00f3venes, migrantes, sobrevivientes de la dictadura y, espec\u00edficamente, a l\u00edderes de sectores populares. La idea de capacitar a aquellas que no pudieron estudiar o que necesitaban m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":22,"footnotes":""},"categories":[4,6],"tags":[],"class_list":["post-2002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medios","category-articulos"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; Por Luciana Peker La Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero junt\u00f3 el saber de muchas feministas acad\u00e9micas para llegar a mujeres de actividad barrial, pueblos originarios, j\u00f3venes, migrantes, sobrevivientes de la dictadura y, espec\u00edficamente, a l\u00edderes de sectores populares. La idea de capacitar a aquellas que no pudieron estudiar o que necesitaban m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-16T17:00:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\"},\"headline\":\"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo\",\"datePublished\":\"2012-06-16T17:00:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/\"},\"wordCount\":2853,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Medios\",\"Mujeres en Palabras\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/\",\"name\":\"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2012-06-16T17:00:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/adm18df\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/","og_locale":"es_ES","og_type":"article","og_title":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino","og_description":"&nbsp; &nbsp; Por Luciana Peker La Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero junt\u00f3 el saber de muchas feministas acad\u00e9micas para llegar a mujeres de actividad barrial, pueblos originarios, j\u00f3venes, migrantes, sobrevivientes de la dictadura y, espec\u00edficamente, a l\u00edderes de sectores populares. La idea de capacitar a aquellas que no pudieron estudiar o que necesitaban m\u00e1s [&hellip;]","og_url":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2012-06-16T17:00:16+00:00","og_image":[{"width":855,"height":319,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6"},"headline":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo","datePublished":"2012-06-16T17:00:16+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/"},"wordCount":2853,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#primaryimage"},"thumbnailUrl":"","articleSection":["Medios","Mujeres en Palabras"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/","url":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/","name":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#primaryimage"},"thumbnailUrl":"","datePublished":"2012-06-16T17:00:16+00:00","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/escuela-sociopolitica-de-genero-un-punto-de-encuentro-entre-el-feminismo-academico-y-las-mujeres-del-pueblo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Escuela Sociopol\u00edtica de G\u00e9nero. Un punto de encuentro entre el feminismo acad\u00e9mico y las mujeres del pueblo"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/medios\/\" rel=\"category tag\">Medios<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/articulos\/\" rel=\"category tag\">Mujeres en Palabras<\/a>","rttpg_excerpt":"&nbsp; &nbsp; Por Luciana Peker La Escuela de Capacitaci\u00f3n Sociopol\u00edtica de G\u00e9nero junt\u00f3 el saber de muchas feministas acad\u00e9micas para llegar a mujeres de actividad barrial, pueblos originarios, j\u00f3venes, migrantes, sobrevivientes de la dictadura y, espec\u00edficamente, a l\u00edderes de sectores populares. La idea de capacitar a aquellas que no pudieron estudiar o que necesitaban m\u00e1s&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/2002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=2002"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/2002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=2002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=2002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=2002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}