{"id":18559,"date":"2015-07-01T11:23:25","date_gmt":"2015-07-01T14:23:25","guid":{"rendered":"http:\/\/www.diariofemenino.com.ar\/?p=18559"},"modified":"2015-07-01T11:23:25","modified_gmt":"2015-07-01T14:23:25","slug":"jornadas-federales-sobre-violencia-contra-las-mujeres","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/","title":{"rendered":"Jornadas Federales sobre Violencia contra las Mujeres"},"content":{"rendered":"<p><span style=\"color: #000000;\"><em><strong>Docentes y estudiantes de tres instituciones educativas de la provincia de La Pampa, que trabajaron en experiencias concretas de Educaci\u00f3n Sexual Integral, participaron en las Jornadas Federales sobre Violencia contra las Mujeres.<\/strong><\/em><\/span><br \/>\n<figure id=\"attachment_18560\" aria-describedby=\"caption-attachment-18560\" style=\"width: 585px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-18560 \" alt=\"Jornadas Federales sobre Violencia contra las Mujeres\" src=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\" width=\"585\" height=\"351\" \/><\/a><figcaption id=\"caption-attachment-18560\" class=\"wp-caption-text\">Jornadas Federales sobre Violencia contra las Mujeres<\/figcaption><\/figure><br \/>\n<span style=\"color: #000000;\">Las propuestas escolares que representaron a nuestra Provincia fueron: \u201cLa violencia de g\u00e9nero como problem\u00e1tica actual\u201d, una investigaci\u00f3n para la concientizaci\u00f3n de la violencia de g\u00e9nero, organizada por estudiantes y docentes de la Escuela N\u00b0 6 de la ciudad de Santa Rosa, perteneciente a la modalidad de Educaci\u00f3n Permanente de J\u00f3venes y Adultos. El proyecto \u201cTodos somos iguales y diferentes a la vez\u201d de la Escuela Agrot\u00e9cnica de Guatrach\u00e9. Y el proyecto interdisciplinario y de socializaci\u00f3n con la comunidad sobre el rol de la mujer en la sociedad, \u201cEstereotipos y Violencia hacia la Mujer\u201d, del Colegio Secundario Dr. Ren\u00e9 Favaloro de la localidad de Ataliva Roca.<\/span><br \/>\n<span style=\"color: #000000;\">La delegaci\u00f3n estuvo acompa\u00f1ada por equipos t\u00e9cnicos del Ministerio de Cultura y Educaci\u00f3n.<\/span><br \/>\n<span style=\"color: #000000;\">Las Jornadas Federales \u201cLa violencia contra las mujeres: las escuelas como escenarios de protecci\u00f3n de derechos\u201d, fueron organizadas por el Programa Nacional de Educaci\u00f3n Sexual Integral, e impulsado por la Subsecretar\u00eda de Equidad y Calidad Educativa del Ministerio de Educaci\u00f3n de la Naci\u00f3n.<\/span><br \/>\n<span style=\"color: #000000;\">El objetivo principal del encuentro apunto a visibilizar, fortalecer y multiplicar las acciones que las escuelas desarrollan en el marco de la implementaci\u00f3n de la Educaci\u00f3n Sexual Integral, para promover la equidad de g\u00e9nero y trabajar acerca de los v\u00ednculos violentos en parejas adolescentes; adem\u00e1s del intercambio entre docentes, estudiantes y equipos de las jurisdicciones del pa\u00eds, difundiendo las pol\u00edticas p\u00fablicas que se desarrollan en relaci\u00f3n a la violencia de g\u00e9nero.<\/span><br \/>\n<span style=\"color: #000000;\">La apertura estuvo a cargo del ministro de Educaci\u00f3n de la Naci\u00f3n, Alberto Sileoni, del secretario de Educaci\u00f3n de la Naci\u00f3n, Jaime Perczyk y de la presidenta del Consejo Nacional de las Mujeres del Ministerio de Desarrollo Social, Mariana Grass.<\/span><br \/>\n<span style=\"color: #000000;\">\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Docentes y estudiantes de tres instituciones educativas de la provincia de La Pampa, que trabajaron en experiencias concretas de Educaci\u00f3n Sexual Integral, participaron en las Jornadas Federales sobre Violencia contra las Mujeres. Las propuestas escolares que representaron a nuestra Provincia fueron: \u201cLa violencia de g\u00e9nero como problem\u00e1tica actual\u201d, una investigaci\u00f3n para la concientizaci\u00f3n de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":5,"footnotes":""},"categories":[9,4,13,580],"tags":[11,12,37,16],"class_list":["post-18559","post","type-post","status-publish","format-standard","hentry","category-de-esi-si-se-habla","category-medios","category-mujeres-sindicalistas","category-resistencia-verdevioleta","tag-educacion","tag-infancia-y-adolescencia","tag-juventud","tag-violencia-de-genero"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino<\/title>\n<meta name=\"description\" content=\"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-07-01T14:23:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\"},\"headline\":\"Jornadas Federales sobre Violencia contra las Mujeres\",\"datePublished\":\"2015-07-01T14:23:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/\"},\"wordCount\":358,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\",\"keywords\":[\"Educaci\u00f3n\",\"Infancia y Adolescencia\",\"Juventud\",\"Violencia de g\u00e9nero\"],\"articleSection\":[\"De ESI S\u00ed Se Habla\",\"Medios\",\"Mujeres Sindicalistas\",\"Resistencia VerdeVioleta\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/\",\"name\":\"Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\",\"datePublished\":\"2015-07-01T14:23:25+00:00\",\"description\":\"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\",\"contentUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/jornadas-federales-sobre-violencia-contra-las-mujeres\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jornadas Federales sobre Violencia contra las Mujeres\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/adm18df\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino","description":"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/","og_locale":"es_ES","og_type":"article","og_title":"Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino","og_description":"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.","og_url":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2015-07-01T14:23:25+00:00","og_image":[{"url":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6"},"headline":"Jornadas Federales sobre Violencia contra las Mujeres","datePublished":"2015-07-01T14:23:25+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/"},"wordCount":358,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#primaryimage"},"thumbnailUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg","keywords":["Educaci\u00f3n","Infancia y Adolescencia","Juventud","Violencia de g\u00e9nero"],"articleSection":["De ESI S\u00ed Se Habla","Medios","Mujeres Sindicalistas","Resistencia VerdeVioleta"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/","url":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/","name":"Jornadas Federales sobre Violencia contra las Mujeres - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#primaryimage"},"thumbnailUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg","datePublished":"2015-07-01T14:23:25+00:00","description":"Jornadas Federales sobre Violencia contra las Mujeres, participaron alumnos y alumnas de tres colegios de la provincia de La Pampa.","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#primaryimage","url":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg","contentUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/jornadas-federales-sobre-violencia-contra-las-mujeres.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/jornadas-federales-sobre-violencia-contra-las-mujeres\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Jornadas Federales sobre Violencia contra las Mujeres"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/de-esi-si-se-habla\/\" rel=\"category tag\">De ESI S\u00ed Se Habla<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/medios\/\" rel=\"category tag\">Medios<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/mujeres-sindicalistas\/\" rel=\"category tag\">Mujeres Sindicalistas<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/resistencia-verdevioleta\/\" rel=\"category tag\">Resistencia VerdeVioleta<\/a>","rttpg_excerpt":"Docentes y estudiantes de tres instituciones educativas de la provincia de La Pampa, que trabajaron en experiencias concretas de Educaci\u00f3n Sexual Integral, participaron en las Jornadas Federales sobre Violencia contra las Mujeres. Las propuestas escolares que representaron a nuestra Provincia fueron: \u201cLa violencia de g\u00e9nero como problem\u00e1tica actual\u201d, una investigaci\u00f3n para la concientizaci\u00f3n de la&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/18559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=18559"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/18559\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=18559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=18559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=18559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}