{"id":1256,"date":"2012-05-24T12:37:16","date_gmt":"2012-05-24T15:37:16","guid":{"rendered":"http:\/\/www.diariofemenino.com.ar\/?p=1256"},"modified":"2012-05-24T12:37:16","modified_gmt":"2012-05-24T15:37:16","slug":"poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/","title":{"rendered":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o"},"content":{"rendered":"<p>&nbsp;<br \/>\n&nbsp;<br \/>\nLa vicegobernadora <strong>Norma Durango<\/strong> recibi\u00f3 informaci\u00f3n<strong> sobre el n\u00famero creciente de denuncias por abuso sexual y por violencia con la mujer <\/strong>que se reciben diariamente en el Poder Judicial. Por el nuevo C\u00f3digo Procesal Penal, hay 2.000 causas residuales y s\u00f3lo se sacan 150 por a\u00f1o.<br \/>\nDurango recorri\u00f3 la ciudad judicial durante la ma\u00f1ana del mi\u00e9rcoles. En di\u00e1logo con los empleados recogi\u00f3 diversos datos. En un informe de prensa de la C\u00e1mara de Diputados se enumeraron los datos recortados que recibi\u00f3 la vicegobernadora.<br \/>\nEl panorama que se llev\u00f3 la funcionario fue grave, seg\u00fan los datos que trascendieron.El informe detalla las siguientes afirmaciones realizadas por diferentes integrantes de la Justicia:<br \/>\n* \u00abNos preocupa la enorme cantidad de denuncias pro abuso sexual que estamos recibiendo a diario.\u00a0 Las vemos resolviendo y en algunos casos con fuertes penas (en General Pico la semana pasada hubo una condena de 20 a\u00f1os de prisi\u00f3n) para los responsables que, en no pocos casos tienen a las madres como c\u00f3mplices.<br \/>\n* \u00abSon muchas las causas pendientes, luego de la implementaci\u00f3n del nuevo C\u00f3digo Procesal Penal, tenemos alrededor de dos mil causas sin resoluci\u00f3n (las llamadas residuales) y no podemos sacar m\u00e1s de 150 por a\u00f1o al ritmo que estamos siguiendo. Lo bueno es que muchas de estas causas se resuelven con juicios abreviados u otros tipos de resoluciones alternativas.<br \/>\n* \u201cNos preocupa la enorme cantidad de denuncias pro abuso sexual que estamos recibiendo a diario.\u00a0 Las vemos resolviendo y en algunos casos con fuertes penas (en General Pico la semana pasada hubo una condena de 20 a\u00f1os de prisi\u00f3n) para los responsables que, en no pocos casos tienen a las madres como c\u00f3mplices.* \u00abEn los casos de violencia de genero, hay muchos m\u00e1s pedidos de ayuda de los hombres que lo que la gente cree.<br \/>\n* \u00abEn fiscal\u00eda, hace 20 a\u00f1os, se tomaban un par de denuncias al mes, hoy no son menos de diez diarias\u00bb.<br \/>\nAnte todo esto, la vicegobernadora dijo:\u00a0 \u00ab<strong>Aparentemente y por lo que me corroboran los jueces con los que estuvimos hablando hay m\u00e1s denuncias de casos de violencia de g\u00e9nero, aunque no tenemos claro es si hay m\u00e1s violencia.<\/strong> Todos los d\u00edas ingresan una cantidad muy importante de denuncias de este tipo y de abusos sexuales, nos remarcaron que hay muchas, ante lo que desde el poder judicial, yo como mujer y el trabajo en conjunto con la secretar\u00eda de la mujer de la provincia y tantas mujeres y varones, que est\u00e1n trabajando en esta tem\u00e1tica estamos preocupados en ver las l\u00edneas de acciones para que este flagelo sea cada vez menor y no que siga creciendo.\u00bb<br \/>\n<strong>Edificio<\/strong><br \/>\nEn relaci\u00f3n a la Ciudad Judicial, Durango dijo que \u201cme voy muy impactada, no solamente por como est\u00e1n pensados los espacios por la luminosidad que tienen\u00a0 sino tambi\u00e9n por como se han pensado desde el punto de vista judicial, quiero decir los accesos, las posibilidades\u00a0 de capacitaci\u00f3n, las posibilidades de toma de declaraciones a los ni\u00f1os en C\u00e1mara Gesell, creo que es un edificio contempor\u00e1neo en lo arquitect\u00f3nico y moderno desde la resoluci\u00f3n judicial\u00bb.<br \/>\n<strong>En la Unidad de G\u00e9nero<\/strong><br \/>\n<a href=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-1257\" title=\"Vicegob__en_Pol__de_la_Mujer\" src=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg\" alt=\"\" width=\"419\" height=\"265\" \/><\/a><br \/>\nEn la ma\u00f1ana de hoy la vicegobernadora tambi\u00e9n estuvo en la Unidad de G\u00e9nero (conocida como \u00abcomisar\u00eda de la mujer\u00bb) de Santa Rosa donde fue recibida por su responsable, la comisaria Sonia Mart\u00edn.<br \/>\nLa titular de la Unidad de G\u00e9nero dijo que \u00abla cantidad de trabajo que aqu\u00ed tenemos es cada vez m\u00e1s \u00abcomplicada\u00bb porque se va incrementando la cantidad de denuncias y eso se debe a que las mujeres, sabiendo que cuentan con un espacio como \u00e9ste, se animan m\u00e1s a efectuar su denuncia y no hay forma de que los polic\u00edas no le tomen sus denuncias\u00bb.Tambi\u00e9n revel\u00f3 ante la vicegobernadora que \u00abla Unidad de G\u00e9nero de Santa Rosa (que se tom\u00f3 como modelo para la implementaci\u00f3n de una de similares caracter\u00edsticas en General Pico) cuenta con un equipo t\u00e9cnico de cinco asistentes sociales y dos sic\u00f3logos\u00bb y asegur\u00f3 que \u00abtrabajar con la mujer golpeada lleva su tiempo, es algo desgastante\u00bb.La vicegobernadora recorri\u00f3 las instalaciones y puso especial inter\u00e9s al derrotero que en las mismas siguen las mujeres que llegan al lugar con la pretensi\u00f3n de efectuar una denuncia y qued\u00f3 en claro que desde que llegan al lugar hasta que termina con las tramitaciones burocr\u00e1ticas est\u00e1n acompa\u00f1adas por asistentes sociales y\/o sicol\u00f3gos capacitados para afrontar este tipo de situaciones.\u00bb<br \/>\n&nbsp;<br \/>\nFuente. <a href=\"http:\/\/www.eldiariodelapampa.com.ar\/index.php?option=com_content&amp;view=article&amp;id=109610:poder-judicial-hay-2000-causas-penales-pendientes-y-se-resuelven-150-al-ano&amp;catid=61:locales&amp;Itemid=2\">El Diario<br \/>\n<\/a>Foto: Prensa Legislativa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; La vicegobernadora Norma Durango recibi\u00f3 informaci\u00f3n sobre el n\u00famero creciente de denuncias por abuso sexual y por violencia con la mujer que se reciben diariamente en el Poder Judicial. Por el nuevo C\u00f3digo Procesal Penal, hay 2.000 causas residuales y s\u00f3lo se sacan 150 por a\u00f1o. Durango recorri\u00f3 la ciudad judicial durante la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":2,"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1256","post","type-post","status-publish","format-standard","hentry","category-medios"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &nbsp; La vicegobernadora Norma Durango recibi\u00f3 informaci\u00f3n sobre el n\u00famero creciente de denuncias por abuso sexual y por violencia con la mujer que se reciben diariamente en el Poder Judicial. Por el nuevo C\u00f3digo Procesal Penal, hay 2.000 causas residuales y s\u00f3lo se sacan 150 por a\u00f1o. Durango recorri\u00f3 la ciudad judicial durante la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-24T15:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\"},\"headline\":\"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o\",\"datePublished\":\"2012-05-24T15:37:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/\"},\"wordCount\":804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/Vicegob__en_Pol__de_la_Mujer.jpg\",\"articleSection\":[\"Medios\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/\",\"name\":\"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/Vicegob__en_Pol__de_la_Mujer.jpg\",\"datePublished\":\"2012-05-24T15:37:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/Vicegob__en_Pol__de_la_Mujer.jpg\",\"contentUrl\":\"http:\\\/\\\/www.diariofemenino.com.ar\\\/wp-content\\\/uploads\\\/Vicegob__en_Pol__de_la_Mujer.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/adm18df\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/","og_locale":"es_ES","og_type":"article","og_title":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino","og_description":"&nbsp; &nbsp; La vicegobernadora Norma Durango recibi\u00f3 informaci\u00f3n sobre el n\u00famero creciente de denuncias por abuso sexual y por violencia con la mujer que se reciben diariamente en el Poder Judicial. Por el nuevo C\u00f3digo Procesal Penal, hay 2.000 causas residuales y s\u00f3lo se sacan 150 por a\u00f1o. Durango recorri\u00f3 la ciudad judicial durante la [&hellip;]","og_url":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2012-05-24T15:37:16+00:00","og_image":[{"url":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg","type":"","width":"","height":""}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6"},"headline":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o","datePublished":"2012-05-24T15:37:16+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#primaryimage"},"thumbnailUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg","articleSection":["Medios"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/","url":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/","name":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#primaryimage"},"thumbnailUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg","datePublished":"2012-05-24T15:37:16+00:00","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#primaryimage","url":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg","contentUrl":"http:\/\/www.diariofemenino.com.ar\/wp-content\/uploads\/Vicegob__en_Pol__de_la_Mujer.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/poder-judicial-hay-2-000-causas-penales-pendientes-y-se-resuelven-150-al-ano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"Poder Judicial: hay 2.000 causas penales pendientes y se resuelven 150 al a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/medios\/\" rel=\"category tag\">Medios<\/a>","rttpg_excerpt":"&nbsp; &nbsp; La vicegobernadora Norma Durango recibi\u00f3 informaci\u00f3n sobre el n\u00famero creciente de denuncias por abuso sexual y por violencia con la mujer que se reciben diariamente en el Poder Judicial. Por el nuevo C\u00f3digo Procesal Penal, hay 2.000 causas residuales y s\u00f3lo se sacan 150 por a\u00f1o. Durango recorri\u00f3 la ciudad judicial durante la&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/1256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=1256"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/1256\/revisions"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=1256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=1256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=1256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}