{"id":1169,"date":"2012-05-23T11:08:36","date_gmt":"2012-05-23T14:08:36","guid":{"rendered":"http:\/\/www.diariofemenino.com.ar\/?p=1169"},"modified":"2012-05-23T11:08:36","modified_gmt":"2012-05-23T14:08:36","slug":"el-flagelo-de-la-trata-de-personas","status":"publish","type":"post","link":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/","title":{"rendered":"El flagelo de la trata de personas"},"content":{"rendered":"<h3><\/h3>\n<p><em>El encuentro de di\u00f3cesis de frontera que se realiza en Gualeguaych\u00fa aporta el an\u00e1lisis de uno de los flagelos m\u00e1s antiguos de la historia de la humanidad y que no ha perdido, lamentablemente, vigencia.<\/em><br \/>\nLa referencia es directa a la lucha contra la trata de personas, donde tanto el Estado como las organizaciones no gubernamentales y el conjunto de la ciudadan\u00eda no puede permanecer indiferente ni al margen.<br \/>\nLa trata y el tr\u00e1fico de personas son delitos que se han incrementado en forma alarmante en los \u00faltimos a\u00f1os, debido a las dif\u00edciles condiciones de vida en los pa\u00edses menos desarrollados, al endurecimiento de las pol\u00edticas migratorias en los pa\u00edses industrializados y al hecho de que por mucho tiempo estos fen\u00f3menos no fueron considerados como un problema estructural sino como una serie de episodios aislados.<br \/>\nA nivel provincial, el Municipio de Gualeguaych\u00fa fue uno de los primeros en implementar la clausura de todos los prost\u00edbulos, a\u00fan de aquellos que disimulaban sus actividades con otras nominaciones. Fue un gran avance que en todo el ejido no haya m\u00e1s esta clase de negocios, dado que se sabe que junto con la prostituci\u00f3n existen otras clases de delitos conexos como, por ejemplo, la comercializaci\u00f3n de estupefacientes, por citar solo uno.<br \/>\nA nivel nacional, las autoridades indicaron que tan s\u00f3lo en abril se logr\u00f3 rescatar a 176 personas que estaban atrapadas y siendo esclavizadas en distintas redes de trata. Es, a todas luces, un n\u00famero superior a todo el trimestre previo, seg\u00fan datos oficiales del Ministerio de Justicia y Derechos Humanos.<br \/>\nSi se tiene en cuenta todos los operativos que se vienen realizando durante este a\u00f1o, el n\u00famero de v\u00edctimas rescatadas ascienden a 346 personas, quienes padecieron sometimientos brutales en la explotaci\u00f3n sexual e incluso en otros casos, explotaci\u00f3n laboral. Este dado indica un promedio de tres por d\u00eda y muchos de ellos eran menores.<br \/>\nEsta lucha debe ser impostergable y simult\u00e1neamente sistem\u00e1tica. Se trata del tercer delito en importancia mundial, seg\u00fan califican los expertos.<br \/>\nEn Argentina, la ley 26.364 contra la trata de personas fue sancionada en abril de 2008. Desde entonces se liberaron 3.099 personas, 2.646 mayores y 453 menores de edad.<br \/>\nLa trata de persona es un crimen que tambi\u00e9n se inscribe en organizaciones mafiosas, que se caracterizan por degradar a sus v\u00edctimas a niveles inaceptables y es un delito que colisiona de manera frontal y directa con la abolici\u00f3n de toda clase de esclavitud.<br \/>\nEnfrentar este flagelo tambi\u00e9n implica un gran cambio cultural y para ello es irremplazable el acompa\u00f1amiento del conjunto de la comunidad. Frente a este delito no se puede actuar solo y hay que insistir en la necesidad de establecer severas y graves penas al cliente o consumidor de la explotaci\u00f3n sexual como laboral.<br \/>\nPor eso la iniciativa del encuentro de di\u00f3cesis de frontera es m\u00e1s que oportuno, m\u00e1xime en Gualeguaych\u00fa, ciudad fronteriza y rodeada por grandes v\u00edas de comunicaci\u00f3n, que torna indispensable una constante pol\u00edtica preventiva y al mismo tiempo un innegociable trabajo de concientizaci\u00f3n para que nadie, directa o indirectamente, alimente este flagelo.<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n&nbsp;<br \/>\n<em>Fuente: <a href=\"http:\/\/www.diarioelargentino.com.ar\/noticias\/107776\/el-flagelo-de-la-trata-de-personas\">Editorial de El Argentino<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El encuentro de di\u00f3cesis de frontera que se realiza en Gualeguaych\u00fa aporta el an\u00e1lisis de uno de los flagelos m\u00e1s antiguos de la historia de la humanidad y que no ha perdido, lamentablemente, vigencia. La referencia es directa a la lucha contra la trata de personas, donde tanto el Estado como las organizaciones no gubernamentales [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1170,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":""},"categories":[4,6,2,15],"tags":[],"class_list":["post-1169","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medios","category-articulos","category-sin-categoria","category-trata-de-personas"],"nelio_content":{"autoShareEndMode":"never","automationSources":{"useCustomSentences":false,"customSentences":[]},"efiAlt":"","efiUrl":"","followers":[],"highlights":[],"isAutoShareEnabled":true,"networkImageIds":[],"permalinkQueryArgs":[],"series":[],"suggestedReferences":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El flagelo de la trata de personas - Diario Digital Femenino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El flagelo de la trata de personas - Diario Digital Femenino\" \/>\n<meta property=\"og:description\" content=\"El encuentro de di\u00f3cesis de frontera que se realiza en Gualeguaych\u00fa aporta el an\u00e1lisis de uno de los flagelos m\u00e1s antiguos de la historia de la humanidad y que no ha perdido, lamentablemente, vigencia. La referencia es directa a la lucha contra la trata de personas, donde tanto el Estado como las organizaciones no gubernamentales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"Diario Digital Femenino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-23T14:08:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"855\" \/>\n\t<meta property=\"og:image:height\" content=\"319\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:site\" content=\"@DiarioFemenino1\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/\"},\"author\":{\"name\":\"Admin\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\"},\"headline\":\"El flagelo de la trata de personas\",\"datePublished\":\"2012-05-23T14:08:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":{\"0\":\"Medios\",\"1\":\"Mujeres en Palabras\",\"3\":\"Trata de Pers.\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/\",\"name\":\"El flagelo de la trata de personas - Diario Digital Femenino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2012-05-23T14:08:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/el-flagelo-de-la-trata-de-personas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El flagelo de la trata de personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#website\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"name\":\"Diario Digital Femenino\",\"description\":\"Cuesti\u00f3n de G\u00e9nero\",\"publisher\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#organization\",\"name\":\"Diario Femenino\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/logo.png\",\"width\":500,\"height\":92,\"caption\":\"Diario Femenino\"},\"image\":{\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DiarioDigitaFemenino\\\/\",\"https:\\\/\\\/x.com\\\/DiarioFemenino1\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/#\\\/schema\\\/person\\\/38f54b3bfd13f561de2460ba95c169c6\",\"name\":\"Admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/wp-content\\\/uploads\\\/2018\\\/12\\\/favicon-150x150.jpg\",\"caption\":\"Admin\"},\"url\":\"https:\\\/\\\/diariofemenino.com.ar\\\/df\\\/author\\\/adm18df\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El flagelo de la trata de personas - Diario Digital Femenino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/","og_locale":"es_ES","og_type":"article","og_title":"El flagelo de la trata de personas - Diario Digital Femenino","og_description":"El encuentro de di\u00f3cesis de frontera que se realiza en Gualeguaych\u00fa aporta el an\u00e1lisis de uno de los flagelos m\u00e1s antiguos de la historia de la humanidad y que no ha perdido, lamentablemente, vigencia. La referencia es directa a la lucha contra la trata de personas, donde tanto el Estado como las organizaciones no gubernamentales [&hellip;]","og_url":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/","og_site_name":"Diario Digital Femenino","article_publisher":"https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","article_published_time":"2012-05-23T14:08:36+00:00","og_image":[{"width":855,"height":319,"url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2016\/10\/logo-negro.png","type":"image\/png"}],"author":"Admin","twitter_card":"summary_large_image","twitter_creator":"@DiarioFemenino1","twitter_site":"@DiarioFemenino1","twitter_misc":{"Escrito por":"Admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#article","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/"},"author":{"name":"Admin","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6"},"headline":"El flagelo de la trata de personas","datePublished":"2012-05-23T14:08:36+00:00","mainEntityOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#primaryimage"},"thumbnailUrl":"","articleSection":{"0":"Medios","1":"Mujeres en Palabras","3":"Trata de Pers."},"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/","url":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/","name":"El flagelo de la trata de personas - Diario Digital Femenino","isPartOf":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#website"},"primaryImageOfPage":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#primaryimage"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#primaryimage"},"thumbnailUrl":"","datePublished":"2012-05-23T14:08:36+00:00","breadcrumb":{"@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/diariofemenino.com.ar\/df\/el-flagelo-de-la-trata-de-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/diariofemenino.com.ar\/df\/"},{"@type":"ListItem","position":2,"name":"El flagelo de la trata de personas"}]},{"@type":"WebSite","@id":"https:\/\/diariofemenino.com.ar\/df\/#website","url":"https:\/\/diariofemenino.com.ar\/df\/","name":"Diario Digital Femenino","description":"Cuesti\u00f3n de G\u00e9nero","publisher":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/diariofemenino.com.ar\/df\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/diariofemenino.com.ar\/df\/#organization","name":"Diario Femenino","url":"https:\/\/diariofemenino.com.ar\/df\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/10\/logo.png","width":500,"height":92,"caption":"Diario Femenino"},"image":{"@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DiarioDigitaFemenino\/","https:\/\/x.com\/DiarioFemenino1"]},{"@type":"Person","@id":"https:\/\/diariofemenino.com.ar\/df\/#\/schema\/person\/38f54b3bfd13f561de2460ba95c169c6","name":"Admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","url":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","contentUrl":"https:\/\/diariofemenino.com.ar\/df\/wp-content\/uploads\/2018\/12\/favicon-150x150.jpg","caption":"Admin"},"url":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"rttpg_featured_image_url":null,"rttpg_author":{"display_name":"Admin","author_link":"https:\/\/diariofemenino.com.ar\/df\/author\/adm18df\/"},"rttpg_comment":0,"rttpg_category":"<a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/medios\/\" rel=\"category tag\">Medios<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/articulos\/\" rel=\"category tag\">Mujeres en Palabras<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/sin-categoria\/\" rel=\"category tag\">Sin categor\u00eda<\/a> <a href=\"https:\/\/diariofemenino.com.ar\/df\/category\/trata-de-personas\/\" rel=\"category tag\">Trata de Pers.<\/a>","rttpg_excerpt":"El encuentro de di\u00f3cesis de frontera que se realiza en Gualeguaych\u00fa aporta el an\u00e1lisis de uno de los flagelos m\u00e1s antiguos de la historia de la humanidad y que no ha perdido, lamentablemente, vigencia. La referencia es directa a la lucha contra la trata de personas, donde tanto el Estado como las organizaciones no gubernamentales&hellip;","_links":{"self":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/1169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/comments?post=1169"}],"version-history":[{"count":0,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/posts\/1169\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/media?parent=1169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/categories?post=1169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diariofemenino.com.ar\/df\/wp-json\/wp\/v2\/tags?post=1169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}